{"id":10557,"date":"2022-06-11T16:29:28","date_gmt":"2022-06-11T14:29:28","guid":{"rendered":"http:\/\/just-now.news\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/"},"modified":"2022-06-11T16:29:28","modified_gmt":"2022-06-11T14:29:28","slug":"us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/","title":{"rendered":"US-Verteidigungsminister warnt vor Chinas \u201ewachsendem Zwang\u201c gegen\u00fcber Taiwan"},"content":{"rendered":"<p><\/p>\n<div>\n<p>Die Vereinigten Staaten werden ihre F\u00e4higkeit aufrechterhalten, jeder Kraft zu widerstehen, die die Sicherheit Taiwans bedroht, sagte US-Verteidigungsminister Llyod J. Austin am Samstag, als er vor dem \u201ewachsenden Zwang\u201c aus Peking warnte.<\/p>\n<p>Beim Shangri-La-Dialog in Singapur sagte Austin, dass das chinesische kommunistische Regime in seinen Gebietsanspr\u00fcchen \u201ezwingender und aggressiver\u201c geworden sei, und verwies auf Pekings illegale maritime Aktivit\u00e4ten im umstrittenen S\u00fcdchinesischen Meer.<\/p>\n<p>\u201eWir haben einen alarmierenden Anstieg der Zahl unsicherer Luftangriffe und Konfrontationen auf See durch PLA erlebt [People\u2019s Liberation Army] Flugzeuge und Schiffe\u201c, sagte er und zitierte einen Vorfall im Februar, als ein Schiff der PLA Navy einen Laser auf ein australisches Kampfflugzeug richtete.<\/p>\n<p>Aber die Eins\u00e4tze sind \u201ebesonders stark in der Stra\u00dfe von Taiwan\u201c, sagte Austin.<\/p>\n<p>\u201eWir haben eine stetige Zunahme provokanter und destabilisierender milit\u00e4rischer Aktivit\u00e4ten in der N\u00e4he von Taiwan erlebt.  Und dazu geh\u00f6ren PLA-Flugzeuge, die in den letzten Monaten in Rekordzahlen und fast t\u00e4glich in der N\u00e4he von Taiwan geflogen sind\u201c, erkl\u00e4rte er.<\/p>\n<p>Die Spannungen \u00fcber die Taiwanstra\u00dfe haben in den letzten Monaten zugenommen, wobei China am 30. Mai mit 30 PLA-Kampfflugzeugen seinen zweitgr\u00f6\u00dften Einfall in Taiwans Air Defense Identification Zone unternahm.<\/p>\n<p>China beansprucht die selbstverwaltete Insel f\u00fcr sich und hat geschworen, sie notfalls mit Gewalt zu erobern.<\/p>\n<p>Austin sagte, Washington bleibe der \u201eEin-China\u201c-Politik verpflichtet, obwohl es Taiwan immer noch mit den notwendigen F\u00e4higkeiten ausstatten w\u00fcrde, um seine Verteidigung aufrechtzuerhalten, und wiederholte damit die \u00c4u\u00dferungen von Pr\u00e4sident Joe Biden in Tokio im vergangenen Monat.<\/p>\n<p>\u201eUnd es bedeutet, unsere eigene F\u00e4higkeit aufrechtzuerhalten, jeder Anwendung von Gewalt oder anderen Formen von Zwang zu widerstehen, die die Sicherheit oder das soziale oder wirtschaftliche System der Menschen in Taiwan gef\u00e4hrden w\u00fcrden\u201c, bemerkte Austin.<\/p>\n<p>Er wies ferner darauf hin, dass Pekings j\u00fcngste Milit\u00e4rman\u00f6ver in der N\u00e4he von Taiwan die indopazifische Region zu destabilisieren drohten, und betonte, dass die Aufrechterhaltung von Frieden und Sicherheit \u00fcber die Taiwanstra\u00dfe hinweg ein globales Problem und nicht nur ein US-Interesse sei.<\/p>\n<p>\u201eWir suchen keine Konfrontation oder Konflikte.  Und wir streben keinen neuen Kalten Krieg, eine asiatische NATO oder eine in feindliche Bl\u00f6cke gespaltene Region an\u201c, sagte er und bezog sich dabei auf die Organisation des Nordatlantikvertrags.<\/p>\n<p>\u201eWir werden unsere Interessen verteidigen, ohne zur\u00fcckzuschrecken.  Aber wir werden auch auf unsere Vision f\u00fcr diese Region hinarbeiten \u2013 eine der Erweiterung der Sicherheit, einer verst\u00e4rkten Zusammenarbeit und nicht einer wachsenden Spaltung.\u201c<\/p>\n<p>Austins \u00c4u\u00dferungen kamen einen Tag nach seinem Treffen mit dem chinesischen Verteidigungsminister General Wei Fenghe am Rande des Shangri-La-Dialoggipfels, bei dem er Washingtons Besorgnis \u00fcber das \u201eunsichere, aggressive und unprofessionelle Verhalten\u201c der PLA in der Taiwanstra\u00dfe \u00e4u\u00dferte.<\/p>\n<p>W\u00e4hrend des Treffens teilte Austin Wei mit, dass Washington die Unabh\u00e4ngigkeit Taiwans nicht unterst\u00fctze, Taiwan aber nach dem Taiwan Relations Act von 1979 dennoch Verteidigungswaffen liefern w\u00fcrde.<\/p>\n<p>\u201eSekret\u00e4r Austin wiederholte den Punkt, den er am Telefon gemacht hatte, dass wir die Situation sehr genau beobachten und China dringend davon abhalten, Russland f\u00fcr seinen Krieg in der Ukraine materiell zu unterst\u00fctzen\u201c, sagte das US-Verteidigungsministerium in einer Erkl\u00e4rung.<\/p>\n<\/div>\n<p><br \/>\n<b> Text ist eine \u00dcbersetzung vom Epoch Times Artikel:<\/p>\n<p><a href=\"https:\/\/www.theepochtimes.com\/us-defense-secretary-warns-of-chinas-growing-coercion-of-taiwan_4526984.html\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Vereinigten Staaten werden ihre F\u00e4higkeit aufrechterhalten, jeder Kraft zu widerstehen, die die Sicherheit Taiwans bedroht, sagte US-Verteidigungsminister Llyod J. Austin am Samstag, als er vor dem \u201ewachsenden Zwang\u201c aus Peking warnte. Beim Shangri-La-Dialog in Singapur sagte Austin, dass das chinesische kommunistische Regime in seinen Gebietsanspr\u00fcchen \u201ezwingender und aggressiver\u201c geworden sei, und verwies auf Pekings [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":10558,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_automatic_camp":["1164"],"18322c23b335a8c820ba08e1b2a960d5":["US-Verteidigungsminister warnt vor Chinas \u201ewachsendem Zwang\u201c gegen\u00fcber Taiwan\n"],"original_link":["https:\/\/www.theepochtimes.com\/us-defense-secretary-warns-of-chinas-growing-coercion-of-taiwan_4526984.html"],"_thumbnail_id":["10558"],"wp_automatic_remove_first_image":["yes"],"jnews_social_counter_last_update":["1778534865"]},"categories":[21],"tags":[3313,8962,1043,23941,320,24072,912,8954],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>US-Verteidigungsminister warnt vor Chinas \u201ewachsendem Zwang\u201c gegen\u00fcber Taiwan - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"US-Verteidigungsminister warnt vor Chinas \u201ewachsendem Zwang\u201c gegen\u00fcber Taiwan\" \/>\n<meta property=\"og:description\" content=\"Die Vereinigten Staaten werden ihre F\u00e4higkeit aufrechterhalten, jeder Kraft zu widerstehen, die die Sicherheit Taiwans bedroht, sagte US-Verteidigungsminister Llyod J. Austin am Samstag, als er vor dem \u201ewachsenden Zwang\u201c aus Peking warnte. Beim Shangri-La-Dialog in Singapur sagte Austin, dass das chinesische kommunistische Regime in seinen Gebietsanspr\u00fcchen \u201ezwingender und aggressiver\u201c geworden sei, und verwies auf Pekings [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-11T14:29:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/1654959821_US-Verteidigungsminister-warnt-vor-Chinas-\u201ewachsendem-Zwang-gegenueber-Taiwan.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"753\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"epoch\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"epoch\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/\"},\"author\":{\"name\":\"epoch\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/c6dfcd35a72a074487761b9d49aef52f\"},\"headline\":\"US-Verteidigungsminister warnt vor Chinas \u201ewachsendem Zwang\u201c gegen\u00fcber Taiwan\",\"datePublished\":\"2022-06-11T14:29:28+00:00\",\"dateModified\":\"2022-06-11T14:29:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/\"},\"wordCount\":546,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/1654959821_US-Verteidigungsminister-warnt-vor-Chinas-\u201ewachsendem-Zwang-gegenueber-Taiwan.jpg\",\"keywords\":[\"Chinas\",\"gegen\u00fcber\",\"Taiwan\",\"USVerteidigungsminister\",\"vor\",\"wachsendem\",\"warnt\",\"zwang\"],\"articleSection\":[\"China\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/\",\"url\":\"https:\/\/now-news.de\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/\",\"name\":\"US-Verteidigungsminister warnt vor Chinas \u201ewachsendem Zwang\u201c gegen\u00fcber Taiwan - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/1654959821_US-Verteidigungsminister-warnt-vor-Chinas-\u201ewachsendem-Zwang-gegenueber-Taiwan.jpg\",\"datePublished\":\"2022-06-11T14:29:28+00:00\",\"dateModified\":\"2022-06-11T14:29:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/1654959821_US-Verteidigungsminister-warnt-vor-Chinas-\u201ewachsendem-Zwang-gegenueber-Taiwan.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/1654959821_US-Verteidigungsminister-warnt-vor-Chinas-\u201ewachsendem-Zwang-gegenueber-Taiwan.jpg\",\"width\":1200,\"height\":753},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"US-Verteidigungsminister warnt vor Chinas \u201ewachsendem Zwang\u201c gegen\u00fcber Taiwan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/c6dfcd35a72a074487761b9d49aef52f\",\"name\":\"epoch\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/56933836307948e61ef581cc4d100335?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/56933836307948e61ef581cc4d100335?s=96&d=mm&r=g\",\"caption\":\"epoch\"},\"url\":\"https:\/\/now-news.de\/de\/author\/epoch\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"US-Verteidigungsminister warnt vor Chinas \u201ewachsendem Zwang\u201c gegen\u00fcber Taiwan - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/","og_locale":"de_DE","og_type":"article","og_title":"US-Verteidigungsminister warnt vor Chinas \u201ewachsendem Zwang\u201c gegen\u00fcber Taiwan","og_description":"Die Vereinigten Staaten werden ihre F\u00e4higkeit aufrechterhalten, jeder Kraft zu widerstehen, die die Sicherheit Taiwans bedroht, sagte US-Verteidigungsminister Llyod J. Austin am Samstag, als er vor dem \u201ewachsenden Zwang\u201c aus Peking warnte. Beim Shangri-La-Dialog in Singapur sagte Austin, dass das chinesische kommunistische Regime in seinen Gebietsanspr\u00fcchen \u201ezwingender und aggressiver\u201c geworden sei, und verwies auf Pekings [&hellip;]","og_url":"https:\/\/now-news.de\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2022-06-11T14:29:28+00:00","og_image":[{"width":1200,"height":753,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/1654959821_US-Verteidigungsminister-warnt-vor-Chinas-\u201ewachsendem-Zwang-gegenueber-Taiwan.jpg","type":"image\/jpeg"}],"author":"epoch","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"epoch","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/"},"author":{"name":"epoch","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/c6dfcd35a72a074487761b9d49aef52f"},"headline":"US-Verteidigungsminister warnt vor Chinas \u201ewachsendem Zwang\u201c gegen\u00fcber Taiwan","datePublished":"2022-06-11T14:29:28+00:00","dateModified":"2022-06-11T14:29:28+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/"},"wordCount":546,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/1654959821_US-Verteidigungsminister-warnt-vor-Chinas-\u201ewachsendem-Zwang-gegenueber-Taiwan.jpg","keywords":["Chinas","gegen\u00fcber","Taiwan","USVerteidigungsminister","vor","wachsendem","warnt","zwang"],"articleSection":["China"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/","url":"https:\/\/now-news.de\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/","name":"US-Verteidigungsminister warnt vor Chinas \u201ewachsendem Zwang\u201c gegen\u00fcber Taiwan - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/1654959821_US-Verteidigungsminister-warnt-vor-Chinas-\u201ewachsendem-Zwang-gegenueber-Taiwan.jpg","datePublished":"2022-06-11T14:29:28+00:00","dateModified":"2022-06-11T14:29:28+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/1654959821_US-Verteidigungsminister-warnt-vor-Chinas-\u201ewachsendem-Zwang-gegenueber-Taiwan.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/1654959821_US-Verteidigungsminister-warnt-vor-Chinas-\u201ewachsendem-Zwang-gegenueber-Taiwan.jpg","width":1200,"height":753},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/china\/us-verteidigungsminister-warnt-vor-chinas-wachsendem-zwang-gegenueber-taiwan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"US-Verteidigungsminister warnt vor Chinas \u201ewachsendem Zwang\u201c gegen\u00fcber Taiwan"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/c6dfcd35a72a074487761b9d49aef52f","name":"epoch","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/56933836307948e61ef581cc4d100335?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/56933836307948e61ef581cc4d100335?s=96&d=mm&r=g","caption":"epoch"},"url":"https:\/\/now-news.de\/de\/author\/epoch\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/10557"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=10557"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/10557\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/10558"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=10557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=10557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=10557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}