{"id":105200,"date":"2026-06-17T15:45:10","date_gmt":"2026-06-17T13:45:10","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\/"},"modified":"2026-06-17T15:45:10","modified_gmt":"2026-06-17T13:45:10","slug":"cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\/","title":{"rendered":"CIA sieht Iran-Deal skeptisch \u2013 Zweifel an Teherans Absichten"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/6a32765ab480cc32e02f183e.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Erkenntnisse der US-Geheimdienste werfen erhebliche Zweifel daran auf, ob Iran bereit ist, die von den USA geforderten nuklearen Zugest\u00e4ndnisse im Rahmen eines m\u00f6glichen endg\u00fcltigen Abkommens zu machen. JD Vance unterst\u00fctzt den Deal jedoch.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p data-start=\"70\" data-end=\"500\">CIA-Direktor John Ratcliffe hat Pr\u00e4sident Donald Trump und andere ranghohe Regierungsvertreter dar\u00fcber informiert, dass Erkenntnisse der US-Geheimdienste erhebliche Zweifel daran aufwerfen, ob Iran bereit ist, die von den USA geforderten nuklearen Zugest\u00e4ndnisse im Rahmen eines m\u00f6glichen endg\u00fcltigen Abkommens zu machen. Das berichten drei mit den Gespr\u00e4chen vertraute Quellen gegen\u00fcber <em>Axios<\/em>.<\/p>\n<p data-start=\"502\" data-end=\"1065\">Ratcliffe ist nicht der einzige Skeptiker im engeren Team von Trump. In internen Gespr\u00e4chen \u00e4u\u00dferten auch Au\u00dfenminister Marco Rubio und Verteidigungsminister Pete Hegseth Bedenken und stellten Fragen zum am Sonntag angek\u00fcndigten Memorandum of Understanding (MOU). Dagegen sprachen sich Vizepr\u00e4sident JD Vance sowie die US-Unterh\u00e4ndler Steve Witkoff und Jared Kushner f\u00fcr das Abkommen aus, wie zwei Quellen berichten.<\/p>\n<p data-start=\"1067\" data-end=\"1227\">In der Vorbereitungsphase der Ank\u00fcndigung des Abkommens fanden mehrere hochrangige Treffen zwischen Trump und seinen Beratern zum Deal statt. Dabei diskutierten Trump und sein Team Geheimdiensterkenntnisse mehrerer US-Beh\u00f6rden, denen zufolge die iranische Kommunikation \u00fcber das Abkommen intern nicht mit dem \u00fcbereinstimmt, was Teheran gegen\u00fcber Vermittlern und den USA \u00e4u\u00dferte.<\/p>\n<p data-start=\"1483\" data-end=\"1690\">Ratcliffe und Rubio erkl\u00e4rten auf Grundlage dieser Informationen, sie zweifelten daran, dass Iran bereit sei, die von den USA geforderten nuklearen Schritte tats\u00e4chlich umzusetzen. Bei <em>Axios<\/em> hei\u00dft es dazu:<\/p>\n<p data-start=\"1483\" data-end=\"1690\"><em>&#8220;Die Geheimdienstinformationen deuten darauf hin, dass die iranischen Absichten nicht mit ihren Verpflichtungen im Rahmen des Abkommens \u00fcbereinstimmen.&#8221;<\/em><\/p>\n<p data-start=\"746\" data-end=\"916\">Die nuklearen Bestandteile\u00a0der am Sonntag unterzeichneten Absichtserkl\u00e4rung (MOU) h\u00e4ngen davon ab, ob die Parteien innerhalb der kommenden 60 Tage ein detaillierteres Atomabkommen erreichen.<\/p>\n<p data-start=\"918\" data-end=\"1300\">JD Vance, Steve Witkoff und Jared Kushner sollen sich am Freitag mit dem iranischen Parlamentspr\u00e4sidenten Mohammad-Bagher Ghalibaf und Au\u00dfenminister Abbas Araghtschi sowie pakistanischen und katarischen Vermittlern treffen, um die n\u00e4chste Verhandlungsphase zu besprechen.\u00a0<\/p>\n<p data-start=\"1332\" data-end=\"1610\">Der vollst\u00e4ndige Text des 14-Punkte-Entwurfs wurde bislang nicht ver\u00f6ffentlicht. Eine mit dem Text vertraute Quelle erkl\u00e4rte jedoch, dass Iran im Rahmen des MOU mehr erhalten k\u00f6nnte, als er zugesteht \u2013 sofern er kein Atomabkommen unterzeichnet, das den US-Zielen entspricht.<\/p>\n<p data-start=\"2756\" data-end=\"2951\">Interne Skeptiker des Abkommens argumentieren, dass Iran wahrscheinlich kein Atomabkommen zu US-Bedingungen unterzeichnen werde und im Gegenzug kurzfristig st\u00e4rker vom MOU profitiere als die USA.<\/p>\n<p data-start=\"2756\" data-end=\"2951\"><strong>Mehr zum Thema<\/strong>\u00a0\u2013\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/der-nahe-osten\/283287-usa-und-iran-vereinbaren-absichtserklaerung\/\">Herber R\u00fcckschlag f\u00fcr Trumps Kriegspolitik &#8211; Die Absichtserkl\u00e4rung von USA und Iran<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v795fp0\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/283435-cia-sieht-iran-deal-skeptisch\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erkenntnisse der US-Geheimdienste werfen erhebliche Zweifel daran auf, ob Iran bereit ist, die von den USA geforderten nuklearen Zugest\u00e4ndnisse im Rahmen eines m\u00f6glichen endg\u00fcltigen Abkommens zu machen. JD Vance unterst\u00fctzt den Deal jedoch. CIA-Direktor John Ratcliffe hat Pr\u00e4sident Donald Trump und andere ranghohe Regierungsvertreter dar\u00fcber informiert, dass Erkenntnisse der US-Geheimdienste erhebliche Zweifel daran aufwerfen, ob [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":105201,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1781704525"],"wp_automatic_camp":["217"],"4d50ef98c9e0853723becc84b30c9169":["CIA sieht Iran-Deal skeptisch \u2013 Zweifel an Teherans Absichten"],"original_link":["https:\/\/de.rt.com\/international\/283435-cia-sieht-iran-deal-skeptisch\/"],"_thumbnail_id":["105201"],"jnews_social_counter_last_update":["1788288503"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2026-06-17 15:56:24\";}"]},"categories":[19,23],"tags":[18766,5266,73290,6809,20777,45364,36158],"class_list":["post-105200","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-absichten","tag-cia","tag-irandeal","tag-sieht","tag-skeptisch","tag-teherans","tag-zweifel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>CIA sieht Iran-Deal skeptisch \u2013 Zweifel an Teherans Absichten - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CIA sieht Iran-Deal skeptisch \u2013 Zweifel an Teherans Absichten\" \/>\n<meta property=\"og:description\" content=\"Erkenntnisse der US-Geheimdienste werfen erhebliche Zweifel daran auf, ob Iran bereit ist, die von den USA geforderten nuklearen Zugest\u00e4ndnisse im Rahmen eines m\u00f6glichen endg\u00fcltigen Abkommens zu machen. JD Vance unterst\u00fctzt den Deal jedoch. CIA-Direktor John Ratcliffe hat Pr\u00e4sident Donald Trump und andere ranghohe Regierungsvertreter dar\u00fcber informiert, dass Erkenntnisse der US-Geheimdienste erhebliche Zweifel daran aufwerfen, ob [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-17T13:45:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/6a32765ab480cc32e02f183e.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"CIA sieht Iran-Deal skeptisch \u2013 Zweifel an Teherans Absichten\",\"datePublished\":\"2026-06-17T13:45:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\\\/\"},\"wordCount\":419,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/06\\\/CIA-sieht-Iran-Deal-skeptisch-\u2013-Zweifel-an-Teherans-Absichten.jpg\",\"keywords\":[\"Absichten\",\"CIA\",\"IranDeal\",\"sieht\",\"skeptisch\",\"Teherans\",\"Zweifel\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\\\/\",\"name\":\"CIA sieht Iran-Deal skeptisch \u2013 Zweifel an Teherans Absichten - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/06\\\/CIA-sieht-Iran-Deal-skeptisch-\u2013-Zweifel-an-Teherans-Absichten.jpg\",\"datePublished\":\"2026-06-17T13:45:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/06\\\/CIA-sieht-Iran-Deal-skeptisch-\u2013-Zweifel-an-Teherans-Absichten.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/06\\\/CIA-sieht-Iran-Deal-skeptisch-\u2013-Zweifel-an-Teherans-Absichten.jpg\",\"width\":460,\"height\":259,\"caption\":\"CIA sieht Iran-Deal skeptisch \u2013 Zweifel an Teherans Absichten\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CIA sieht Iran-Deal skeptisch \u2013 Zweifel an Teherans Absichten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"CIA sieht Iran-Deal skeptisch \u2013 Zweifel an Teherans Absichten - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\/","og_locale":"de_DE","og_type":"article","og_title":"CIA sieht Iran-Deal skeptisch \u2013 Zweifel an Teherans Absichten","og_description":"Erkenntnisse der US-Geheimdienste werfen erhebliche Zweifel daran auf, ob Iran bereit ist, die von den USA geforderten nuklearen Zugest\u00e4ndnisse im Rahmen eines m\u00f6glichen endg\u00fcltigen Abkommens zu machen. JD Vance unterst\u00fctzt den Deal jedoch. CIA-Direktor John Ratcliffe hat Pr\u00e4sident Donald Trump und andere ranghohe Regierungsvertreter dar\u00fcber informiert, dass Erkenntnisse der US-Geheimdienste erhebliche Zweifel daran aufwerfen, ob [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2026-06-17T13:45:10+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/6a32765ab480cc32e02f183e.jpg","type":"","width":"","height":""}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"CIA sieht Iran-Deal skeptisch \u2013 Zweifel an Teherans Absichten","datePublished":"2026-06-17T13:45:10+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\/"},"wordCount":419,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/CIA-sieht-Iran-Deal-skeptisch-\u2013-Zweifel-an-Teherans-Absichten.jpg","keywords":["Absichten","CIA","IranDeal","sieht","skeptisch","Teherans","Zweifel"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\/","url":"https:\/\/now-news.de\/de\/deutschland\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\/","name":"CIA sieht Iran-Deal skeptisch \u2013 Zweifel an Teherans Absichten - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/CIA-sieht-Iran-Deal-skeptisch-\u2013-Zweifel-an-Teherans-Absichten.jpg","datePublished":"2026-06-17T13:45:10+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/CIA-sieht-Iran-Deal-skeptisch-\u2013-Zweifel-an-Teherans-Absichten.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/CIA-sieht-Iran-Deal-skeptisch-\u2013-Zweifel-an-Teherans-Absichten.jpg","width":460,"height":259,"caption":"CIA sieht Iran-Deal skeptisch \u2013 Zweifel an Teherans Absichten"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/cia-sieht-iran-deal-skeptisch-zweifel-an-teherans-absichten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"CIA sieht Iran-Deal skeptisch \u2013 Zweifel an Teherans Absichten"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/105200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=105200"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/105200\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/105201"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=105200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=105200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=105200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}