{"id":105075,"date":"2026-06-15T20:04:12","date_gmt":"2026-06-15T18:04:12","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/"},"modified":"2026-06-15T20:04:12","modified_gmt":"2026-06-15T18:04:12","slug":"globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/","title":{"rendered":"GlobalSign zieht &quot;digitale Ausweise&quot; russischer Webseiten zur\u00fcck"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/6a3015ffb480cc3a4c228ec5.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Eines der weltweit gr\u00f6\u00dften Zertifizierungszentren widerruft die Sicherheitszertifikate russischer Webseiten. Dies geschieht aus Sanktionsgr\u00fcnden \u2013 mit der m\u00f6glichen Folge, dass ausl\u00e4ndische Browser diese als unsicher einstufen.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Russische Internetseiten verlieren m\u00f6glicherweise von einem Tag auf den anderen die Sichtbarkeit in ausl\u00e4ndischen Browsern. Die Folgen k\u00f6nnten nicht nur Zehntausende von Webseiten betreffen, sondern auch verschiedene Anwendungen, deren Funktion von ausl\u00e4ndischen Sicherheitszertifikaten abh\u00e4ngt.<\/p>\n<p>Das japanische Unternehmen GlobalSign \u2013 eine der gr\u00f6\u00dften Zertifizierungsstellen weltweit \u2013 hat am Morgen des 13. Juni damit begonnen, zuvor ausgestellte SSL-Zertifikate von Unternehmen aus Russland zwangsweise zu widerrufen. Dar\u00fcber berichtet das Wirtschaftsportal <em>RB<\/em><em>K<\/em> unter Berufung auf ein Schreiben des Generaldirektors des russischen Unternehmens &#8220;GMO GlobalSign Russia&#8221;, Dmitri Ryschikow, an die Partner des Unternehmens im Land. Wie <em>RB<\/em><em>K<\/em> weiter berichtet, hei\u00dft es in Ryschikows Schreiben, dass die globale Regulierungsbeh\u00f6rde, das Internationale Konsortium &#8220;CA\/Browser Forum&#8221;, dem alle gro\u00dfen Zertifizierungsstellen der Welt sowie Browser-Entwickler angeh\u00f6ren, aktualisierte Anforderungen f\u00fcr die \u00dcberpr\u00fcfung von Organisationen verabschiedet habe. Ryschikow schreibt insbesondere:<\/p>\n<blockquote>\n<p><em>&#8220;Zu unserem gro\u00dfen Bedauern erfordern die derzeitigen strengen Vorschriften dieses Konsortiums zwangsl\u00e4ufig die Einhaltung internationaler Sanktionsbeschr\u00e4nkungen. Aus diesem Grund hat die globale Zertifizierungsstelle ein Verfahren zur zwangsweisen R\u00fccknahme eines Teils der zuvor ausgestellten Zertifikate f\u00fcr Unternehmen aus Russland eingeleitet.&#8221; <\/em><\/p>\n<\/blockquote>\n<p>In dem Schreiben wird zudem betont, dass GlobalSign keinen Einfluss auf die Entscheidungen der globalen Regulierungsbeh\u00f6rde habe und lediglich dazu verpflichtet sei, diese umzusetzen, was das Unternehmen in den kommenden Tagen und Wochen auch tun werde. Wie <em>RB<\/em><em>K\u00a0<\/em>anmerkt, enth\u00e4lt das auf der Webseite des CA\/Browser Forums ver\u00f6ffentlichte Dokument, das am 4. Mai in Kraft getreten ist, ein direktes Verbot f\u00fcr Zertifizierungsstellen, Zertifikate an Unternehmen aus Sanktionslisten auszustellen.<\/p>\n<p>Die russische T-Bank hat ihren Kunden bereits SMS mit der Warnung verschickt, dass es zu Schwierigkeiten beim Zugriff auf die Webseiten und Apps der Bank kommen k\u00f6nnte. Nach Sch\u00e4tzungen von Marktteilnehmern stehen etwa 15.000 bis 20.000 Second-Level-Domains \u2013 also die Hauptadressen der Webseiten \u2013 auf der Liste f\u00fcr den Widerruf von Zertifikaten, doch unter jeder dieser Domains k\u00f6nnen sich Hunderte oder Tausende von Subdomains der dritten und weiterer Ebenen befinden. Die tats\u00e4chliche Anzahl der Zertifikate, die widerrufen werden k\u00f6nnten, k\u00f6nnte daher in die Millionen gehen.<\/p>\n<p>Der unabh\u00e4ngige Experte f\u00fcr Informationssicherheit, Alexei Lukazki, wies im Gespr\u00e4ch mit <em>RB<\/em><em>K<\/em> darauf hin, dass der derzeitige Entzug von Zertifikaten nicht der letzte sein werde. Er betonte:<\/p>\n<blockquote>\n<p><em>&#8220;<\/em><em>Es h\u00e4ngt alles davon ab, welche Unternehmen unter die neue Regulierung fallen. Eine sehr gro\u00dfe Anzahl bedeutender Akteure der russischen Wirtschaft ist von Sanktionen oder k\u00fcnftigen europ\u00e4ischen Sanktionspaketen betroffen \u2013 und diese Geschichte wird sich mit Sicherheit fortsetzen.<\/em><em>&#8220;<\/em><\/p>\n<\/blockquote>\n<p>Ein SSL-Zertifikat ist der digitale &#8220;Ausweis&#8221; einer Webseite. Es best\u00e4tigt die Echtheit der Webseite und garantiert, dass der Nutzer tats\u00e4chlich mit der gew\u00fcnschten Seite verbunden ist und nicht mit einer gef\u00e4lschten. Au\u00dferdem verschl\u00fcsselt es den Datenverkehr zwischen Browser und Server, sodass dieser nicht abgefangen werden kann. Der Widerruf eines Zertifikats bedeutet, dass Browser und Systeme es als ung\u00fcltig betrachten, und viele Browser sowie Dienste, einschlie\u00dflich Unternehmensanwendungen, k\u00f6nnen den Zugriff sogar vollst\u00e4ndig blockieren.<\/p>\n<p>GlobalSign war die einzige internationale Zertifizierungsstelle, die bereits im Jahr 2013 eine Niederlassung in Russland er\u00f6ffnet hatte. Nachdem im M\u00e4rz 2022 internationale Zertifizierungsstellen die Ausstellung von Zertifikaten f\u00fcr die russischen Domains .RU, .\u0420\u0424, .SU sowie die wei\u00dfrussische Domain .BY eingestellt hatten, blieb GlobalSign die einzige gro\u00dfe kommerzielle Zertifizierungsstelle weltweit, die ihre Arbeit mit russischen Kunden in vollem Umfang fortsetzte.<\/p>\n<p><strong>Mehr zum Thema\u00a0\u2012 <\/strong><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de-rtnews.com\/europa\/281289-eu-bereitet-rekordstrafe-gegen-google-vor\/\">Google unter Druck: EU bereitet Rekordstrafe gegen IT-Konzern vor<\/a><\/p>\n<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/283242-japanische-globalsign-zieht-digitalen-ausweise\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eines der weltweit gr\u00f6\u00dften Zertifizierungszentren widerruft die Sicherheitszertifikate russischer Webseiten. Dies geschieht aus Sanktionsgr\u00fcnden \u2013 mit der m\u00f6glichen Folge, dass ausl\u00e4ndische Browser diese als unsicher einstufen. Russische Internetseiten verlieren m\u00f6glicherweise von einem Tag auf den anderen die Sichtbarkeit in ausl\u00e4ndischen Browsern. Die Folgen k\u00f6nnten nicht nur Zehntausende von Webseiten betreffen, sondern auch verschiedene Anwendungen, deren [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":105076,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1781547497"],"wp_automatic_camp":["217"],"05a25cdd029322b1f424f3b6b7b97f22":["GlobalSign zieht &quot;digitale Ausweise&quot; russischer Webseiten zur\u00fcck"],"original_link":["https:\/\/de.rt.com\/international\/283242-japanische-globalsign-zieht-digitalen-ausweise\/"],"_thumbnail_id":["105076"],"jnews_social_counter_last_update":["1784083008"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2026-06-15 20:19:17\";}"]},"categories":[19,23],"tags":[73866,73864,73865,793,51144,20511,3337],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>GlobalSign zieht &quot;digitale Ausweise&quot; russischer Webseiten zur\u00fcck - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GlobalSign zieht &quot;digitale Ausweise&quot; russischer Webseiten zur\u00fcck\" \/>\n<meta property=\"og:description\" content=\"Eines der weltweit gr\u00f6\u00dften Zertifizierungszentren widerruft die Sicherheitszertifikate russischer Webseiten. Dies geschieht aus Sanktionsgr\u00fcnden \u2013 mit der m\u00f6glichen Folge, dass ausl\u00e4ndische Browser diese als unsicher einstufen. Russische Internetseiten verlieren m\u00f6glicherweise von einem Tag auf den anderen die Sichtbarkeit in ausl\u00e4ndischen Browsern. Die Folgen k\u00f6nnten nicht nur Zehntausende von Webseiten betreffen, sondern auch verschiedene Anwendungen, deren [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-15T18:04:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/6a3015ffb480cc3a4c228ec5.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"GlobalSign zieht &quot;digitale Ausweise&quot; russischer Webseiten zur\u00fcck\",\"datePublished\":\"2026-06-15T18:04:12+00:00\",\"dateModified\":\"2026-06-15T18:04:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/\"},\"wordCount\":618,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/GlobalSign-zieht-quotdigitale-Ausweisequot-russischer-Webseiten-zurueck.jpg\",\"keywords\":[\"Ausweisequot\",\"GlobalSign\",\"quotdigitale\",\"Russischer\",\"Webseiten\",\"zieht\",\"zur\u00fcck\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/\",\"name\":\"GlobalSign zieht &quot;digitale Ausweise&quot; russischer Webseiten zur\u00fcck - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/GlobalSign-zieht-quotdigitale-Ausweisequot-russischer-Webseiten-zurueck.jpg\",\"datePublished\":\"2026-06-15T18:04:12+00:00\",\"dateModified\":\"2026-06-15T18:04:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/GlobalSign-zieht-quotdigitale-Ausweisequot-russischer-Webseiten-zurueck.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/GlobalSign-zieht-quotdigitale-Ausweisequot-russischer-Webseiten-zurueck.jpg\",\"width\":460,\"height\":259,\"caption\":\"GlobalSign zieht &quot;digitale Ausweise&quot; russischer Webseiten zur\u00fcck\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GlobalSign zieht &quot;digitale Ausweise&quot; russischer Webseiten zur\u00fcck\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"GlobalSign zieht &quot;digitale Ausweise&quot; russischer Webseiten zur\u00fcck - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/","og_locale":"de_DE","og_type":"article","og_title":"GlobalSign zieht &quot;digitale Ausweise&quot; russischer Webseiten zur\u00fcck","og_description":"Eines der weltweit gr\u00f6\u00dften Zertifizierungszentren widerruft die Sicherheitszertifikate russischer Webseiten. Dies geschieht aus Sanktionsgr\u00fcnden \u2013 mit der m\u00f6glichen Folge, dass ausl\u00e4ndische Browser diese als unsicher einstufen. Russische Internetseiten verlieren m\u00f6glicherweise von einem Tag auf den anderen die Sichtbarkeit in ausl\u00e4ndischen Browsern. Die Folgen k\u00f6nnten nicht nur Zehntausende von Webseiten betreffen, sondern auch verschiedene Anwendungen, deren [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2026-06-15T18:04:12+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/6a3015ffb480cc3a4c228ec5.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"GlobalSign zieht &quot;digitale Ausweise&quot; russischer Webseiten zur\u00fcck","datePublished":"2026-06-15T18:04:12+00:00","dateModified":"2026-06-15T18:04:12+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/"},"wordCount":618,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/GlobalSign-zieht-quotdigitale-Ausweisequot-russischer-Webseiten-zurueck.jpg","keywords":["Ausweisequot","GlobalSign","quotdigitale","Russischer","Webseiten","zieht","zur\u00fcck"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/","url":"https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/","name":"GlobalSign zieht &quot;digitale Ausweise&quot; russischer Webseiten zur\u00fcck - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/GlobalSign-zieht-quotdigitale-Ausweisequot-russischer-Webseiten-zurueck.jpg","datePublished":"2026-06-15T18:04:12+00:00","dateModified":"2026-06-15T18:04:12+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/GlobalSign-zieht-quotdigitale-Ausweisequot-russischer-Webseiten-zurueck.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/GlobalSign-zieht-quotdigitale-Ausweisequot-russischer-Webseiten-zurueck.jpg","width":460,"height":259,"caption":"GlobalSign zieht &quot;digitale Ausweise&quot; russischer Webseiten zur\u00fcck"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/globalsign-zieht-digitale-ausweise-russischer-webseiten-zurueck\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"GlobalSign zieht &quot;digitale Ausweise&quot; russischer Webseiten zur\u00fcck"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/105075"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=105075"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/105075\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/105076"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=105075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=105075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=105075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}