{"id":104900,"date":"2026-06-12T07:20:00","date_gmt":"2026-06-12T05:20:00","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\/"},"modified":"2026-06-12T07:20:00","modified_gmt":"2026-06-12T05:20:00","slug":"russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\/","title":{"rendered":"Russland nimmt Weizenexport nach Madagaskar wieder auf \u2013 Insgesamt mehr als 100 Abnehmerl\u00e4nder"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/6a2a981bb480cc5ce95ee0dd.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Russland ist nicht nur eine Atommacht, sondern auch ein Top-Produzent von Getreide. Nach einigen Jahren Pause hat das Land seinen Weizenexport nach Madagaskar wiederaufgenommen. \u00dcberhaupt entfallen auf L\u00e4nder in Nahost und Afrika gut 80 Prozent der russischen Weizenausfuhr.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Nach einer langen Unterbrechung hat Russland im laufenden Jahr den Export von Weizen nach Madagaskar wiederaufgenommen. Wie die Nachrichtenagentur <em>TASS<\/em> unter Berufung auf das F\u00f6derale Zentrum zur F\u00f6rderung des Agrarexports beim russischen Landwirtschaftsministerium (Agroexport) berichtet, wurden in den ersten f\u00fcnf Monaten dieses Jahres sch\u00e4tzungsweise gut 30.000 Tonnen Weizen an den ostafrikanischen Inselstaat verkauft. Der Wert der Lieferungen wurde dabei auf mehr als sieben Millionen US-Dollar beziffert.<\/p>\n<p>Zuletzt hatte Russland im Jahr 2021 nach Madagaskar Weizen exportiert. Damals erreichte das Gesamtvolumen der Lieferungen 66.000 Tonnen im Wert von mehr als 16 Millionen US-Dollar. Dagegen verkaufte das eurasische Land im Jahr 2025 an den Staat im Indischen Ozean kaum noch Landwirtschaftserzeugnisse.<\/p>\n<p>Mit Verweis auf die russische Landwirtschaftsministerin Oxana Lut schreibt\u00a0<em>TASS<\/em>, dass \u00fcberhaupt 82 Prozent des russischen Weizenexports auf L\u00e4nder in Afrika und im Nahen Osten entfallen. Demnach importieren mehr als 100 L\u00e4nder der Welt Getreide aus Russland, sodass das Land 20 Prozent des weltweiten Weizenexports abwickelt. Lut zufolge ist \u00c4gypten der gr\u00f6\u00dfte Abnehmer von Weizen aus dem eurasischen Land.<\/p>\n<p>Das Landwirtschaftsministerium in Moskau rechnet damit, dass in dieser Saison, die den Zeitraum vom 1. Juli 2025 bis zum 30. Juni 2026 umfasst, insgesamt rund 60 Millionen Tonnen Getreide, darunter 50 Millionen Tonnen Weizen, ins Ausland verkauft werden. Stand Ende Mai soll Russland schon 52 Millionen Tonnen Getreide auf die internationalen M\u00e4rkte geliefert haben. In der vergangenen Saison, das hei\u00dft im Zeitraum vom 1. Juli 2024 bis zum 30. Juni 2025, waren es insgesamt 53 Millionen Tonnen Getreide, darunter 44 Millionen Tonnen Weizen, gewesen.<\/p>\n<p><strong>Mehr zum Thema<\/strong>\u00a0\u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de-rtnews.com\/meinung\/258939-afrika-setzt-auf-russland-bergbau\/\">Afrika setzt auf Russland: Bergbau-Hochschule Sankt Petersburg hilft dem Kontinent<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v74xl4q\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/282844-russland-nimmt-weizenexport-nach-madagaskar-wieder-auf\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Russland ist nicht nur eine Atommacht, sondern auch ein Top-Produzent von Getreide. Nach einigen Jahren Pause hat das Land seinen Weizenexport nach Madagaskar wiederaufgenommen. \u00dcberhaupt entfallen auf L\u00e4nder in Nahost und Afrika gut 80 Prozent der russischen Weizenausfuhr. Nach einer langen Unterbrechung hat Russland im laufenden Jahr den Export von Weizen nach Madagaskar wiederaufgenommen. Wie [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":104901,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1781241783"],"wp_automatic_camp":["217"],"1aca50bdb0bd2f7cf1beaa67a73c7ac5":["Russland nimmt Weizenexport nach Madagaskar wieder auf \u2013 Insgesamt mehr als 100 Abnehmerl\u00e4nder"],"original_link":["https:\/\/de.rt.com\/international\/282844-russland-nimmt-weizenexport-nach-madagaskar-wieder-auf\/"],"_thumbnail_id":["104901"],"jnews_social_counter_last_update":["1788333908"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2026-06-12 07:24:05\";}"]},"categories":[19,23],"tags":[73787,273,133,20742,68446,2063,979,5233,126,67395,904],"class_list":["post-104900","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-abnehmerlaender","tag-als","tag-auf","tag-insgesamt","tag-madagaskar","tag-mehr","tag-nach","tag-nimmt","tag-russland","tag-weizenexport","tag-wieder"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Russland nimmt Weizenexport nach Madagaskar wieder auf \u2013 Insgesamt mehr als 100 Abnehmerl\u00e4nder - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Russland nimmt Weizenexport nach Madagaskar wieder auf \u2013 Insgesamt mehr als 100 Abnehmerl\u00e4nder\" \/>\n<meta property=\"og:description\" content=\"Russland ist nicht nur eine Atommacht, sondern auch ein Top-Produzent von Getreide. Nach einigen Jahren Pause hat das Land seinen Weizenexport nach Madagaskar wiederaufgenommen. \u00dcberhaupt entfallen auf L\u00e4nder in Nahost und Afrika gut 80 Prozent der russischen Weizenausfuhr. Nach einer langen Unterbrechung hat Russland im laufenden Jahr den Export von Weizen nach Madagaskar wiederaufgenommen. Wie [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-12T05:20:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/6a2a981bb480cc5ce95ee0dd.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Russland nimmt Weizenexport nach Madagaskar wieder auf \u2013 Insgesamt mehr als 100 Abnehmerl\u00e4nder\",\"datePublished\":\"2026-06-12T05:20:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\\\/\"},\"wordCount\":306,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/Russland-nimmt-Weizenexport-nach-Madagaskar-wieder-auf-\u2013-Insgesamt-mehr.jpg\",\"keywords\":[\"Abnehmerl\u00e4nder\",\"als\",\"AUF\",\"Insgesamt\",\"Madagaskar\",\"mehr\",\"nach\",\"nimmt\",\"russland\",\"Weizenexport\",\"wieder\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\\\/\",\"name\":\"Russland nimmt Weizenexport nach Madagaskar wieder auf \u2013 Insgesamt mehr als 100 Abnehmerl\u00e4nder - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/Russland-nimmt-Weizenexport-nach-Madagaskar-wieder-auf-\u2013-Insgesamt-mehr.jpg\",\"datePublished\":\"2026-06-12T05:20:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/Russland-nimmt-Weizenexport-nach-Madagaskar-wieder-auf-\u2013-Insgesamt-mehr.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/Russland-nimmt-Weizenexport-nach-Madagaskar-wieder-auf-\u2013-Insgesamt-mehr.jpg\",\"caption\":\"Russland nimmt Weizenexport nach Madagaskar wieder auf \u2013 Insgesamt mehr als 100 Abnehmerl\u00e4nder\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Russland nimmt Weizenexport nach Madagaskar wieder auf \u2013 Insgesamt mehr als 100 Abnehmerl\u00e4nder\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Russland nimmt Weizenexport nach Madagaskar wieder auf \u2013 Insgesamt mehr als 100 Abnehmerl\u00e4nder - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\/","og_locale":"de_DE","og_type":"article","og_title":"Russland nimmt Weizenexport nach Madagaskar wieder auf \u2013 Insgesamt mehr als 100 Abnehmerl\u00e4nder","og_description":"Russland ist nicht nur eine Atommacht, sondern auch ein Top-Produzent von Getreide. Nach einigen Jahren Pause hat das Land seinen Weizenexport nach Madagaskar wiederaufgenommen. \u00dcberhaupt entfallen auf L\u00e4nder in Nahost und Afrika gut 80 Prozent der russischen Weizenausfuhr. Nach einer langen Unterbrechung hat Russland im laufenden Jahr den Export von Weizen nach Madagaskar wiederaufgenommen. Wie [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2026-06-12T05:20:00+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/06\/6a2a981bb480cc5ce95ee0dd.jpg","type":"","width":"","height":""}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Russland nimmt Weizenexport nach Madagaskar wieder auf \u2013 Insgesamt mehr als 100 Abnehmerl\u00e4nder","datePublished":"2026-06-12T05:20:00+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\/"},"wordCount":306,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Russland-nimmt-Weizenexport-nach-Madagaskar-wieder-auf-\u2013-Insgesamt-mehr.jpg","keywords":["Abnehmerl\u00e4nder","als","AUF","Insgesamt","Madagaskar","mehr","nach","nimmt","russland","Weizenexport","wieder"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\/","url":"https:\/\/now-news.de\/de\/deutschland\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\/","name":"Russland nimmt Weizenexport nach Madagaskar wieder auf \u2013 Insgesamt mehr als 100 Abnehmerl\u00e4nder - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Russland-nimmt-Weizenexport-nach-Madagaskar-wieder-auf-\u2013-Insgesamt-mehr.jpg","datePublished":"2026-06-12T05:20:00+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Russland-nimmt-Weizenexport-nach-Madagaskar-wieder-auf-\u2013-Insgesamt-mehr.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Russland-nimmt-Weizenexport-nach-Madagaskar-wieder-auf-\u2013-Insgesamt-mehr.jpg","caption":"Russland nimmt Weizenexport nach Madagaskar wieder auf \u2013 Insgesamt mehr als 100 Abnehmerl\u00e4nder"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/russland-nimmt-weizenexport-nach-madagaskar-wieder-auf-insgesamt-mehr-als-100-abnehmerlaender\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Russland nimmt Weizenexport nach Madagaskar wieder auf \u2013 Insgesamt mehr als 100 Abnehmerl\u00e4nder"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/104900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=104900"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/104900\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/104901"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=104900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=104900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=104900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}