{"id":103828,"date":"2026-05-25T16:05:43","date_gmt":"2026-05-25T14:05:43","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/"},"modified":"2026-05-25T16:05:43","modified_gmt":"2026-05-25T14:05:43","slug":"tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/","title":{"rendered":"Tschechien: Russischer Metropolit wegen angeblichen Drogenbesitzes festgenommen"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/05\/6a14482648fbef149e09f7b3.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Im tschechischen Karlsbad ist am Sonntag ein russisch-orthodoxer Metropolit festgenommen worden. Die Polizei stellte ihm einen Hinterhalt, als er nach dem Gottesdienst die \u00f6rtliche Kirche im PKW verlie\u00df. Ihm wird Drogenbesitz vorgeworfen, der Geistliche bestreitet dies und spricht von einer Provokation.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Die tschechische Polizei hat den russisch-orthodoxen Metropoliten im Ruhestand Hilarion (Alfejew) wegen des Verdachts auf Drogenbesitz festgenommen, berichtet <em>RIA Nowosti<\/em> unter Berufung auf einen Mitarbeiter des Geistlichen.<\/p>\n<p><em>&#8220;Um 10:30 Uhr (am Montag, d. Red.) begann die Vernehmung des Metropoliten unter Beteiligung eines Staatsanwalts, eines Richters, des russischen Konsuls und eines Anwalts. Gestern wurde ihm offiziell der Verdacht auf eine Straftat \u2013 der Besitz von Bet\u00e4ubungsmitteln \u2013 er\u00f6ffnet. Auf dieser Grundlage wurde er festgenommen, in Untersuchungshaft genommen&#8221;<\/em>, berichtet der namentlich nicht genannte Mitarbeiter.<\/p>\n<p>In der Nacht auf Montag habe der 59 Jahre alte Hilarion Besuch von einem Anwalt sowie vom russischen Konsul erhalten, der sich ein Bild von den Haftbedingungen machen und alles \u00fcberpr\u00fcfen konnte, f\u00fcgte er hinzu.<\/p>\n<p>Im Telegram-Kanal des Metropoliten hei\u00dft es, dass sein Auto am Vortag von der Polizei angehalten worden sei und diese angeblich im Kofferraum vier kleine Beh\u00e4lter &#8220;mit einer wei\u00dfen Substanz&#8221; gefunden habe. In dem Beitrag werden auch die Worte des Verteidigers des Metropoliten wiedergegeben. Er pr\u00e4zisierte, dass der Geistliche zum Zeitpunkt der Durchsuchung in einen Laden an der Tankstelle gef\u00fchrt und faktisch daran gehindert wurde, zu beobachten, was die Sicherheitskr\u00e4fte an seinem Auto machen.<\/p>\n<p>Die Polizei stoppte den Wagen, als der Metropolit nach dem sonnt\u00e4glichen Gottesdienst die Peter-und-Paul-Kirche in Karlsbad verlie\u00df, in deren N\u00e4he, wird auf Hilarions Telegramkanal weiter ausgef\u00fchrt. Es wurde kein Grund f\u00fcr das Anhalten mitgeteilt, die Beamten h\u00e4tten sofort mit der Durchsuchung des PKW begonnen. Zeugen zufolge h\u00e4tten zwei Polizeiwagen auf den Metropoliten gewartet. Als sie den Wagen des Geistlichen erblickten, fuhren die Einsatzwagen los \u2013 einer vor dem PKW des Metropoliten, einer hinter ihm. Es habe den den Eindruck erweckt, dass es sich nicht um eine Verkehrskontrolle, sondern um einen f\u00fcr Hilarion eingerichteten Hinterhalt handelte. Es habe auch keinerlei sichtbaren Anlass f\u00fcr eine Verkehrskontrolle gegeben, die Beamten h\u00e4tten auch keinen Verkehrsversto\u00df behauptet.<\/p>\n<p>Metropolit Hilarion selbst bezeichnete den Vorfall als Provokation und bestritt jegliche Schuld. Seinen Angaben zufolge habe er in den letzten Monaten wiederholt anonyme Drohungen erhalten, darunter auch mit k\u00f6rperlicher Gewalt, mit der Aufforderung, Tschechien zu verlassen.<\/p>\n<p>Von 2009 bis 2022 leitete der auch als Komponist, Buchautor und TV-Prediger begabte Theologe die Abteilung f\u00fcr kirchliche Au\u00dfenbeziehungen des Moskauer Patriarchats und war damit einer der aussichtsreichen Nachwuchskandidaten f\u00fcr das Patriarchenamt. Als TV-Prediger fiel er auch mit kontroversen \u00c4u\u00dferungen auf. So hatte er 2021 erkl\u00e4rt, Impfverweigerer w\u00fcrden eine S\u00fcnde begehen und sich f\u00fcr den Tod von Angesteckten verantwortlich machen, <em>RT DE<\/em> hatte <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de-rtnews.com\/russland\/120250-russisch-orthodoxe-kirche-impfverweigerer-begehen\/\">berichtet<\/a>.<\/p>\n<p>Nachdem der Patriarch von Konstantinopel eine neu gegr\u00fcndete ukrainische Nationalkirche <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de-rtnews.com\/europa\/77707-nach-kirchenstreit-wegen-ukraine-russische\/\">anerkannt hatte<\/a>, was als pers\u00f6nliche Verantwortung und Niederlage von Hilarion galt, verlor er diesen Posten und \u00fcbernahm die Leitung der Di\u00f6zese Budapest-Ungarn.<\/p>\n<p>Im Juli 2024 versetzte ihn die Russisch-Orthodoxe Kirche nach nie aufgekl\u00e4rten Ger\u00fcchten, die seine private Lebensf\u00fchrung betrafen, in den Ruhestand mit Alterssitz im tschechischen Karlsbad. In Tschechien wurde 2025 \u00f6ffentlich diskutiert, ihn zur Persona non grata zu erkl\u00e4ren.<\/p>\n<p><strong>Mehr zum Thema<\/strong>\u00a0<strong>\u2013<\/strong>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de-rtnews.com\/newsticker\/77650-russische-kirche-bricht-beziehungen-zu\/\">Vertiefte Spaltung: Russische Kirche bricht Beziehungen zu Konstantinopel ab<\/a><\/p>\n<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/europa\/281174-metropolit-rok-im-ruhestand-hilarion-verhaftet\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im tschechischen Karlsbad ist am Sonntag ein russisch-orthodoxer Metropolit festgenommen worden. Die Polizei stellte ihm einen Hinterhalt, als er nach dem Gottesdienst die \u00f6rtliche Kirche im PKW verlie\u00df. Ihm wird Drogenbesitz vorgeworfen, der Geistliche bestreitet dies und spricht von einer Provokation. Die tschechische Polizei hat den russisch-orthodoxen Metropoliten im Ruhestand Hilarion (Alfejew) wegen des Verdachts [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":103829,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1779718042"],"wp_automatic_camp":["217"],"d66e079f8503c135cab34865e6488c12":["Tschechien: Russischer Metropolit wegen angeblichen Drogenbesitzes festgenommen"],"original_link":["https:\/\/de.rt.com\/europa\/281174-metropolit-rok-im-ruhestand-hilarion-verhaftet\/"],"_thumbnail_id":["103829"],"jnews_social_counter_last_update":["1784147402"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2026-05-25 16:08:20\";}"]},"categories":[19,23],"tags":[16552,73297,1356,42681,793,32609,145],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tschechien: Russischer Metropolit wegen angeblichen Drogenbesitzes festgenommen - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tschechien: Russischer Metropolit wegen angeblichen Drogenbesitzes festgenommen\" \/>\n<meta property=\"og:description\" content=\"Im tschechischen Karlsbad ist am Sonntag ein russisch-orthodoxer Metropolit festgenommen worden. Die Polizei stellte ihm einen Hinterhalt, als er nach dem Gottesdienst die \u00f6rtliche Kirche im PKW verlie\u00df. Ihm wird Drogenbesitz vorgeworfen, der Geistliche bestreitet dies und spricht von einer Provokation. Die tschechische Polizei hat den russisch-orthodoxen Metropoliten im Ruhestand Hilarion (Alfejew) wegen des Verdachts [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-25T14:05:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/05\/6a14482648fbef149e09f7b3.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Tschechien: Russischer Metropolit wegen angeblichen Drogenbesitzes festgenommen\",\"datePublished\":\"2026-05-25T14:05:43+00:00\",\"dateModified\":\"2026-05-25T14:05:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/\"},\"wordCount\":560,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Tschechien-Russischer-Metropolit-wegen-angeblichen-Drogenbesitzes-festgenommen.jpg\",\"keywords\":[\"angeblichen\",\"Drogenbesitzes\",\"festgenommen\",\"Metropolit\",\"Russischer\",\"Tschechien\",\"wegen\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/\",\"name\":\"Tschechien: Russischer Metropolit wegen angeblichen Drogenbesitzes festgenommen - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Tschechien-Russischer-Metropolit-wegen-angeblichen-Drogenbesitzes-festgenommen.jpg\",\"datePublished\":\"2026-05-25T14:05:43+00:00\",\"dateModified\":\"2026-05-25T14:05:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Tschechien-Russischer-Metropolit-wegen-angeblichen-Drogenbesitzes-festgenommen.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Tschechien-Russischer-Metropolit-wegen-angeblichen-Drogenbesitzes-festgenommen.jpg\",\"caption\":\"Tschechien: Russischer Metropolit wegen angeblichen Drogenbesitzes festgenommen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tschechien: Russischer Metropolit wegen angeblichen Drogenbesitzes festgenommen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tschechien: Russischer Metropolit wegen angeblichen Drogenbesitzes festgenommen - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/","og_locale":"de_DE","og_type":"article","og_title":"Tschechien: Russischer Metropolit wegen angeblichen Drogenbesitzes festgenommen","og_description":"Im tschechischen Karlsbad ist am Sonntag ein russisch-orthodoxer Metropolit festgenommen worden. Die Polizei stellte ihm einen Hinterhalt, als er nach dem Gottesdienst die \u00f6rtliche Kirche im PKW verlie\u00df. Ihm wird Drogenbesitz vorgeworfen, der Geistliche bestreitet dies und spricht von einer Provokation. Die tschechische Polizei hat den russisch-orthodoxen Metropoliten im Ruhestand Hilarion (Alfejew) wegen des Verdachts [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2026-05-25T14:05:43+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/05\/6a14482648fbef149e09f7b3.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Tschechien: Russischer Metropolit wegen angeblichen Drogenbesitzes festgenommen","datePublished":"2026-05-25T14:05:43+00:00","dateModified":"2026-05-25T14:05:43+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/"},"wordCount":560,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Tschechien-Russischer-Metropolit-wegen-angeblichen-Drogenbesitzes-festgenommen.jpg","keywords":["angeblichen","Drogenbesitzes","festgenommen","Metropolit","Russischer","Tschechien","wegen"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/","url":"https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/","name":"Tschechien: Russischer Metropolit wegen angeblichen Drogenbesitzes festgenommen - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Tschechien-Russischer-Metropolit-wegen-angeblichen-Drogenbesitzes-festgenommen.jpg","datePublished":"2026-05-25T14:05:43+00:00","dateModified":"2026-05-25T14:05:43+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Tschechien-Russischer-Metropolit-wegen-angeblichen-Drogenbesitzes-festgenommen.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Tschechien-Russischer-Metropolit-wegen-angeblichen-Drogenbesitzes-festgenommen.jpg","caption":"Tschechien: Russischer Metropolit wegen angeblichen Drogenbesitzes festgenommen"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/tschechien-russischer-metropolit-wegen-angeblichen-drogenbesitzes-festgenommen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Tschechien: Russischer Metropolit wegen angeblichen Drogenbesitzes festgenommen"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/103828"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=103828"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/103828\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/103829"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=103828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=103828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=103828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}