{"id":103813,"date":"2026-05-25T12:18:46","date_gmt":"2026-05-25T10:18:46","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/"},"modified":"2026-05-25T12:18:46","modified_gmt":"2026-05-25T10:18:46","slug":"bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/","title":{"rendered":"BAf\u00f6G-Erh\u00f6hung f\u00e4llt Aufr\u00fcstung und Krieg zum Opfer"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/05\/6a141bbab480cc29851390a4.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Jens Spahn, in seiner Zeit als Gesundheitsminister unter Angela Merkel nicht gerade f\u00fcr seine Sparsamkeit bekannt, k\u00fcndigte nun an, Erh\u00f6hungen bei staatlichen Leistungen m\u00fcssten unterbleiben \u2012 auch beim BAf\u00f6G, dessen Anpassung an die realen Kosten im Koalitionsvertrag steht.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Die angek\u00fcndigte BAF\u00f6G-Erh\u00f6hung, die im August in Kraft treten sollte, war eines der wenigen zukunftssichernden Vorhaben der schwarz-roten Koalition. Zum kommenden Wintersemester sollte die Wohnkostenpauschale f\u00fcr Studenten, die nicht mehr bei den Eltern wohnen, von 380 auf 440 Euro erh\u00f6ht werden. Laut einer regelm\u00e4\u00dfig erhobenen <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.moses-mendelssohn-institut.de\/aktuelles\/Studentische_Wohnkosten_Hochschulorte_WiSe_2025_2026\/\">Studie<\/a> liegen die realen Wohnkosten\u00a0im bundesweiten Durchschnitt bereits bei 505 Euro. Dabei liegen die Mieten schon in 70 von 88 St\u00e4dten \u00fcber dem heute g\u00fcltigen Wert der Wohnkostenpauschale.<\/p>\n<p>Das urspr\u00fcngliche Ziel im Koalitionsvertrag lautete, das BAf\u00f6G schrittweise auf das Niveau der Grundsicherung anzuheben. Das BAf\u00f6G ist die wichtigste Leistung, um Kindern aus \u00e4rmeren Familien ein Studium zu erm\u00f6glichen.\u00a0Der Anteil der BAf\u00f6G-Gef\u00f6rderten unter den Studenten und der Arbeiterkinder an den Universit\u00e4ten korreliert direkt.<\/p>\n<p>Zu den Hochzeiten, Anfang der 1970er, hatten einmal \u00fcber 40 Prozent der Studenten BAf\u00f6G bezogen \u2012 inzwischen sind es nur noch zwischen 11 und 12 Prozent. Der Durchschnitt der BAf\u00f6G-Leistungen 2024 lag bei 635 Euro. Besonders viele Studenten, die BAf\u00f6G beziehen, studieren auf Lehramt \u2012 bekanntlich derzeit ein Beruf mit Nachwuchsproblemen.<\/p>\n<p>Am Samstag erkl\u00e4rte nun Jens Spahn \u2012 trotz mehrerer Skandale um Maskenk\u00e4ufe zu Corona-Zeiten und den Erwerb einer verg\u00fcnstigten Villa in Berlin \u2012, die BAf\u00f6G-Erh\u00f6hung k\u00f6nne nicht umgesetzt werden. In einem <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.merkur.de\/politik\/spahn-ueber-buergergeld-empfinden-die-menschen-zurecht-als-ungerecht-zr-94319662.html\">Interview<\/a> mit dem <em>M\u00fcnchner Merkur<\/em> sagte der Fraktionsvorsitzende der CDU\/CSU: &#8220;Staatliche Leistungen wie B\u00fcrgergeld, Wohngeld, Elterngeld, BAf\u00f6G werden wir absehbar nicht erh\u00f6hen k\u00f6nnen, in manchen Bereichen m\u00fcssen wir sparen \u2013 jedenfalls solange wir kein Wachstum haben.&#8221;<\/p>\n<p>Wenn man die Zahl der 2024 gef\u00f6rderten Studenten zur Grundlage nimmt, 484.000, dann erg\u00e4be die Erh\u00f6hung der Wohnkostenpauschale einen Aufwand von 316 Millionen Euro. Die H\u00e4lfte der BAf\u00f6G-Leistung wird als Darlehen gezahlt\u00a0\u2012 die reale Belastung f\u00fcr den Bundeshaushalt liegt also nur bei 157 Millionen. Verglichen mit den Summen, die allein f\u00fcr den vom deutschen Steuerzahler zu schulternden Teil der 90 Milliarden &#8220;Kredit&#8221; an die Ukraine f\u00e4llig werden\u00a0und nach dem deutschen Anteil am EU-Haushalt bei etwa einem Drittel liegen d\u00fcrften, geradezu banal.<\/p>\n<p>Der Vorsitzende des Deutschen Studierendenwerks, Matthias Anbuhl, <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.spiegel.de\/start\/bafoeg-studierende-empoert-ueber-jens-spahns-absage-an-hoehere-saetze-a-b4a41f00-4952-4830-97fe-ec155e462a79\">reagierte<\/a> im <em>Spiegel<\/em> dementsprechend: &#8220;Wer eine Milliardensumme f\u00fcr einen Tankrabatt ausgibt und gleichzeitig an Bildungschancen sparen will, agiert leistungsfeindlich und zukunftsblind.&#8221;<\/p>\n<p>Das Publikum in den sozialen Medien reagierte zum Teil noch direkter:<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet lazyload\" data-twitter=\"twitter-tweet\">\n<p lang=\"de\" dir=\"ltr\">F\u00fcr das Geld, dass der ach so feine Herr f\u00fcr seine Masken in den Sand gesetzt hat, h\u00e4tte man das Baf\u00f6g flei\u00dfig erh\u00f6hen k\u00f6nnen<\/p>\n<p>\u2014 Bernard Sheyan (@BSheyan80613) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/BSheyan80613\/status\/2058796592266633237?ref_src=twsrc%5Etfw\">May 25, 2026<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<p><strong>Mehr zum Thema<\/strong>\u00a0\u2012 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de-rtnews.com\/inland\/217297-studieren-wird-in-deutschland-zum-luxus\/\">Alles wird teurer, mickrige BAf\u00f6G-S\u00e4tze: Studieren wird in Deutschland zum Luxus<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v5arnad\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/281160-bafoeg-erhoehung-faellt-aufruestung-und\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jens Spahn, in seiner Zeit als Gesundheitsminister unter Angela Merkel nicht gerade f\u00fcr seine Sparsamkeit bekannt, k\u00fcndigte nun an, Erh\u00f6hungen bei staatlichen Leistungen m\u00fcssten unterbleiben \u2012 auch beim BAf\u00f6G, dessen Anpassung an die realen Kosten im Koalitionsvertrag steht. Die angek\u00fcndigte BAF\u00f6G-Erh\u00f6hung, die im August in Kraft treten sollte, war eines der wenigen zukunftssichernden Vorhaben der [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":103814,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1779704591"],"wp_automatic_camp":["217"],"07f0a90c242df7fcfdf09406351e2bc2":["BAf\u00f6G-Erh\u00f6hung f\u00e4llt Aufr\u00fcstung und Krieg zum Opfer"],"original_link":["https:\/\/de.rt.com\/inland\/281160-bafoeg-erhoehung-faellt-aufruestung-und\/"],"_thumbnail_id":["103814"],"jnews_social_counter_last_update":["1784079643"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2026-05-25 12:24:21\";}"]},"categories":[19,23],"tags":[24790,73291,1939,130,497,140,565],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>BAf\u00f6G-Erh\u00f6hung f\u00e4llt Aufr\u00fcstung und Krieg zum Opfer - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BAf\u00f6G-Erh\u00f6hung f\u00e4llt Aufr\u00fcstung und Krieg zum Opfer\" \/>\n<meta property=\"og:description\" content=\"Jens Spahn, in seiner Zeit als Gesundheitsminister unter Angela Merkel nicht gerade f\u00fcr seine Sparsamkeit bekannt, k\u00fcndigte nun an, Erh\u00f6hungen bei staatlichen Leistungen m\u00fcssten unterbleiben \u2012 auch beim BAf\u00f6G, dessen Anpassung an die realen Kosten im Koalitionsvertrag steht. Die angek\u00fcndigte BAF\u00f6G-Erh\u00f6hung, die im August in Kraft treten sollte, war eines der wenigen zukunftssichernden Vorhaben der [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-25T10:18:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/05\/6a141bbab480cc29851390a4.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"BAf\u00f6G-Erh\u00f6hung f\u00e4llt Aufr\u00fcstung und Krieg zum Opfer\",\"datePublished\":\"2026-05-25T10:18:46+00:00\",\"dateModified\":\"2026-05-25T10:18:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/\"},\"wordCount\":486,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/BAfoeG-Erhoehung-faellt-Aufruestung-und-Krieg-zum-Opfer.jpg\",\"keywords\":[\"Aufr\u00fcstung\",\"BAf\u00f6GErh\u00f6hung\",\"f\u00e4llt\",\"krieg\",\"Opfer\",\"und\",\"zum\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/\",\"name\":\"BAf\u00f6G-Erh\u00f6hung f\u00e4llt Aufr\u00fcstung und Krieg zum Opfer - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/BAfoeG-Erhoehung-faellt-Aufruestung-und-Krieg-zum-Opfer.jpg\",\"datePublished\":\"2026-05-25T10:18:46+00:00\",\"dateModified\":\"2026-05-25T10:18:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/BAfoeG-Erhoehung-faellt-Aufruestung-und-Krieg-zum-Opfer.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/BAfoeG-Erhoehung-faellt-Aufruestung-und-Krieg-zum-Opfer.jpg\",\"caption\":\"BAf\u00f6G-Erh\u00f6hung f\u00e4llt Aufr\u00fcstung und Krieg zum Opfer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BAf\u00f6G-Erh\u00f6hung f\u00e4llt Aufr\u00fcstung und Krieg zum Opfer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"BAf\u00f6G-Erh\u00f6hung f\u00e4llt Aufr\u00fcstung und Krieg zum Opfer - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/","og_locale":"de_DE","og_type":"article","og_title":"BAf\u00f6G-Erh\u00f6hung f\u00e4llt Aufr\u00fcstung und Krieg zum Opfer","og_description":"Jens Spahn, in seiner Zeit als Gesundheitsminister unter Angela Merkel nicht gerade f\u00fcr seine Sparsamkeit bekannt, k\u00fcndigte nun an, Erh\u00f6hungen bei staatlichen Leistungen m\u00fcssten unterbleiben \u2012 auch beim BAf\u00f6G, dessen Anpassung an die realen Kosten im Koalitionsvertrag steht. Die angek\u00fcndigte BAF\u00f6G-Erh\u00f6hung, die im August in Kraft treten sollte, war eines der wenigen zukunftssichernden Vorhaben der [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2026-05-25T10:18:46+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/05\/6a141bbab480cc29851390a4.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"BAf\u00f6G-Erh\u00f6hung f\u00e4llt Aufr\u00fcstung und Krieg zum Opfer","datePublished":"2026-05-25T10:18:46+00:00","dateModified":"2026-05-25T10:18:46+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/"},"wordCount":486,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/BAfoeG-Erhoehung-faellt-Aufruestung-und-Krieg-zum-Opfer.jpg","keywords":["Aufr\u00fcstung","BAf\u00f6GErh\u00f6hung","f\u00e4llt","krieg","Opfer","und","zum"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/","url":"https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/","name":"BAf\u00f6G-Erh\u00f6hung f\u00e4llt Aufr\u00fcstung und Krieg zum Opfer - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/BAfoeG-Erhoehung-faellt-Aufruestung-und-Krieg-zum-Opfer.jpg","datePublished":"2026-05-25T10:18:46+00:00","dateModified":"2026-05-25T10:18:46+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/BAfoeG-Erhoehung-faellt-Aufruestung-und-Krieg-zum-Opfer.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/BAfoeG-Erhoehung-faellt-Aufruestung-und-Krieg-zum-Opfer.jpg","caption":"BAf\u00f6G-Erh\u00f6hung f\u00e4llt Aufr\u00fcstung und Krieg zum Opfer"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/bafoeg-erhoehung-faellt-aufruestung-und-krieg-zum-opfer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"BAf\u00f6G-Erh\u00f6hung f\u00e4llt Aufr\u00fcstung und Krieg zum Opfer"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/103813"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=103813"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/103813\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/103814"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=103813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=103813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=103813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}