{"id":10295,"date":"2022-06-09T08:23:11","date_gmt":"2022-06-09T06:23:11","guid":{"rendered":"http:\/\/just-now.news\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/"},"modified":"2022-06-09T08:23:11","modified_gmt":"2022-06-09T06:23:11","slug":"verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/","title":{"rendered":"Verantwortungslose Egozentrik: Wie Merkel \u00fcber Putin redet und sich selbst blo\u00dfstellt"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/62a1811548fbef44e37e3ef5.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                In fr\u00fcheren Jahrhunderten wurden die Eigenschaften politischer Gestalten oft anhand von Anekdoten \u00fcberliefert. In der Geschichte von Friedrich II. und dem M\u00fcller etwa. Merkel liefert ihre Anekdote selbst. Aber sie erz\u00e4hlt etwas v\u00f6llig anderes, als was vom Mainstream aus ihr herausgelesen wird.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>von Dagmar Henn<\/em><\/p>\n<p>Nein, ich habe es mir nicht angesehen, das lange Gespr\u00e4ch mit Angela Merkel. Mein Nervenkost\u00fcm vertr\u00e4gt die deutschen Medien nur in begrenzten Dosen, und gleiches gilt f\u00fcr die entsprechenden Politiker, selbst wenn es ehemalige sind. Aber \u00fcber eine Stelle bin ich dann doch <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.merkur.de\/politik\/angela-merkel-interview-heute-wladimir-putin-ukraine-krieg-news-konflikt-russland-fernsehen-phoenix-kanzlerin-zr-91595832.html\">gestolpert<\/a>, zwischen dem Geraune, sie habe Putin durchschaut, und ihren entsprechend absurden Zitaten. Weil sie wirklich viel dar\u00fcber aussagt, was die deutsche Politik verloren hat, auch durch Merkel.<\/p>\n<blockquote>\n<p><em>&#8220;F\u00fcr ihn war der Zerfall der Sowjetunion die schlimmste Sache des 20. Jahrhunderts. Ich habe ihm gesagt: &#8216;Wei\u00dft du, f\u00fcr mich war das der Gl\u00fccksumstand meines Lebens: So konnte ich eben in die Freiheit und dann eben auch machen, was mir Spa\u00df und Freude macht.&#8217; Da war schon klar, dass da ein gro\u00dfer Dissens ist.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Es ist nicht wirklich erstaunlich, dass in der deutschen Presse niemand merkt, wie abgr\u00fcndig diese S\u00e4tze sind; so ist nun einmal das Niveau. Aber versuchen wir doch mal, diese S\u00e4tze auf eine einfachere, allt\u00e4glichere Ebene zu \u00fcbersetzen.<\/p>\n<p>Man stelle sich zwei H\u00e4user vor. Eines der beiden brennt ab, mehrere der Bewohner kommen dabei ums Leben. L\u00e4ngere Zeit danach trifft sich einer der Bewohner mit jemandem aus dem Nachbarhaus und sagt, wie schrecklich dieser Brand war. Und der Nachbar antwortet darauf: &#8220;Das finde ich nicht. Die Aussicht aus meinem Wohnzimmer ist jetzt viel sch\u00f6ner.&#8221;<\/p>\n<p>Merkel erz\u00e4hlt, ohne gro\u00df dar\u00fcber nachzudenken, eine Geschichte, in der sie, wie eine Pubertierende, die Welt nicht anders wahrnehmen kann als auf sich selbst bezogen. Sie hat Vorteile, also ist alles gut, gleich, wie viele Menschen das mit dem Leben bezahlten.<\/p>\n<p>Dieses Muster hat Deutschland vier Wahlperioden lang regiert: Egozentrik ohne jedes Verantwortungsgef\u00fchl. Ohne jede Wahrnehmung f\u00fcr die Differenz zwischen dem \u00d6ffentlichen und dem Privaten, zwischen dem Individuellen und dem Kollektiven und zwischen dem Anekdotischen und dem Historischen.<\/p>\n<p>Das Ende der Sowjetunion war nicht nur f\u00fcr die Menschen dort eine Katastrophe. Es f\u00fchrte nicht nur zu einer massiven Verelendung breiter Massen, zu einem Absinken der Lebenserwartung in Russland, zu einer fast vollst\u00e4ndigen Deindustrialisierung eines der f\u00fchrenden Industriel\u00e4nder dieser Erde. Es f\u00fchrte ganz nebenbei beispielsweise auch zum Zusammenbruch des indischen Gesundheitswesens, weil Indien die Rohstoffe, die die Sowjetunion im Tauschhandel geliefert hatte, jetzt gegen m\u00fchsam zu erwirtschaftende Dollar kaufen musste. Indien war schon damals ein Land mit \u00fcber einer Milliarde Einwohner. Wie viele Millionen hat diese Ver\u00e4nderung das Leben gekostet? In Indien allein?<\/p>\n<p>Und welche Folgen hatte die US-amerikanische Allmacht, die daraufhin ausbrach? In Asien, Afrika, Lateinamerika? Wie viel Elend h\u00e4tte es nicht gegeben? Wie viele Kriege w\u00e4ren nicht gef\u00fchrt worden? Libyen w\u00e4re heute noch das moderne Land, das es einmal war, und keine Ruine. Ebenso der Irak. Die Welt w\u00e4re von der Welle des islamistischen Terrors verschont geblieben, der erst mit den gegen die Sowjetunion gerichteten Man\u00f6vern der USA in Afghanistan gro\u00df wurde. Wie hoch ist die Summe der Opfer? Zehn Millionen?<\/p>\n<p>Die halbe Million irakischer Kinder, deren Tod Madeleine Albright so unbedeutend fand, w\u00e4re nicht umgekommen. Das ist ein Land von vielen, in denen sich dieser eine Faktor, das Ende der Sowjetunion, auswirkte. Wie viele Tote ist die Freiheit einer Angela Merkel wert? Dass sie &#8220;dann eben auch machen&#8221; konnte, was ihr &#8220;Spa\u00df und Freude macht&#8221;?<\/p>\n<p>Nicht einmal das Elend, das unmittelbar vor ihrer Haust\u00fcr stattfand, dieses gigantische \u00f6konomische Nichts in Mecklenburg, nicht die unz\u00e4hligen nicht anerkannten Berufsabschl\u00fcsse, die zerst\u00f6rten Industrien, die verschwundene d\u00f6rfliche Infrastruktur, das ausgel\u00f6schte Kulturleben rund um sie herum hatte Gewicht gegen den Spa\u00df, den Angela Merkel an ihrer Freiheit hatte.<\/p>\n<p>Es gibt bestimmte Eigenschaften, die ein Mensch, der eine Regierung leitet, haben sollte. Eine sehr wichtige davon ist die Wahrnehmung von Verantwortung. Das Wissen darum, dass es eben nicht um den pers\u00f6nlichen Spa\u00dffaktor geht, auch nicht darum, was man nett oder weniger nett findet, sondern um das ganz konkrete Leben ganz konkreter Menschen, ihre Bed\u00fcrfnisse, ihre Zukunft. Ein Mensch, der die mindesten Anforderungen an ein politisches Amt oberhalb einer Kleingemeinde erf\u00fcllt, h\u00e4tte sagen k\u00f6nnen: F\u00fcr mich war es ein Gl\u00fccksfall, aber f\u00fcr viele andere leider nicht. Angela Merkel sp\u00fcrt selbst nach 16 Jahren Kanzlerschaft die Notwendigkeit dieses &#8220;aber&#8221; nicht.<\/p>\n<p>Das erkl\u00e4rt nat\u00fcrlich, wie sie im Jahr 2015 mehr als eine Million Menschen in das Land lassen konnte, ohne danach auch nur einen Handschlag zu unternehmen, die Wohnungen zu bauen, die auch diese Menschen brauchen (von all denen, die in Deutschland davor schon welche brauchten, ganz zu schweigen). Sie f\u00fchlte sich nicht verantwortlich. Helmut Kohl hatte sie aus dem Nichts zur Ministerin gemacht. Dann lernte sie eifrig das Intrigenspiel, und wie man mit Liz Mohn und Friede Springer Kaffee trinkt. War da sonst noch was?<\/p>\n<p>Merkel entlarvt sich mit diesen S\u00e4tzen als eine Art Probemodell f\u00fcr Baerbock. Ihre &#8220;Freiheit&#8221; war immer schon eine, die auf einem Mangel an Rechenschaftspflicht beruhte, und auf der v\u00f6lligen Unf\u00e4higkeit, tats\u00e4chliche Rechenschaft abzulegen. Jede ihrer Reden war eine Ansammlung von Worth\u00fclsen, ohne Zahlen, ohne konkrete Daten, ohne Perspektiven, die sich in irgendeiner Form auf die Menschen bezogen. Im besten Fall noch auf die deutsche Wirtschaft \u2013 daf\u00fcr sorgte das Kaffeekr\u00e4nzchen.<\/p>\n<p>Es mag ja sein, dass f\u00fcr jemanden, der in der DDR aufgewachsen ist, die dort \u00fcbliche Art der Rechenschaftslegung in Gestalt von Tabellen und Pl\u00e4nen \u00f6de und absto\u00dfend wirkte. Aber darauf konnte jeder Zuh\u00f6rer den Finger legen, und einfordern, was fehlte. Auf Merkels Wertew\u00f6lkchen konnte man nichts legen.<\/p>\n<p>Das wirklich zutiefst irritierende ist, dass all diese deutschen Journalisten diese S\u00e4tze lesen und danach \u00fcber Putin r\u00e4tseln. Oder meinen, sie h\u00e4tten mit dem Satz, das Ende der Sowjetunion sei &#8220;die schlimmste Sache des 20. Jahrhunderts&#8221; gewesen, irgendetwas \u00fcber Putin erkannt. Mitnichten. Das ist eine Aussage, der man allerh\u00f6chstens die Frage gegen\u00fcberstellen kann, ob die Macht\u00fcbergabe an Hitler nicht schlimmer gewesen sei. Es ist nicht Putin, der sich in diesem Wortwechsel, so wie Merkel ihn darstellt, entbl\u00f6\u00dft hat \u2013 es war Merkel. Putin wird in diesem Moment begriffen haben, dass da niemand ist, mit dem man vern\u00fcnftig, auf eine den zu l\u00f6senden Aufgaben entsprechende Weise reden kann.<\/p>\n<p>Mehr noch. Selbst wenn sie pers\u00f6nlich davon \u00fcberzeugt gewesen w\u00e4re, dass das Ende der Sowjetunion zumindest f\u00fcr Deutschland ein Segen gewesen sei, w\u00e4re es, weil es sich nicht um einen privaten, sondern einen politischen Besuch handelte, angebracht gewesen, ein, zwei Gedanken darauf zu verschwenden, wie sich das auf russischer Seite angef\u00fchlt hat. Oder ein, zwei Statistiken dar\u00fcber zu kennen. Man bereitet sich schlie\u00dflich vor auf solche Termine. Nein, sie antwortet auf eine politische Aussage in einem diplomatischen Gespr\u00e4ch im Tonfall eines Teenagers.<\/p>\n<p>Man sagt ja, jedes Volk habe die Regierung, die es verdiene. Wie man schon an diesen wenigen S\u00e4tzen erkennen kann, war Merkel eine schwere Strafe. Es war kaum vorstellbar, dass es noch schlimmer kommen k\u00f6nnte. Aber Merkels &#8220;Gl\u00fccksumstand&#8221; und Baerbocks &#8220;die Ukraine muss siegen&#8221; wachsen am selben Baum. An einem, wo Menschen, die wegen v\u00f6llig fehlendem Verantwortungsgef\u00fchls niemals irgendeine politische Rolle spielen sollten, sich ihre Spr\u00fcche abholen, mit dem sie das Land in den Untergang f\u00fchren. Merkel hat damals nicht verstanden, was Putin sagte. Baerbock und Scholz haben jetzt daf\u00fcr gesorgt, dass nicht nur sie, sondern das ganze Land es verstehen lernen wird. Aus eigener, unmittelbarer Anschauung.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de.rt.com\/inland\/140484-merkel-minsk-gab-ukraine-zeit\/\">Merkel: &#8220;Minsk&#8221; gab Ukraine Zeit zu werden, was sie heute ist<\/a><\/p>\n<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/140576-wie-merkel-uber-putin-redete\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In fr\u00fcheren Jahrhunderten wurden die Eigenschaften politischer Gestalten oft anhand von Anekdoten \u00fcberliefert. In der Geschichte von Friedrich II. und dem M\u00fcller etwa. Merkel liefert ihre Anekdote selbst. Aber sie erz\u00e4hlt etwas v\u00f6llig anderes, als was vom Mainstream aus ihr herausgelesen wird. von Dagmar Henn Nein, ich habe es mir nicht angesehen, das lange Gespr\u00e4ch [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":10296,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_automatic_camp":["217"],"c7b2ce54389dbeba9ffbeedc9742e1f2":["Verantwortungslose Egozentrik: Wie Merkel \u00fcber Putin redet und sich selbst blo\u00dfstellt"],"original_link":["https:\/\/de.rt.com\/meinung\/140576-wie-merkel-uber-putin-redete\/"],"_thumbnail_id":["10296"],"_wptg_p2tg_sent2tg":["2022-06-09 08:31:48"],"jnews_social_counter_last_update":["1778555758"]},"categories":[19,23],"tags":[23733,23731,55,125,23732,7618,434,139,140,23730,579],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Verantwortungslose Egozentrik: Wie Merkel \u00fcber Putin redet und sich selbst blo\u00dfstellt - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verantwortungslose Egozentrik: Wie Merkel \u00fcber Putin redet und sich selbst blo\u00dfstellt\" \/>\n<meta property=\"og:description\" content=\"In fr\u00fcheren Jahrhunderten wurden die Eigenschaften politischer Gestalten oft anhand von Anekdoten \u00fcberliefert. In der Geschichte von Friedrich II. und dem M\u00fcller etwa. Merkel liefert ihre Anekdote selbst. Aber sie erz\u00e4hlt etwas v\u00f6llig anderes, als was vom Mainstream aus ihr herausgelesen wird. von Dagmar Henn Nein, ich habe es mir nicht angesehen, das lange Gespr\u00e4ch [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-09T06:23:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/Verantwortungslose-Egozentrik-Wie-Merkel-ueber-Putin-redet-und-sich-selbst.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Verantwortungslose Egozentrik: Wie Merkel \u00fcber Putin redet und sich selbst blo\u00dfstellt\",\"datePublished\":\"2022-06-09T06:23:11+00:00\",\"dateModified\":\"2022-06-09T06:23:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/\"},\"wordCount\":1338,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/Verantwortungslose-Egozentrik-Wie-Merkel-ueber-Putin-redet-und-sich-selbst.jpg\",\"keywords\":[\"blo\u00dfstellt\",\"Egozentrik\",\"Merkel\",\"putin\",\"redet\",\"selbst\",\"sich\",\"\u00fcber\",\"und\",\"Verantwortungslose\",\"Wie\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/\",\"name\":\"Verantwortungslose Egozentrik: Wie Merkel \u00fcber Putin redet und sich selbst blo\u00dfstellt - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/Verantwortungslose-Egozentrik-Wie-Merkel-ueber-Putin-redet-und-sich-selbst.jpg\",\"datePublished\":\"2022-06-09T06:23:11+00:00\",\"dateModified\":\"2022-06-09T06:23:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/Verantwortungslose-Egozentrik-Wie-Merkel-ueber-Putin-redet-und-sich-selbst.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/Verantwortungslose-Egozentrik-Wie-Merkel-ueber-Putin-redet-und-sich-selbst.jpg\",\"width\":460,\"height\":259,\"caption\":\"Verantwortungslose Egozentrik: Wie Merkel \u00fcber Putin redet und sich selbst blo\u00dfstellt\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Verantwortungslose Egozentrik: Wie Merkel \u00fcber Putin redet und sich selbst blo\u00dfstellt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Verantwortungslose Egozentrik: Wie Merkel \u00fcber Putin redet und sich selbst blo\u00dfstellt - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/","og_locale":"de_DE","og_type":"article","og_title":"Verantwortungslose Egozentrik: Wie Merkel \u00fcber Putin redet und sich selbst blo\u00dfstellt","og_description":"In fr\u00fcheren Jahrhunderten wurden die Eigenschaften politischer Gestalten oft anhand von Anekdoten \u00fcberliefert. In der Geschichte von Friedrich II. und dem M\u00fcller etwa. Merkel liefert ihre Anekdote selbst. Aber sie erz\u00e4hlt etwas v\u00f6llig anderes, als was vom Mainstream aus ihr herausgelesen wird. von Dagmar Henn Nein, ich habe es mir nicht angesehen, das lange Gespr\u00e4ch [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2022-06-09T06:23:11+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/Verantwortungslose-Egozentrik-Wie-Merkel-ueber-Putin-redet-und-sich-selbst.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Verantwortungslose Egozentrik: Wie Merkel \u00fcber Putin redet und sich selbst blo\u00dfstellt","datePublished":"2022-06-09T06:23:11+00:00","dateModified":"2022-06-09T06:23:11+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/"},"wordCount":1338,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/Verantwortungslose-Egozentrik-Wie-Merkel-ueber-Putin-redet-und-sich-selbst.jpg","keywords":["blo\u00dfstellt","Egozentrik","Merkel","putin","redet","selbst","sich","\u00fcber","und","Verantwortungslose","Wie"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/","url":"https:\/\/now-news.de\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/","name":"Verantwortungslose Egozentrik: Wie Merkel \u00fcber Putin redet und sich selbst blo\u00dfstellt - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/Verantwortungslose-Egozentrik-Wie-Merkel-ueber-Putin-redet-und-sich-selbst.jpg","datePublished":"2022-06-09T06:23:11+00:00","dateModified":"2022-06-09T06:23:11+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/Verantwortungslose-Egozentrik-Wie-Merkel-ueber-Putin-redet-und-sich-selbst.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/06\/Verantwortungslose-Egozentrik-Wie-Merkel-ueber-Putin-redet-und-sich-selbst.jpg","width":460,"height":259,"caption":"Verantwortungslose Egozentrik: Wie Merkel \u00fcber Putin redet und sich selbst blo\u00dfstellt"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/verantwortungslose-egozentrik-wie-merkel-ueber-putin-redet-und-sich-selbst-blossstellt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Verantwortungslose Egozentrik: Wie Merkel \u00fcber Putin redet und sich selbst blo\u00dfstellt"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/10295"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=10295"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/10295\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/10296"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=10295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=10295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=10295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}