{"id":102832,"date":"2026-05-07T07:00:00","date_gmt":"2026-05-07T05:00:00","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/"},"modified":"2026-05-07T07:00:00","modified_gmt":"2026-05-07T05:00:00","slug":"dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/","title":{"rendered":"Dodik: Zukunft der Welt h\u00e4ngt von Russlands Souver\u00e4nit\u00e4t ab"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/05\/69fb038db480cc54d07ee3a8.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Milorad Dodik sieht Russland als Schl\u00fcssel zur k\u00fcnftigen Weltordnung. Moskaus Kurs entscheide \u00fcber Stabilit\u00e4t und Souver\u00e4nit\u00e4t weltweit. Zugleich wirft er dem Westen L\u00fcgen vor \u2013 und bezeichnet die Ukraine als Instrument europ\u00e4ischer Machtpolitik.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Der ehemalige Pr\u00e4sident der Republika Srpska in Bosnien und Herzegowina und der\u00a0Vorsitzende der Partei &#8220;Allianz der unabh\u00e4ngigen Sozialdemokraten&#8221;, Milorad Dodik, hat dem Westen schwere Vorw\u00fcrfe gemacht. In einem Interview mit <em>RIA Nowosti<\/em> zeichnete er ein umfassendes Bild der aktuellen geopolitischen Lage.<\/p>\n<p><strong>Globale Kr\u00e4fte ordnen sich neu<\/strong><\/p>\n<p>Dodik sieht eine Verschiebung der internationalen Machtverh\u00e4ltnisse. Neben den Vereinigten Staaten und China sei Russland zu einem der zentralen Akteure geworden.<\/p>\n<p><em>&#8220;Heute sind die globalen Kr\u00e4fte vor allem mit Russland, China und den Vereinigten Staaten verbunden, sowie mit anderen M\u00e4chten, die zu ihnen aufschlie\u00dfen.&#8221;<\/em><\/p>\n<p>Zugleich versammeln sich &#8220;deutlich mehr L\u00e4nder&#8221; um Russland und die BRICS als um den Westen. Er leitet daraus ab, dass die Zukunft der Welt davon abh\u00e4ngt, wie erfolgreich Russland seinen Kurs der Stabilisierung und St\u00e4rkung der Souver\u00e4nit\u00e4t fortsetzt. Dies werde f\u00fcr viele Staaten \u2013 insbesondere kleinere \u2013 zum Orientierungsrahmen.<\/p>\n<p><strong>Russland als &#8220;Leuchtturm&#8221;<\/strong><\/p>\n<p>Russland sei heute &#8220;ein Leuchtturm einer gerechten Weltordnung&#8221;. Es vertrete Werte, die auf Zusammenarbeit und gegenseitigem Respekt beruhten.\u00a0&#8220;Russland respektiert die Interessen anderer&#8221;, erkl\u00e4rte Dodik. Der Westen hingegen verfolge eigene Ziele und setze diese notfalls mit Gewalt durch.\u00a0&#8220;Er versucht zun\u00e4chst, mit dem Zuckerbrot zu locken. Wenn das nicht gelingt, greift er zu harter Gewalt&#8221;,\u00a0so Dodik. Als Beispiel nannte\u00a0er die Bombardierung Serbiens durch die NATO:<\/p>\n<p><em>&#8220;Sie haben Bomben auf uns abgeworfen und ihre Operation &#8216;Barmherziger Engel&#8217; genannt. Stellen Sie sich diesen Zynismus vor.&#8221;<br \/><\/em><\/p>\n<p>Gleichzeitig betonte Dodik, Russland sei ein unverzichtbarer Akteur der internationalen Beziehungen und ein integraler Bestandteil der heutigen Weltordnung. Noch vor wenigen Jahren sei\u00a0Russland als regionale Macht eingeordnet worden \u2013 ein Irrtum, wie sich heute zeige. Russland sei ein Staat, der nicht nur \u00fcberlebe, sondern Prozesse gestalte und kontrolliere, w\u00e4hrend der Westen an Einfluss verliere. Auch dessen Versuche, durch Umschreibung der Geschichte an Bedeutung zu gewinnen, seien gescheitert.<\/p>\n<p><strong>Ukraine als &#8220;Instrument&#8221; des Westens<\/strong><\/p>\n<p>Im Kontext der milit\u00e4rischen Sonderoperation erkl\u00e4rte Dodik, Russland habe diese vorsichtig gef\u00fchrt und versucht, zivile Opfer zu minimieren. Zugleich warnte er vor einer falschen Einordnung des Konflikts: Dieser sei nicht lediglich eine Auseinandersetzung zwischen Russland und der Ukraine, sondern ein Konflikt mit dem Westen, insbesondere mit der Europ\u00e4ischen Union.\u00a0Die Ukraine werde dabei vom Westen als Instrument genutzt. &#8220;Der Westen versuchte, \u00fcber die Ukraine Krieg gegen Russland zu f\u00fchren, und tut dies bis heute&#8221;, sagte Dodik. Die Ukraine sei zugleich &#8220;das einzige m\u00f6gliche Element des Selbsterhalts Westeuropas&#8221;. Bereits vor Beginn der Operation seien die Entwicklungen in Europa ung\u00fcnstig gewesen. Im Falle eines Friedens werde Europa vollst\u00e4ndig destabilisiert sein.<\/p>\n<p><em>&#8220;Europa wird ohne F\u00fchrung, ohne Rohstoffe und ohne Werte dastehen. Ein Europa ohne Zukunftskonzept stimmt zweifellos nicht optimistisch.&#8221;<\/em><\/p>\n<p><strong>Minsker Abkommen und internationale Ordnung<br \/><\/strong><\/p>\n<p>Scharf \u00e4u\u00dferte sich Dodik auch zu den Minsker Abkommen. Diese seien bewusst nicht umgesetzt worden. Sowohl der ehemalige franz\u00f6sische Pr\u00e4sident Fran\u00e7ois Hollande als auch die ehemalige Bundeskanzlerin Angela Merkel h\u00e4tten einger\u00e4umt, dass die Abkommen lediglich als Zeitgewinn zur Aufr\u00fcstung der Ukraine gedient h\u00e4tten. Das zeige, dass sie stets versuchen, sich auf Kosten anderer zu behaupten.\u00a0Er\u00a0verwies auch auf das Dayton-Abkommen. Dieses habe eine Struktur geschaffen, &#8220;in der Ausl\u00e4nder \u00fcber Bosnien und Herzegowina entscheiden&#8221;.\u00a0&#8220;Heute haben wir eine internationale Verwaltung kolonialen Charakters&#8221;, sagte er. Die Darstellung des Westens, es handle sich um Demokratie, bezeichnete er als &#8220;gro\u00dfe L\u00fcge&#8221;.<\/p>\n<p><strong>Russland und der Ursprung des Konflikts<\/strong><\/p>\n<p>Russland habe im Rahmen der Sonderoperation &#8220;sein wahres Gesicht gezeigt&#8221; \u2013 als ein Staat, der sein Volk sch\u00fctzt, so Dodik. Er verwies auf die russischsprachige Bev\u00f6lkerung in der Ukraine und argumentierte, Russland habe daher ein Recht auf deren Schutz. Es sei bekannt, dass auf dem Gebiet der Ukraine eine erhebliche Zahl russischsprachiger Menschen lebt. Daraus leitete er ab, dass Russland das volle Recht gehabt habe, sein Volk und seine Werte in diesen Gebieten zu verteidigen. Zudem habe die Ukraine nach dem Zerfall der Sowjetunion mehr erhalten, als ihr zustand, und sich anschlie\u00dfend zunehmend westlichen Interessen zugewandt. Parallel dazu habe der Westen versucht, Russland milit\u00e4risch zu umkreisen \u2013 insbesondere \u00fcber die NATO \u2013, mit dem Ziel, es geopolitisch zu schw\u00e4chen und langfristig aufzuteilen.<\/p>\n<p><strong>Aufruf zur Neuordnung<\/strong><\/p>\n<p>Laut Dodik w\u00fcrde ohne Russlands Pr\u00e4sident Wladimir Putin heute eine vom Westen dominierte Weltordnung bestehen, die von einseitigen Interessen gepr\u00e4gt w\u00e4re. In diesem System bliebe kein Platz mehr f\u00fcr andere als die &#8220;uners\u00e4ttlichen Interessen&#8221; westlicher Staaten und ihrer F\u00fchrung. Er rief daher Russland, die BRICS-Staaten und die &#8220;freie Welt&#8221; zu enger Zusammenarbeit auf. Die internationale Ordnung m\u00fcsse auf Kooperation und gegenseitigem Respekt beruhen. &#8220;Wenn Russland seinen Weg erfolgreich fortsetzt, wird das die Zukunft der Welt bestimmen&#8221;, sagte er abschlie\u00dfend.<\/p>\n<p><strong>Mehr zum Thema <\/strong>\u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de-rtnews.com\/meinung\/279171-karaganow-wie-russland-im-neuen\/\">Karaganow: Wie Russland im neuen Weltkrieg gewinnen kann<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v76xdcq\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/europa\/279244-dodik-zukunft-welt-haengt-von-russland-ab\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Milorad Dodik sieht Russland als Schl\u00fcssel zur k\u00fcnftigen Weltordnung. Moskaus Kurs entscheide \u00fcber Stabilit\u00e4t und Souver\u00e4nit\u00e4t weltweit. Zugleich wirft er dem Westen L\u00fcgen vor \u2013 und bezeichnet die Ukraine als Instrument europ\u00e4ischer Machtpolitik. Der ehemalige Pr\u00e4sident der Republika Srpska in Bosnien und Herzegowina und der\u00a0Vorsitzende der Partei &#8220;Allianz der unabh\u00e4ngigen Sozialdemokraten&#8221;, Milorad Dodik, hat dem [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":102833,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1778130659"],"wp_automatic_camp":["217"],"a85c27bf3f32a7686a61241bb8f7ddb3":["Dodik: Zukunft der Welt h\u00e4ngt von Russlands Souver\u00e4nit\u00e4t ab"],"original_link":["https:\/\/de.rt.com\/europa\/279244-dodik-zukunft-welt-haengt-von-russland-ab\/"],"_thumbnail_id":["102833"],"jnews_social_counter_last_update":["1778611767"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2026-05-07 07:11:53\";}"]},"categories":[19,23],"tags":[82,55595,27972,142,20302,50,778,3250],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dodik: Zukunft der Welt h\u00e4ngt von Russlands Souver\u00e4nit\u00e4t ab - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dodik: Zukunft der Welt h\u00e4ngt von Russlands Souver\u00e4nit\u00e4t ab\" \/>\n<meta property=\"og:description\" content=\"Milorad Dodik sieht Russland als Schl\u00fcssel zur k\u00fcnftigen Weltordnung. Moskaus Kurs entscheide \u00fcber Stabilit\u00e4t und Souver\u00e4nit\u00e4t weltweit. Zugleich wirft er dem Westen L\u00fcgen vor \u2013 und bezeichnet die Ukraine als Instrument europ\u00e4ischer Machtpolitik. Der ehemalige Pr\u00e4sident der Republika Srpska in Bosnien und Herzegowina und der\u00a0Vorsitzende der Partei &#8220;Allianz der unabh\u00e4ngigen Sozialdemokraten&#8221;, Milorad Dodik, hat dem [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-07T05:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/05\/69fb038db480cc54d07ee3a8.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Dodik: Zukunft der Welt h\u00e4ngt von Russlands Souver\u00e4nit\u00e4t ab\",\"datePublished\":\"2026-05-07T05:00:00+00:00\",\"dateModified\":\"2026-05-07T05:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/\"},\"wordCount\":850,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Dodik-Zukunft-der-Welt-haengt-von-Russlands-Souveraenitaet-ab.jpg\",\"keywords\":[\"der\",\"Dodik\",\"h\u00e4ngt\",\"Russlands\",\"Souver\u00e4nit\u00e4t\",\"von\",\"Welt\",\"Zukunft\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/\",\"name\":\"Dodik: Zukunft der Welt h\u00e4ngt von Russlands Souver\u00e4nit\u00e4t ab - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Dodik-Zukunft-der-Welt-haengt-von-Russlands-Souveraenitaet-ab.jpg\",\"datePublished\":\"2026-05-07T05:00:00+00:00\",\"dateModified\":\"2026-05-07T05:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Dodik-Zukunft-der-Welt-haengt-von-Russlands-Souveraenitaet-ab.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Dodik-Zukunft-der-Welt-haengt-von-Russlands-Souveraenitaet-ab.jpg\",\"caption\":\"Dodik: Zukunft der Welt h\u00e4ngt von Russlands Souver\u00e4nit\u00e4t ab\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dodik: Zukunft der Welt h\u00e4ngt von Russlands Souver\u00e4nit\u00e4t ab\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dodik: Zukunft der Welt h\u00e4ngt von Russlands Souver\u00e4nit\u00e4t ab - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/","og_locale":"de_DE","og_type":"article","og_title":"Dodik: Zukunft der Welt h\u00e4ngt von Russlands Souver\u00e4nit\u00e4t ab","og_description":"Milorad Dodik sieht Russland als Schl\u00fcssel zur k\u00fcnftigen Weltordnung. Moskaus Kurs entscheide \u00fcber Stabilit\u00e4t und Souver\u00e4nit\u00e4t weltweit. Zugleich wirft er dem Westen L\u00fcgen vor \u2013 und bezeichnet die Ukraine als Instrument europ\u00e4ischer Machtpolitik. Der ehemalige Pr\u00e4sident der Republika Srpska in Bosnien und Herzegowina und der\u00a0Vorsitzende der Partei &#8220;Allianz der unabh\u00e4ngigen Sozialdemokraten&#8221;, Milorad Dodik, hat dem [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2026-05-07T05:00:00+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/05\/69fb038db480cc54d07ee3a8.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Dodik: Zukunft der Welt h\u00e4ngt von Russlands Souver\u00e4nit\u00e4t ab","datePublished":"2026-05-07T05:00:00+00:00","dateModified":"2026-05-07T05:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/"},"wordCount":850,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Dodik-Zukunft-der-Welt-haengt-von-Russlands-Souveraenitaet-ab.jpg","keywords":["der","Dodik","h\u00e4ngt","Russlands","Souver\u00e4nit\u00e4t","von","Welt","Zukunft"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/","url":"https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/","name":"Dodik: Zukunft der Welt h\u00e4ngt von Russlands Souver\u00e4nit\u00e4t ab - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Dodik-Zukunft-der-Welt-haengt-von-Russlands-Souveraenitaet-ab.jpg","datePublished":"2026-05-07T05:00:00+00:00","dateModified":"2026-05-07T05:00:00+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Dodik-Zukunft-der-Welt-haengt-von-Russlands-Souveraenitaet-ab.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Dodik-Zukunft-der-Welt-haengt-von-Russlands-Souveraenitaet-ab.jpg","caption":"Dodik: Zukunft der Welt h\u00e4ngt von Russlands Souver\u00e4nit\u00e4t ab"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/dodik-zukunft-der-welt-haengt-von-russlands-souveraenitaet-ab\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Dodik: Zukunft der Welt h\u00e4ngt von Russlands Souver\u00e4nit\u00e4t ab"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/102832"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=102832"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/102832\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/102833"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=102832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=102832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=102832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}