{"id":102714,"date":"2026-05-04T21:50:00","date_gmt":"2026-05-04T19:50:00","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/"},"modified":"2026-05-04T21:50:00","modified_gmt":"2026-05-04T19:50:00","slug":"usa-verlassen-deutschland-aber-nicht-europa","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/","title":{"rendered":"USA verlassen Deutschland \u2013 aber nicht Europa"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/05\/69f8b8f0b480cc7bd6740960.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Der Abzug von US-Truppen aus Deutschland ist keine launische Entscheidung des Pr\u00e4sidenten Donald Trump, sondern Teil einer langfristigeren Strategie, in deren Rahmen Washington seine milit\u00e4rische Logistik nach Osteuropa und seine Kampftruppen in den Nahen Osten oder in die Indopazifik-Region verlagert.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Ilja Kramnik<\/em><\/p>\n<p>Die von Trump angek\u00fcndigte K\u00fcrzung des US-amerikanischen Kontingents in Deutschland hat viel tiefere Gr\u00fcnde, als der gegenw\u00e4rtige &#8220;Unmut&#8221; des US-Pr\u00e4sidenten \u00fcber die NATO. De facto ist das eine Fortsetzung der langfristigen US-amerikanischen Zweiparteien-Politik, die auf eine Reduzierung der milit\u00e4rischen Pr\u00e4senz der USA in Europa zugunsten der Verlagerung in die Indopazifik-Region.<\/p>\n<p>Deutschland ist historisch das Hauptgebiet f\u00fcr die Stationierung der US-Truppen in Europa: Dort dienen etwa 38.000 der insgesamt 80.000 Soldaten, die in Europa stationiert sind. Auf Platz zwei liegen Italien und Gro\u00dfbritannien mit jeweils 13.000 und 10.000 US-Milit\u00e4rs. Spanien (4.000) und die T\u00fcrkei (2.000) schlie\u00dfen die Top-5 ab.<\/p>\n<p>Betrachtet man die Zusammensetzung der in Europa, darunter in Deutschland, stationierten Verb\u00e4nde,\u00a0wird deutlich, dass es dort gar nicht so viele Kampfeinheiten gibt. Den Gro\u00dfteil der in Europa stationierten US-Verb\u00e4nde stellen diverse Versorgungs- und Spezialtruppen dar: Aufkl\u00e4rungseinheiten, Ingenieurstruppen, Truppen f\u00fcr Transport, Wartung, Ausbildung und so weiter. Im Grunde ist das eine Infrastruktur, die bei Bedarf eine schnelle Verst\u00e4rkung des Truppenverbands erm\u00f6glicht, etwa durch die Verlegung des 3. Panzerkorps der USA.<\/p>\n<p>Doch in der zweiten H\u00e4lfte der 2010er Jahre zwang die Eskalation zwischen Russland und der NATO die USA nicht nur, die Reduzierung ihrer Verb\u00e4nde in Europa zu stoppen, sondern sie sogar aufzustocken \u2013 vor allem durch Stationierung von Truppen bei multinationalen Verb\u00e4nden in Osteuropa. Und wenn man vermuten sollte, wohin die aus Deutschland verlegten Truppen gehen k\u00f6nnten, d\u00fcrfte Polen durchaus zu den Ziell\u00e4ndern geh\u00f6ren. Welche Verb\u00e4nde konkret verlegt werden, ist eine andere Frage. Mit gro\u00dfer Wahrscheinlichkeit werden ebenfalls zus\u00e4tzliche Versorgungseinheiten nach Polen verlegt, um dort bei Bedarf Kampftruppen aufzustellen. Die eigentlichen Kampftruppen werden aber wahrscheinlich nach Asien verlegt werden \u2013 ob in den Nahen oder in den Fernen Osten h\u00e4ngt davon ab, ob Trump die Kampfhandlungen gegen Iran wiederaufnehmen will oder nicht.<\/p>\n<p><em>\u00dcbersetzt aus dem Russischen. Verfasst speziell f\u00fcr RT am 3. Mai 2026.<\/em><\/p>\n<p><em>Ilja Kramnik ist Milit\u00e4ranalyst, Experte beim Russischen Rat f\u00fcr Internationale Angelegenheiten und Forscher an der Russischen Akademie der Wissenschaften.<\/em><\/p>\n<p><strong>Mehr zum Thema <\/strong>\u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de-rtnews.com\/international\/278821-trumps-drohungen-kurz-vor-verwirklichung\/\">Trumps Drohungen kurz vor Verwirklichung: Abzug von 5.000 Soldaten aus Deutschland steht an<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v774gg4\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/279059-usa-verlassen-deutschland-aber-nicht\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Abzug von US-Truppen aus Deutschland ist keine launische Entscheidung des Pr\u00e4sidenten Donald Trump, sondern Teil einer langfristigeren Strategie, in deren Rahmen Washington seine milit\u00e4rische Logistik nach Osteuropa und seine Kampftruppen in den Nahen Osten oder in die Indopazifik-Region verlagert. Von Ilja Kramnik Die von Trump angek\u00fcndigte K\u00fcrzung des US-amerikanischen Kontingents in Deutschland hat viel [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":102715,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1777924532"],"wp_automatic_camp":["217"],"5696e8ab097ca0270bd4406f759eeb0e":["USA verlassen Deutschland \u2013 aber nicht Europa"],"original_link":["https:\/\/de.rt.com\/meinung\/279059-usa-verlassen-deutschland-aber-nicht\/"],"_thumbnail_id":["102715"],"jnews_social_counter_last_update":["1783928526"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2026-05-04 21:56:34\";}"]},"categories":[19,23],"tags":[2205,179,1370,800,193,4369],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>USA verlassen Deutschland \u2013 aber nicht Europa - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"USA verlassen Deutschland \u2013 aber nicht Europa\" \/>\n<meta property=\"og:description\" content=\"Der Abzug von US-Truppen aus Deutschland ist keine launische Entscheidung des Pr\u00e4sidenten Donald Trump, sondern Teil einer langfristigeren Strategie, in deren Rahmen Washington seine milit\u00e4rische Logistik nach Osteuropa und seine Kampftruppen in den Nahen Osten oder in die Indopazifik-Region verlagert. Von Ilja Kramnik Die von Trump angek\u00fcndigte K\u00fcrzung des US-amerikanischen Kontingents in Deutschland hat viel [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-04T19:50:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/05\/69f8b8f0b480cc7bd6740960.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"USA verlassen Deutschland \u2013 aber nicht Europa\",\"datePublished\":\"2026-05-04T19:50:00+00:00\",\"dateModified\":\"2026-05-04T19:50:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/\"},\"wordCount\":412,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/USA-verlassen-Deutschland-\u2013-aber-nicht-Europa.jpg\",\"keywords\":[\"aber\",\"Deutschland\",\"Europa\",\"nicht\",\"USA\",\"verlassen\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/\",\"name\":\"USA verlassen Deutschland \u2013 aber nicht Europa - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/USA-verlassen-Deutschland-\u2013-aber-nicht-Europa.jpg\",\"datePublished\":\"2026-05-04T19:50:00+00:00\",\"dateModified\":\"2026-05-04T19:50:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/USA-verlassen-Deutschland-\u2013-aber-nicht-Europa.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/USA-verlassen-Deutschland-\u2013-aber-nicht-Europa.jpg\",\"caption\":\"USA verlassen Deutschland \u2013 aber nicht Europa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"USA verlassen Deutschland \u2013 aber nicht Europa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"USA verlassen Deutschland \u2013 aber nicht Europa - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/","og_locale":"de_DE","og_type":"article","og_title":"USA verlassen Deutschland \u2013 aber nicht Europa","og_description":"Der Abzug von US-Truppen aus Deutschland ist keine launische Entscheidung des Pr\u00e4sidenten Donald Trump, sondern Teil einer langfristigeren Strategie, in deren Rahmen Washington seine milit\u00e4rische Logistik nach Osteuropa und seine Kampftruppen in den Nahen Osten oder in die Indopazifik-Region verlagert. Von Ilja Kramnik Die von Trump angek\u00fcndigte K\u00fcrzung des US-amerikanischen Kontingents in Deutschland hat viel [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2026-05-04T19:50:00+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/05\/69f8b8f0b480cc7bd6740960.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"USA verlassen Deutschland \u2013 aber nicht Europa","datePublished":"2026-05-04T19:50:00+00:00","dateModified":"2026-05-04T19:50:00+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/"},"wordCount":412,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/USA-verlassen-Deutschland-\u2013-aber-nicht-Europa.jpg","keywords":["aber","Deutschland","Europa","nicht","USA","verlassen"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/","url":"https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/","name":"USA verlassen Deutschland \u2013 aber nicht Europa - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/USA-verlassen-Deutschland-\u2013-aber-nicht-Europa.jpg","datePublished":"2026-05-04T19:50:00+00:00","dateModified":"2026-05-04T19:50:00+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/USA-verlassen-Deutschland-\u2013-aber-nicht-Europa.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/USA-verlassen-Deutschland-\u2013-aber-nicht-Europa.jpg","caption":"USA verlassen Deutschland \u2013 aber nicht Europa"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/usa-verlassen-deutschland-aber-nicht-europa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"USA verlassen Deutschland \u2013 aber nicht Europa"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/102714"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=102714"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/102714\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/102715"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=102714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=102714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=102714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}