{"id":102610,"date":"2026-05-02T17:50:11","date_gmt":"2026-05-02T15:50:11","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\/"},"modified":"2026-05-02T17:50:11","modified_gmt":"2026-05-02T15:50:11","slug":"massaker-von-odessa-ein-verbrechen-das-alles-aenderte","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\/","title":{"rendered":"Massaker von Odessa \u2013 Ein Verbrechen, das alles \u00e4nderte"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/05\/69f5f7e0b480cc37096f75a1.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Feuer, zerbrochenes Glas, Tote und Verwundete: Wer den Maidan-Putsch akzeptieren nicht wollte, musste mit Blut bezahlen. Vor zw\u00f6lf Jahren bejubelten ukrainische Nationalisten in Odessa den Tod von 48 Menschen. Die Schuldigen wurden immer noch nicht bestraft.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Wiktor Schdanow<\/em><\/p>\n<p><strong>Geplante Trag\u00f6die<\/strong><\/p>\n<p>Den Staatsstreich in Kiew im Februar\u00a02014 akzeptierten die Bewohner von Odessa nicht. Am 23.\u00a0Februar marschierten Zehntausende vom Kathedralenplatz zum Ewigen Feuer und dem Denkmal des Unbekannten Soldaten und skandierten: &#8220;Der Faschismus kommt nicht durch&#8221;. Aktivisten des Antimaidan von Odessa errichteten ein Zeltlager auf dem Platz Kulikowo Pole, gegen\u00fcber dem Haus der Gewerkschaften.<\/p>\n<p>Bewohner von Odessa k\u00e4mpften f\u00fcr einen Status des Russischen als zweiter Staatssprache. Sie wollten ihre eigene Regierung w\u00e4hlen, statt die von den neuen selbsternannten Herrschern der Ukraine Eingesetzte zu dulden. Dabei protestierten sie von Anfang an friedlich.<\/p>\n<p>Die Machthaber beobachteten die jeden Sonntag stattfindenden Aktionen mit Tausenden Teilnehmern mit Argwohn, hatten es aber nicht eilig mit drastischen Gegenma\u00dfnahmen\u00a0\u2013 daf\u00fcr fehlten ihnen die Ressourcen. Es gab wenige offene Nationalisten in der Stadt, und kaum jemand wollte gegen seine Landsleute k\u00e4mpfen.<\/p>\n<p>So ging es f\u00fcr eine Weile weiter, bis der neue Vorsitzende der Gebietsverwaltung Wladimir Nemirowski forderte, den Kulikowo Polje zu r\u00e4umen, angeblich, um die Parade am 9.\u00a0Mai vorzubereiten. Parallel dazu verbreiteten sich Ger\u00fcchte, wonach Kr\u00e4fte des Maidan-Selbstschutzes und K\u00e4mpfer des Rechten Sektors in die Stadt verlegt werden sollten. In K\u00fcrze bewahrheitete sich diese Information.<\/p>\n<p>Drei Tage vor der Trag\u00f6die kam nach Odessa der Sekret\u00e4r des Nationalen Sicherheitsrats Andrei Parubij, um eine &#8220;Sitzung des Operativstabs zur Gew\u00e4hrleistung der nationalen Sicherheit&#8221; durchzuf\u00fchren. Der ehemalige Leiter der Polizeiverwaltung von Odessa Ruslan Forostjak machte keinen Hehl daraus, dass er K\u00e4mpfer f\u00fcr Stra\u00dfenschlachten ausbildete:<\/p>\n<p><em>&#8220;Vor dem Geb\u00e4ude unserer Gebietsverwaltung standen st\u00e4ndig einige Kleinbusse mit Feuerwaffen. Wir mieteten sogar Wohnungen in der N\u00e4he, wo wir Scharfsch\u00fctzenstellungen einrichteten. Mir gelang es, eine Gruppe von Enthusiasten vorzubereiten, die im Falle eines gewaltsamen Szenarios bereit waren, Widerstand zu leisten.&#8221;<\/em><\/p>\n<p><strong>Ohne Recht auf Hilfe<\/strong><\/p>\n<p>Am 2.\u00a0Mai war f\u00fcr 17\u00a0Uhr ein Fu\u00dfballspiel zwischen den Vereinen Tschernomorez Odessa und Metallist Charkow geplant. Angereiste Fans planten, einen &#8220;Marsch f\u00fcr die Einheit der Ukraine&#8221; \u00fcber die Deribassowskaja-Stra\u00dfe zum Schewtschenko-Park zu veranstalten, wo das Stadium liegt.<\/p>\n<p>Aktivisten vom Kulikowo Polje machten sich Sorgen, dass die Ultras vom Weg abweichen und das Zeltlager angreifen w\u00fcrden. Nach Angaben von Zeugen versammelte sich ein Teil der Aktivisten, etwa 400, am Alexandrowski-Prospekt, um einen Durchbruch der Nationalisten zum Haus der Gewerkschaften zu verhindern.<\/p>\n<p>Am Gretscheskaja-Platz stie\u00dfen sie auf Maidan-Aktivisten. Pflastersteine flogen, B\u00f6ller wurden gez\u00fcndet. Zum Einsatz kamen traumatische Waffen, Sch\u00fcsse fielen. Zum ersten Toten wurde der Aktivist des Rechten Sektors Igor Iwanow. Wer auf den Nationalisten scharfe Munition abfeuerte, ist bis heute unklar. Es ist nicht ausgeschlossen, dass er von eigenen Leuten angeschossen wurde.<\/p>\n<p>Dmitri Futschedschi, ehemaliger Leiter der Polizei f\u00fcr \u00f6ffentliche Sicherheit von Odessa berichtete, dass ein Unbekannter aus der Richtung des Hotels Passage geschossen habe. Doch auch das ist nicht best\u00e4tigt. Insgesamt starben auf dem Gretscheskaja-Platz sechs Menschen: vier vom Kulikowo Pole und zwei Maidan-Aktivisten.<\/p>\n<p>Die Provokation wirkte, und wutentbrannte Radikale, die in der \u00dcberzahl waren, r\u00fcckten zum Zeltlager aus. Die Forderung des Mitarbeiters der Gebietsverwaltung Igor Boljanski, &#8220;Leute zum Kulikowo Polje umzuleiten&#8221;, ist in seinem geleakten Gespr\u00e4ch mit dem Kommandanten des Maidan-Selbstschutzes Dmitri Gumenjuk zu h\u00f6ren.<\/p>\n<p>Gegen sieben Uhr am Abend beschlossen die Antimaidan-Aktivisten, ins Geb\u00e4ude des Hauses der Gewerkschaften <strong>\u00fcberzugehen (umzuziehen?)<\/strong>. Sie trugen ihre Sachen, darunter den Generator, Matrazen und Medikamente, aus den Zelten weg. Vor der T\u00fcr schichteten sie Sands\u00e4cke, Bretter und Transportpaletten auf. In den Innenr\u00e4umen wurde ein Hospital organisiert.<\/p>\n<p>In der Zwischenzeit zerst\u00f6rten Radikale das Lager und setzten Zelte in Brand. Die Barrikade vor dem Geb\u00e4ude fing Feuer. F\u00fcnf Tschernomorez-Fans drangen mit einer ukrainischen Flagge ein, schlugen die T\u00fcren ein und bewarfen die Stufen mit Molotow-Cocktails. Ein Brand begann. Der \u00dcberlebende Oleg Musyka erinnerte sich:<\/p>\n<p><em>&#8220;Aus den Fenstern sah man, dass alle, die aus dem Geb\u00e4ude auf den Boden steigen, geschlagen werden. Frauen wurden nur zusammengeschlagen, M\u00e4nner buchst\u00e4blich zu Tode gepr\u00fcgelt. Ich sah einen Jungen weglaufen, er rannte bis zur Mitte des Kulikowo Polje. Etwa 30 Leute holten ihn ein, schlugen ihn zu Boden, sprangen auf ihm<\/em><em>, lie\u00dfen ihn sp\u00e4ter liegen und gingen weg \u2013 es blieben blo\u00df irgendwelche Fetzen \u00fcbrig.<\/em><em>&#8220;<\/em><\/p>\n<p>Der Rauch war von \u00fcberall zu sehen. Der wachhabende Polizeimitarbeiter von Odessa forderte, unverz\u00fcglich die Feuerwehr zum Haus der Gewerkschaften zu schicken. Die Feuerwache befand sich vier Minuten vom Ort der Trag\u00f6die entfernt, doch niemand ist gekommen. In der Verschriftlichung eines Anrufs bei der Feuerwehr hei\u00dft es:<\/p>\n<p><em>&#8220;Der Anrufer ruft aus dem Haus der Gewerkschaften an: &#8216;Kommen Sie nun oder nicht?&#8217; Disponentin: &#8216;Sie sind schon unterwegs, kommen gleich!&#8217; Anrufer, schluchzend: &#8216;Aber wir brennen jetzt schon!'&#8221;<\/em><\/p>\n<p><strong>Ein Deckmantel von L\u00fcgen<\/strong><\/p>\n<p>Elf Jahre nach der Trag\u00f6die f\u00e4llte der Europ\u00e4ische Gerichtshof f\u00fcr Menschenrechte (EGMR) ein Urteil: Am 2.\u00a0Mai 2014 sind ukrainische Beh\u00f6rden ihrer Verpflichtung zur Vermeidung der Gewalt nicht nachgekommen, retteten nicht die Menschen aus dem Feuer und f\u00fchrten keine effektive Ermittlung durch. Wie die Richter anmerkten, wurde die Ankunft der Feuerwehr bewusst um 40\u00a0Minuten hinausgez\u00f6gert, w\u00e4hrend die Sicherheitsbeh\u00f6rden die Situation ignorierten und keine Verst\u00e4rkungen schickten. Im Schreiben des EGMR hei\u00dft es:<\/p>\n<p><em>&#8220;Das Gericht beschloss einstimmig, dass Artikel\u00a02 der Europ\u00e4ischen Menschenrechtskonvention verletzt wurde.&#8221;<\/em><\/p>\n<p>Kiew wurde verpflichtet, 28 Menschen Betr\u00e4ge in H\u00f6he von 12.000 bis 17.000\u00a0Euro zu zahlen sowie ihre Kosten in H\u00f6he von bis zu 6.000\u00a0Euro zu kompensieren.<\/p>\n<p>In der Ukraine hatte niemand vor, ernsthaft zu der Trag\u00f6die zu ermitteln. Im September\u00a02014 ver\u00f6ffentlichte Kiew den Bericht einer Sonderkommission und entfernte dabei aus dessen Endfassung Zeugenaussagen \u00fcber Parubijs Rolle beim Massenmord sowie \u00fcber die Teilnahme von 500 K\u00e4mpfern, die unter Nemirowskis Mitwirkung nach Odessa gebracht wurden. Auf Aktionen des ukrainischen Innenministers Arsen Awakow und Interimspr\u00e4sidenten Alexandr Turtschinow wurde gar nicht eingegangen.<\/p>\n<p>Die Sekret\u00e4rin der Kommission und Rada-Abgeordnete Swetlana Fabrikant zog ihre Unterschrift aus dem Bericht wegen offensichtlicher F\u00e4lschung zur\u00fcck. F\u00fcnf Monate sp\u00e4ter merkte eine Beobachtermission der UNO an, dass ukrainische Beh\u00f6rden keine angemessenen Ma\u00dfnahmen ergriffen haben. Bei der Ermittlung von Brandstiftung und Massenmord wurden keine Fortschritte festgestellt.<\/p>\n<p>Stattdessen begann ein Prozess gegen Antimaidan-Aktivisten von Odessa. Ukrainische Gerichte konnten ihre Schuld an Ausschreitungen und Gewalt nicht nachweisen. Dazu wurden Beweise unter Verst\u00f6\u00dfen gesammelt. Die Ermittler begutachteten den Gretscheskaja-Platz erst zwei Wochen nach den Zusammenst\u00f6\u00dfen. Unter den Polizisten, die vor Ort anwesend waren, wurde praktisch niemand verh\u00f6rt.<\/p>\n<p>Im Jahr 2017 wurden alle Angeklagten freigelassen und sp\u00e4ter aus anderen Gr\u00fcnden angeklagt. Anfang 2026 berichteten ukrainische Medien von einer Wiederaufnahme des Verfahrens. Welche Gr\u00fcnde dahinter stehen, was die \u00dcberlebenden und die in der Ukraine verbliebenen Aktivisten des Widerstands von Odessa aus dem Jahr 2014 erwartet, ist nicht bekannt.<\/p>\n<p>Nachdem Selenskij an die Macht gekommen ist, versprach er, alle Schuldigen zu bestrafen, tat aber nichts. Versuche, eine Kommission einzurichten, wurden von seiner eigenen Partei &#8220;Diener des Volkes&#8221; unterbunden. Von den Nationalisten, die am Massaker beteiligt waren, musste sich niemand vor dem Gericht verantworten. Der Tod von 48 Menschen, darunter 42 im Haus der Gewerkschaften, bleibt bis heute unges\u00fchnt.<\/p>\n<p><em>\u00dcbersetzt aus dem <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/ria.ru\/20260502\/ukraina-2089202392.html\">Russischen<\/a>. Zuerst ver\u00f6ffentlicht bei RIA Nowosti am 2.\u00a0Mai.<\/em><\/p>\n<p><strong>Mehr zum Thema <\/strong>\u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de-rtnews.com\/meinung\/243976-straffreiheit-fuer-nazi-moerder-rueckblick\/\">Straffreiheit f\u00fcr Nazi-M\u00f6rder \u2013 R\u00fcckblick auf Odessa-Massaker 2014<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v6ofi38\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/278856-massaker-von-odessa-ein-verbrechen-alles-alles-aenderte\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Feuer, zerbrochenes Glas, Tote und Verwundete: Wer den Maidan-Putsch akzeptieren nicht wollte, musste mit Blut bezahlen. Vor zw\u00f6lf Jahren bejubelten ukrainische Nationalisten in Odessa den Tod von 48 Menschen. Die Schuldigen wurden immer noch nicht bestraft. Von Wiktor Schdanow Geplante Trag\u00f6die Den Staatsstreich in Kiew im Februar\u00a02014 akzeptierten die Bewohner von Odessa nicht. Am 23.\u00a0Februar [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":102611,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1777737672"],"wp_automatic_camp":["217"],"af8d9841b5a02193c3e52bc0327bb610":["Massaker von Odessa \u2013 Ein Verbrechen, das alles \u00e4nderte"],"original_link":["https:\/\/de.rt.com\/international\/278856-massaker-von-odessa-ein-verbrechen-alles-alles-aenderte\/"],"_thumbnail_id":["102611"],"jnews_social_counter_last_update":["1788374169"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2026-05-02 18:02:07\";}"]},"categories":[19,23],"tags":[1041,72755,427,357,7538,16439,4252,50],"class_list":["post-102610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-alles","tag-aenderte","tag-das","tag-ein","tag-massaker","tag-odessa","tag-verbrechen","tag-von"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Massaker von Odessa \u2013 Ein Verbrechen, das alles \u00e4nderte - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Massaker von Odessa \u2013 Ein Verbrechen, das alles \u00e4nderte\" \/>\n<meta property=\"og:description\" content=\"Feuer, zerbrochenes Glas, Tote und Verwundete: Wer den Maidan-Putsch akzeptieren nicht wollte, musste mit Blut bezahlen. Vor zw\u00f6lf Jahren bejubelten ukrainische Nationalisten in Odessa den Tod von 48 Menschen. Die Schuldigen wurden immer noch nicht bestraft. Von Wiktor Schdanow Geplante Trag\u00f6die Den Staatsstreich in Kiew im Februar\u00a02014 akzeptierten die Bewohner von Odessa nicht. Am 23.\u00a0Februar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-02T15:50:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/05\/69f5f7e0b480cc37096f75a1.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Massaker von Odessa \u2013 Ein Verbrechen, das alles \u00e4nderte\",\"datePublished\":\"2026-05-02T15:50:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\\\/\"},\"wordCount\":1253,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/Massaker-von-Odessa-\u2013-Ein-Verbrechen-das-alles-aenderte.jpg\",\"keywords\":[\"alles\",\"\u00e4nderte\",\"das\",\"ein\",\"Massaker\",\"Odessa\",\"Verbrechen\",\"von\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\\\/\",\"name\":\"Massaker von Odessa \u2013 Ein Verbrechen, das alles \u00e4nderte - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/Massaker-von-Odessa-\u2013-Ein-Verbrechen-das-alles-aenderte.jpg\",\"datePublished\":\"2026-05-02T15:50:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/Massaker-von-Odessa-\u2013-Ein-Verbrechen-das-alles-aenderte.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/Massaker-von-Odessa-\u2013-Ein-Verbrechen-das-alles-aenderte.jpg\",\"caption\":\"Massaker von Odessa \u2013 Ein Verbrechen, das alles \u00e4nderte\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Massaker von Odessa \u2013 Ein Verbrechen, das alles \u00e4nderte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Massaker von Odessa \u2013 Ein Verbrechen, das alles \u00e4nderte - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\/","og_locale":"de_DE","og_type":"article","og_title":"Massaker von Odessa \u2013 Ein Verbrechen, das alles \u00e4nderte","og_description":"Feuer, zerbrochenes Glas, Tote und Verwundete: Wer den Maidan-Putsch akzeptieren nicht wollte, musste mit Blut bezahlen. Vor zw\u00f6lf Jahren bejubelten ukrainische Nationalisten in Odessa den Tod von 48 Menschen. Die Schuldigen wurden immer noch nicht bestraft. Von Wiktor Schdanow Geplante Trag\u00f6die Den Staatsstreich in Kiew im Februar\u00a02014 akzeptierten die Bewohner von Odessa nicht. Am 23.\u00a0Februar [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2026-05-02T15:50:11+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/05\/69f5f7e0b480cc37096f75a1.jpg","type":"","width":"","height":""}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Massaker von Odessa \u2013 Ein Verbrechen, das alles \u00e4nderte","datePublished":"2026-05-02T15:50:11+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\/"},"wordCount":1253,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Massaker-von-Odessa-\u2013-Ein-Verbrechen-das-alles-aenderte.jpg","keywords":["alles","\u00e4nderte","das","ein","Massaker","Odessa","Verbrechen","von"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\/","url":"https:\/\/now-news.de\/de\/deutschland\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\/","name":"Massaker von Odessa \u2013 Ein Verbrechen, das alles \u00e4nderte - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Massaker-von-Odessa-\u2013-Ein-Verbrechen-das-alles-aenderte.jpg","datePublished":"2026-05-02T15:50:11+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Massaker-von-Odessa-\u2013-Ein-Verbrechen-das-alles-aenderte.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Massaker-von-Odessa-\u2013-Ein-Verbrechen-das-alles-aenderte.jpg","caption":"Massaker von Odessa \u2013 Ein Verbrechen, das alles \u00e4nderte"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/massaker-von-odessa-ein-verbrechen-das-alles-aenderte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Massaker von Odessa \u2013 Ein Verbrechen, das alles \u00e4nderte"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/102610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=102610"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/102610\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/102611"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=102610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=102610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=102610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}