{"id":102362,"date":"2026-04-27T11:18:26","date_gmt":"2026-04-27T09:18:26","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/"},"modified":"2026-04-27T11:18:26","modified_gmt":"2026-04-27T09:18:26","slug":"rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/","title":{"rendered":"Rekord bei Milit\u00e4rausgaben im Jahr 2025: Europ\u00e4ische NATO-Mitglieder ganz vorn dabei"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/69ef20cd48fbef335e62a74a.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Die f\u00fcr Waffen und Aufr\u00fcstung bereitgestellten finanziellen Mittel erreichten 2025 weltweit ein Rekordniveau. Das hat das Friedensforschungsinstitut SIPRI festgestellt. Hauptursache dieses Anstiegs: ein Zuwachs an Milit\u00e4rausgaben in Gesamt-Europa.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Wie das schwedische Friedensforschungsinstitut SIPRI heute bekannt gab, sind im Jahr 2025 die globalen R\u00fcstungsausgaben weiter angestiegen. Besonders rasant\u00a0erh\u00f6hten sich\u00a0die Aufwendungen f\u00fcr das Milit\u00e4r in Gesamt-Europa und in Asien. Die R\u00fcstungsausgaben der Vereinigten Staaten sanken dagegen im gleichen Zeitraum, was SIPRI zufolge vor allem auf einen R\u00fcckgang der Ukraine-Hilfen zur\u00fcckzuf\u00fchren ist.<\/p>\n<p>Die Ausgaben f\u00fcr R\u00fcstung und Waffen sind demnach 2025 im Vergleich zum Vorjahreszeitraum um 2,9 Prozent auf 2.887 Milliarden US-Dollar angewachsen. 51 der weltweiten Gesamtausgaben beruhen auf den R\u00fcstungsanstrengungen der gro\u00dfen Staaten USA, China und Russland. Deren R\u00fcstung umfasste 2025 1.480 Milliarden US-Dollar. Europa und Asien plus Ozeanien gaben 2025 im Vergleich zu den weltweiten Milit\u00e4rausgaben \u00fcberdurchschnittlich viel Finanzmittel f\u00fcr R\u00fcstung aus: In Europa war eine Steigerung um 14 Prozent zu verzeichnen, in Asien und Ozeanien um 8,1 Prozent.<\/p>\n<p>Die globale Milit\u00e4rlast, also der zusammengerechnete Anteil der Milit\u00e4rausgaben am Bruttoinlandsprodukt aller L\u00e4nder erreichte 2,5 Prozent \u2013 der h\u00f6chste Stand seit 2009. Insgesamt verlangsamte sich zwar der Anstieg der Milit\u00e4rausgaben: 2025 wuchsen sie um 2,9 Prozent, Im Jahr 2024 betrug das Wachstum dagegen 9,7 Prozent. SIPRI f\u00fchrt dieses verlangsamte Wachstum jedoch gr\u00f6\u00dftenteils auf den Sparkurs der USA zur\u00fcck. Rechnet man den Anteil der Vereinigten Staaten heraus, stiegen die Gesamtausgaben 2025 um 9,2 Prozent. SIPRI rechnet auch f\u00fcr die Folgejahre 2026 und dar\u00fcber hinaus mit massiven Aufr\u00fcstungskampagnen weltweit.<\/p>\n<p>Die Vereinigten Staaten gaben 2025 954 Milliarden US-Dollar f\u00fcr R\u00fcstungsg\u00fcter aus \u2013 7,5 Prozent weniger als 2024. Die haupts\u00e4chliche Ursache: Die USA genehmigten im Berichtsjahr \u2013 anders als in den Jahren zuvor \u2013 keine neuen Finanzhilfen f\u00fcr die Ukraine. Jedoch\u00a0erh\u00f6he Washington\u00a0die Investitionen in\u00a0seine eigenen nuklearen und konventionellen F\u00e4higkeiten. Dabei gehe es den Vereinigten Staaten um die Aufrechterhaltung ihrer Vorherrschaft in der westlichen Hemisph\u00e4re und um eine Abschreckung Chinas, so SIPRI. F\u00fcr die Jahre 2026 und 2027 sei wieder mit einem Anstieg der US-Milit\u00e4rausgaben zu rechnen.<\/p>\n<p>Angesichts des fortdauernden Ukraine-Kriegs sind die massiven R\u00fcstungssteigerungen von Russland und der Ukraine keine \u00dcberraschung. Russlands Milit\u00e4rausgaben umfassten\u00a0laut SIPRI im Jahr 2025 7,5 Prozent des BIP, sie sind dem Forschungsinstitut zufolge um 5,9 Prozent auf 190 Milliarden US-Dollar gestiegen. Die Ukraine war 2025\u00a0an siebter Stelle weltweit bei den Milit\u00e4rausgaben, die mit 84,1 Milliarden US-Dollar 40 Prozent des ukrainischen BIP ausmachten\u00a0\u2013 ein Anstieg von 20 Prozent. Auch hier prognostiziert SIPRI f\u00fcr 2026 eine weitere Steigerung, falls es nicht zu einem Frieden kommt.<\/p>\n<p>Extrem gestiegen sind die Milit\u00e4rausgaben der 29 europ\u00e4ischen NATO-Staaten. Insgesamt waren es 2025 559 Milliarden US-Dollar \u2013 einen so rasanten Anstieg hatte es seit 1953 nicht mehr gegeben (damals tobte der Korea-Krieg). Den vordersten Platz bei der Aufr\u00fcstung der Euro-NATO belegt dabei Deutschland: Die Ausgaben f\u00fcr die Aufr\u00fcstung der Bundeswehr stiegen im Vergleich zu 2024 um 24 Prozent auf 114 Milliarden US-Dollar. Das sind 2,3 Prozent des deutschen BIP 2025. Damit \u00fcberschritt Deutschland zum ersten Mal seit 1990 das Zwei-Prozent-Ziel der NATO von 2014 und liegt nunmehr erstmalig weltweit auf Platz 4\u00a0bei den R\u00fcstungsausgaben. Vor Deutschland befinden sich nur noch die Superm\u00e4chte.<\/p>\n<p>Im Nahen Osten dagegen sind die R\u00fcstungsausgaben 2025 stabil geblieben. Mit 218 Milliarden US-Dollar war nur ein minimaler Anstieg gegen\u00fcber 2024 von 0,1 Prozent zu verzeichnen, was SIPRI auf das Abflammen des Gaza-Konflikts zur\u00fcckf\u00fchrt. In Asien dagegen belief sich der Anstieg auf 8,1 Prozent \u2013 das gr\u00f6\u00dfte Wachstum seit 2009. China erh\u00f6hte seine Milit\u00e4rausgaben um 7,4 Prozent auf 336 Milliarden US-Dollar, Taiwan um 14 Prozent auf 18,2 Milliarden US-Dollar. Rekordwerte erreichten Japans Aufwendungen f\u00fcr das Milit\u00e4r: Sie stiegen um 9,7 Prozent auf 62,2 Milliarden US-Dollar und machten 1,4 Prozent des BIP aus \u2013 so viel wie seit 1958 nicht mehr.<\/p>\n<p><strong>Mehr zum Thema &#8211;<\/strong>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/inland\/277262-deutsche-slawen-gegen-aufruestung-und-krieg-sorbische-friedensinitiative-gegruendet\/\">Deutsche Slawen gegen Aufr\u00fcstung und Krieg: Sorbische Friedensinitiative gegr\u00fcndet<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v76si9a\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/278320-europaeische-nato-mitglieder-2025-rekord-milit%C3%A4rausgaben\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die f\u00fcr Waffen und Aufr\u00fcstung bereitgestellten finanziellen Mittel erreichten 2025 weltweit ein Rekordniveau. Das hat das Friedensforschungsinstitut SIPRI festgestellt. Hauptursache dieses Anstiegs: ein Zuwachs an Milit\u00e4rausgaben in Gesamt-Europa. Wie das schwedische Friedensforschungsinstitut SIPRI heute bekannt gab, sind im Jahr 2025 die globalen R\u00fcstungsausgaben weiter angestiegen. Besonders rasant\u00a0erh\u00f6hten sich\u00a0die Aufwendungen f\u00fcr das Milit\u00e4r in Gesamt-Europa und [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":102363,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1777281915"],"wp_automatic_camp":["217"],"a4240749ef97589210c876b5f5ac4916":["Rekord bei Milit\u00e4rausgaben im Jahr 2025: Europ\u00e4ische NATO-Mitglieder ganz vorn dabei"],"original_link":["https:\/\/de.rt.com\/international\/278320-europaeische-nato-mitglieder-2025-rekord-milit%C3%A4rausgaben\/"],"_thumbnail_id":["102363"],"jnews_social_counter_last_update":["1778635320"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2026-04-27 11:26:15\";}"]},"categories":[19,23],"tags":[363,10432,21307,14576,1615,10292,38411,14355,19074],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rekord bei Milit\u00e4rausgaben im Jahr 2025: Europ\u00e4ische NATO-Mitglieder ganz vorn dabei - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rekord bei Milit\u00e4rausgaben im Jahr 2025: Europ\u00e4ische NATO-Mitglieder ganz vorn dabei\" \/>\n<meta property=\"og:description\" content=\"Die f\u00fcr Waffen und Aufr\u00fcstung bereitgestellten finanziellen Mittel erreichten 2025 weltweit ein Rekordniveau. Das hat das Friedensforschungsinstitut SIPRI festgestellt. Hauptursache dieses Anstiegs: ein Zuwachs an Milit\u00e4rausgaben in Gesamt-Europa. Wie das schwedische Friedensforschungsinstitut SIPRI heute bekannt gab, sind im Jahr 2025 die globalen R\u00fcstungsausgaben weiter angestiegen. Besonders rasant\u00a0erh\u00f6hten sich\u00a0die Aufwendungen f\u00fcr das Milit\u00e4r in Gesamt-Europa und [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-27T09:18:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/69ef20cd48fbef335e62a74a.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Rekord bei Milit\u00e4rausgaben im Jahr 2025: Europ\u00e4ische NATO-Mitglieder ganz vorn dabei\",\"datePublished\":\"2026-04-27T09:18:26+00:00\",\"dateModified\":\"2026-04-27T09:18:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/\"},\"wordCount\":643,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Rekord-bei-Militaerausgaben-im-Jahr-2025-Europaeische-NATO-Mitglieder-ganz-vorn.jpg\",\"keywords\":[\"bei\",\"dabei\",\"europ\u00e4ische\",\"ganz\",\"Jahr\",\"Milit\u00e4rausgaben\",\"NATOMitglieder\",\"Rekord\",\"vorn\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/\",\"name\":\"Rekord bei Milit\u00e4rausgaben im Jahr 2025: Europ\u00e4ische NATO-Mitglieder ganz vorn dabei - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Rekord-bei-Militaerausgaben-im-Jahr-2025-Europaeische-NATO-Mitglieder-ganz-vorn.jpg\",\"datePublished\":\"2026-04-27T09:18:26+00:00\",\"dateModified\":\"2026-04-27T09:18:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Rekord-bei-Militaerausgaben-im-Jahr-2025-Europaeische-NATO-Mitglieder-ganz-vorn.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Rekord-bei-Militaerausgaben-im-Jahr-2025-Europaeische-NATO-Mitglieder-ganz-vorn.jpg\",\"caption\":\"Rekord bei Milit\u00e4rausgaben im Jahr 2025: Europ\u00e4ische NATO-Mitglieder ganz vorn dabei\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rekord bei Milit\u00e4rausgaben im Jahr 2025: Europ\u00e4ische NATO-Mitglieder ganz vorn dabei\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Rekord bei Milit\u00e4rausgaben im Jahr 2025: Europ\u00e4ische NATO-Mitglieder ganz vorn dabei - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/","og_locale":"de_DE","og_type":"article","og_title":"Rekord bei Milit\u00e4rausgaben im Jahr 2025: Europ\u00e4ische NATO-Mitglieder ganz vorn dabei","og_description":"Die f\u00fcr Waffen und Aufr\u00fcstung bereitgestellten finanziellen Mittel erreichten 2025 weltweit ein Rekordniveau. Das hat das Friedensforschungsinstitut SIPRI festgestellt. Hauptursache dieses Anstiegs: ein Zuwachs an Milit\u00e4rausgaben in Gesamt-Europa. Wie das schwedische Friedensforschungsinstitut SIPRI heute bekannt gab, sind im Jahr 2025 die globalen R\u00fcstungsausgaben weiter angestiegen. Besonders rasant\u00a0erh\u00f6hten sich\u00a0die Aufwendungen f\u00fcr das Milit\u00e4r in Gesamt-Europa und [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2026-04-27T09:18:26+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/69ef20cd48fbef335e62a74a.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Rekord bei Milit\u00e4rausgaben im Jahr 2025: Europ\u00e4ische NATO-Mitglieder ganz vorn dabei","datePublished":"2026-04-27T09:18:26+00:00","dateModified":"2026-04-27T09:18:26+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/"},"wordCount":643,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Rekord-bei-Militaerausgaben-im-Jahr-2025-Europaeische-NATO-Mitglieder-ganz-vorn.jpg","keywords":["bei","dabei","europ\u00e4ische","ganz","Jahr","Milit\u00e4rausgaben","NATOMitglieder","Rekord","vorn"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/","url":"https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/","name":"Rekord bei Milit\u00e4rausgaben im Jahr 2025: Europ\u00e4ische NATO-Mitglieder ganz vorn dabei - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Rekord-bei-Militaerausgaben-im-Jahr-2025-Europaeische-NATO-Mitglieder-ganz-vorn.jpg","datePublished":"2026-04-27T09:18:26+00:00","dateModified":"2026-04-27T09:18:26+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Rekord-bei-Militaerausgaben-im-Jahr-2025-Europaeische-NATO-Mitglieder-ganz-vorn.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Rekord-bei-Militaerausgaben-im-Jahr-2025-Europaeische-NATO-Mitglieder-ganz-vorn.jpg","caption":"Rekord bei Milit\u00e4rausgaben im Jahr 2025: Europ\u00e4ische NATO-Mitglieder ganz vorn dabei"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/rekord-bei-militaerausgaben-im-jahr-2025-europaeische-nato-mitglieder-ganz-vorn-dabei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Rekord bei Milit\u00e4rausgaben im Jahr 2025: Europ\u00e4ische NATO-Mitglieder ganz vorn dabei"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/102362"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=102362"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/102362\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/102363"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=102362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=102362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=102362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}