{"id":101567,"date":"2026-04-13T18:27:17","date_gmt":"2026-04-13T16:27:17","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/"},"modified":"2026-04-13T18:27:17","modified_gmt":"2026-04-13T16:27:17","slug":"trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/","title":{"rendered":"Trotz Entlastungsplan von Merz: Spritpreise schie\u00dfen weiter nach oben"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/69dd02e648fbef5c352c2cd9.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Deutsche Tankstellen erh\u00f6hten die Preise f\u00fcr Kraftstoff am Montag wieder massiv. Die Entwicklungen im Iran-Krieg sorgten f\u00fcr Rekordspr\u00fcnge zur Mittagszeit. Die Bundesregierung hatte sich kurz zuvor auf ein kurzfristiges Entlastungspaket gegen die hohen Energiepreise geeinigt. Droht dies zu verpuffen?\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Der R\u00fcckgang der Spritpreise in Deutschland ist vorerst beendet. Wie aus aktuellen ADAC-Daten hervorgeht, fielen die sogenannten Mittagsspr\u00fcnge am Montag so hoch aus wie noch nie seit Einf\u00fchrung der 12-Uhr-Regel: Diesel verteuerte sich zwischen 11.45 Uhr und 12.15 Uhr um 12,5 Cent pro Liter, Super E10 um 11,4 Cent. Nach dem Sprung kostete E10 im bundesweiten Schnitt 2,181 Euro, Diesel 2,385 Euro. Das berichtet die <em>Berliner Zeitung<\/em> am Montag.<\/p>\n<p>Noch am Sonntag hatte E10 im Tagesdurchschnitt 2,10 Euro gekostet, Diesel 2,29 Euro. Eine Woche zuvor war E10 etwa neun, Diesel knapp 15 Cent teurer gewesen. Das Inkrafttreten einer Waffenruhe im Iran-Krieg hatte dies erm\u00f6glicht.<\/p>\n<p>Getrieben werden die Preise nun aber auch weiterhin vom \u00d6lmarkt: Nach dem k\u00fcrzlichen Scheitern der Verhandlungen zwischen den USA und Iran im Nahostkonflikt und der angek\u00fcndigten US-Seeblockade gegen iranische H\u00e4fen ist der \u00d6lpreis wieder auf \u00fcber 100 Dollar pro Barrel gestiegen, Tendenz steigend.<\/p>\n<p>Die Rekordspr\u00fcnge an den Zapfs\u00e4ulen treffen die Autofahrer kurz nachdem die Bundesregierung eine befristete Senkung der Energiesteuer um 17 Cent brutto pro Liter auf Diesel und Benzin verk\u00fcndete. Die Ma\u00dfnahme, die Verbraucher und Wirtschaft laut Arbeitsministerin B\u00e4rbel Bas (SPD) um insgesamt 1,6 Milliarden Euro entlasten soll, gilt f\u00fcr zwei Monate. Bundeskanzler Friedrich Merz (CDU) erwartet, dass die Mineral\u00f6lbranche die Senkung an die Kunden weitergibt. Ob das Wunschdenken ist, wird sich in den n\u00e4chsten Tagen herausstellen.<\/p>\n<p><strong>Mehr zum Thema<\/strong>\u00a0<strong>\u2013<\/strong>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/europa\/275980-kirill-dmitriev-eu-ist-15\/\">Kirill Dmitrijew: EU ist 15 Jahre zu sp\u00e4t, um sich auf Energieschock vorzubereiten<\/a><\/p>\n<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/277052-trotz-entlastungsankuendigung-von-merz-spritpreise\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deutsche Tankstellen erh\u00f6hten die Preise f\u00fcr Kraftstoff am Montag wieder massiv. Die Entwicklungen im Iran-Krieg sorgten f\u00fcr Rekordspr\u00fcnge zur Mittagszeit. Die Bundesregierung hatte sich kurz zuvor auf ein kurzfristiges Entlastungspaket gegen die hohen Energiepreise geeinigt. Droht dies zu verpuffen? Der R\u00fcckgang der Spritpreise in Deutschland ist vorerst beendet. Wie aus aktuellen ADAC-Daten hervorgeht, fielen die [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":101568,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1776205659"],"wp_automatic_camp":["217"],"741fd0e0b0ca0a9af95844424dd90743":["Trotz Entlastungsplan von Merz: Spritpreise schie\u00dfen weiter nach oben"],"original_link":["https:\/\/de.rt.com\/inland\/277052-trotz-entlastungsankuendigung-von-merz-spritpreise\/"],"_thumbnail_id":["101568"],"jnews_social_counter_last_update":["1784001853"],"_wptgpro_p2tg_sent2tg":["a:0:{}"]},"categories":[19,23],"tags":[72314,18728,979,1351,21826,23686,1381,50,601],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trotz Entlastungsplan von Merz: Spritpreise schie\u00dfen weiter nach oben - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trotz Entlastungsplan von Merz: Spritpreise schie\u00dfen weiter nach oben\" \/>\n<meta property=\"og:description\" content=\"Deutsche Tankstellen erh\u00f6hten die Preise f\u00fcr Kraftstoff am Montag wieder massiv. Die Entwicklungen im Iran-Krieg sorgten f\u00fcr Rekordspr\u00fcnge zur Mittagszeit. Die Bundesregierung hatte sich kurz zuvor auf ein kurzfristiges Entlastungspaket gegen die hohen Energiepreise geeinigt. Droht dies zu verpuffen? Der R\u00fcckgang der Spritpreise in Deutschland ist vorerst beendet. Wie aus aktuellen ADAC-Daten hervorgeht, fielen die [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-13T16:27:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/69dd02e648fbef5c352c2cd9.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Trotz Entlastungsplan von Merz: Spritpreise schie\u00dfen weiter nach oben\",\"datePublished\":\"2026-04-13T16:27:17+00:00\",\"dateModified\":\"2026-04-13T16:27:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/\"},\"wordCount\":297,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Trotz-Entlastungsplan-von-Merz-Spritpreise-schiessen-weiter-nach-oben.jpg\",\"keywords\":[\"Entlastungsplan\",\"Merz\",\"nach\",\"oben\",\"schie\u00dfen\",\"Spritpreise\",\"Trotz\",\"von\",\"weiter\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/\",\"name\":\"Trotz Entlastungsplan von Merz: Spritpreise schie\u00dfen weiter nach oben - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Trotz-Entlastungsplan-von-Merz-Spritpreise-schiessen-weiter-nach-oben.jpg\",\"datePublished\":\"2026-04-13T16:27:17+00:00\",\"dateModified\":\"2026-04-13T16:27:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Trotz-Entlastungsplan-von-Merz-Spritpreise-schiessen-weiter-nach-oben.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Trotz-Entlastungsplan-von-Merz-Spritpreise-schiessen-weiter-nach-oben.jpg\",\"caption\":\"Trotz Entlastungsplan von Merz: Spritpreise schie\u00dfen weiter nach oben\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trotz Entlastungsplan von Merz: Spritpreise schie\u00dfen weiter nach oben\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Trotz Entlastungsplan von Merz: Spritpreise schie\u00dfen weiter nach oben - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/","og_locale":"de_DE","og_type":"article","og_title":"Trotz Entlastungsplan von Merz: Spritpreise schie\u00dfen weiter nach oben","og_description":"Deutsche Tankstellen erh\u00f6hten die Preise f\u00fcr Kraftstoff am Montag wieder massiv. Die Entwicklungen im Iran-Krieg sorgten f\u00fcr Rekordspr\u00fcnge zur Mittagszeit. Die Bundesregierung hatte sich kurz zuvor auf ein kurzfristiges Entlastungspaket gegen die hohen Energiepreise geeinigt. Droht dies zu verpuffen? Der R\u00fcckgang der Spritpreise in Deutschland ist vorerst beendet. Wie aus aktuellen ADAC-Daten hervorgeht, fielen die [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2026-04-13T16:27:17+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/69dd02e648fbef5c352c2cd9.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Trotz Entlastungsplan von Merz: Spritpreise schie\u00dfen weiter nach oben","datePublished":"2026-04-13T16:27:17+00:00","dateModified":"2026-04-13T16:27:17+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/"},"wordCount":297,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Trotz-Entlastungsplan-von-Merz-Spritpreise-schiessen-weiter-nach-oben.jpg","keywords":["Entlastungsplan","Merz","nach","oben","schie\u00dfen","Spritpreise","Trotz","von","weiter"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/","url":"https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/","name":"Trotz Entlastungsplan von Merz: Spritpreise schie\u00dfen weiter nach oben - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Trotz-Entlastungsplan-von-Merz-Spritpreise-schiessen-weiter-nach-oben.jpg","datePublished":"2026-04-13T16:27:17+00:00","dateModified":"2026-04-13T16:27:17+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Trotz-Entlastungsplan-von-Merz-Spritpreise-schiessen-weiter-nach-oben.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/Trotz-Entlastungsplan-von-Merz-Spritpreise-schiessen-weiter-nach-oben.jpg","caption":"Trotz Entlastungsplan von Merz: Spritpreise schie\u00dfen weiter nach oben"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/trotz-entlastungsplan-von-merz-spritpreise-schiessen-weiter-nach-oben\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Trotz Entlastungsplan von Merz: Spritpreise schie\u00dfen weiter nach oben"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/101567"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=101567"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/101567\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/101568"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=101567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=101567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=101567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}