{"id":101459,"date":"2026-04-08T17:27:09","date_gmt":"2026-04-08T15:27:09","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/"},"modified":"2026-04-08T17:27:09","modified_gmt":"2026-04-08T15:27:09","slug":"beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/","title":{"rendered":"&quot;Beispiellos seit dem Krieg&quot; \u2013 Netschajew kritisiert Russophobie in Deutschland"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/69d61bfa48fbef6335681ade.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Die Russophobie in Deutschland habe ein beispielloses Ausma\u00df erreicht, warnt der russische Botschafter Netschajew. Gleichzeitig sieht er kaum Interesse westlicher Staaten an einer politischen L\u00f6sung des Ukraine-Konflikts und spricht von einer weiteren Eskalationsspirale.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p data-start=\"85\" data-end=\"238\">Die Russophobie in Deutschland hat nach Einsch\u00e4tzung des russischen Botschafters in Deutschland, Sergei Netschajew, ein Ausma\u00df erreicht, das in der gesamten Nachkriegszeit beispiellos sei. Dies sagte er im <a rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/www.nachdenkseiten.de\/?p=148687\" target=\"_blank\" rel=\"noopener noreferrer\">Interview<\/a> mit dem Portal <em><a rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/www.nachdenkseiten.de\/?p=148697\" target=\"_blank\" rel=\"noopener noreferrer\">NachDenkSeiten<\/a>:<\/em><\/p>\n<p data-start=\"85\" data-end=\"238\"><em>&#8220;Leider hat die Russophobie in Deutschland heute ein in der gesamten Nachkriegszeit beispielloses Ausma\u00df angenommen. Selbst w\u00e4hrend des Kalten Krieges und der ideologischen Konfrontation zwischen West und Ost war nichts dergleichen zu beobachten.&#8221;<br \/><\/em><\/p>\n<p data-start=\"785\" data-end=\"1233\">Laut dem Diplomaten werde in Deutschland gezielt ein &#8220;toxisches Klima&#8221; rund um Russland sowie um Kontakte zu russischen staatlichen und gesellschaftlichen Organisationen und Medien erzeugt. In diesem Zusammenhang sei die Russophobie de facto zu einem festen Bestandteil der innenpolitischen Agenda geworden, die eine tiefgreifende Umgestaltung des sozial\u00f6konomischen Modells zugunsten einer umfassenden Militarisierung rechtfertigen solle.<\/p>\n<p data-start=\"1235\" data-end=\"1599\">&#8220;Nahezu t\u00e4glich erscheinen Meldungen \u00fcber angebliche russische Spione, hybride Angriffe und Desinformationskampagnen&#8221;, so der Botschafter. Diese Narrative zielten darauf ab, die deutsche Gesellschaft zu destabilisieren. Technische Zwischenf\u00e4lle oder St\u00f6rungen der Infrastruktur w\u00fcrden dabei regelm\u00e4\u00dfig den russischen Geheimdiensten zugeschrieben.\u00a0Netschajew w\u00f6rtlich:<\/p>\n<p data-start=\"1235\" data-end=\"1599\"><em>&#8220;Das Ziel dieser Diffamierungen ist offensichtlich: Kontakte zu russischen Vertretern m\u00f6glichst toxisch und gef\u00e4hrlich erscheinen zu lassen und diejenigen einzusch\u00fcchtern, die weiterhin bereit sind, mit uns zusammenzuarbeiten, um die einst freundschaftlichen und konstruktiven Beziehungen zwischen unseren L\u00e4ndern und V\u00f6lkern wiederherzustellen.&#8221;<\/p>\n<p><\/em>Im Alltag sehe sich die russische Botschaft zudem regelm\u00e4\u00dfig mit der Weigerung deutscher Beh\u00f6rden, Unternehmen und Finanzinstitute konfrontiert, aus politischen Gr\u00fcnden oder unter Verweis auf Sanktionsvorgaben zu kooperieren. Dies erschwere ihre Arbeit erheblich. Diese Situation k\u00f6nne kaum als normal bezeichnet werden, pr\u00e4zisierte Netschajew.\u00a0Gleichzeitig \u00e4u\u00dferte er sich vorsichtig optimistisch.\u00a0Ein erheblicher Teil der deutschen Bev\u00f6lkerung bleibe gegen\u00fcber der &#8220;massiven antirussischen Propaganda&#8221; unempf\u00e4nglich und w\u00fcnsche sich weiterhin gute Beziehungen zu Russland:<\/p>\n<p data-start=\"1235\" data-end=\"1599\"><em>&#8220;Es ist ermutigend, dass ein gro\u00dfer Teil der deutschen Bev\u00f6lkerung Russland weiterhin positiv gegen\u00fcbersteht und sich normale, freundschaftliche Beziehungen zu unserem Land w\u00fcnscht. Wir freuen uns, dass wir hier in Deutschland nach wie vor viele Freunde haben, die sich nicht von der antirussischen Haltung der offiziellen Stellen beeinflussen lassen.&#8221;<\/em><\/p>\n<p data-start=\"1920\" data-end=\"2140\">Im Zusammenhang mit dem Ukraine-Konflikt kritisierte der Botschafter die Position westlicher Regierungen. Aus seiner Sicht stehe nicht eine politische L\u00f6sung im Vordergrund, sondern eine fortgesetzte Konfrontationslogik:<\/p>\n<p data-start=\"1920\" data-end=\"2140\"><em>&#8220;Leider m\u00fcssen wir feststellen, dass die meisten westeurop\u00e4ischen Entscheidungstr\u00e4ger an einer politischen Beilegung des Konflikts, der den Kontinent gespalten hat, kein ernsthaftes Interesse zeigen.&#8221;\u00a0<br \/><\/em><\/p>\n<p data-start=\"3310\" data-end=\"3690\">Stattdessen setzten sie auf eine Strategie der &#8220;Abnutzung&#8221; Russlands durch Sanktionen und milit\u00e4rische Ma\u00dfnahmen sowie auf das Ziel einer &#8220;strategischen Niederlage&#8221;. In diesem Zusammenhang verwies Netschajew auf historische Kontinuit\u00e4ten westlicher Planung, darunter die Operation &#8220;Dropshot&#8221;, die im Kalten Krieg massive US-Nuklearschl\u00e4ge gegen sowjetische St\u00e4dte vorgesehen habe.<\/p>\n<p data-start=\"3310\" data-end=\"3690\">Dies zeige eher eine Fortsetzung fr\u00fcherer Denkmuster als ein Abweichen von ihnen. Unter Verweis auf die aktuelle politische Rhetorik sprach er von der erneuten Beschw\u00f6rung einer &#8220;Bedrohung aus dem Osten&#8221;, die dazu diene, innenpolitische Probleme zu erkl\u00e4ren, R\u00fcstungsausgaben zu rechtfertigen und Zustimmung f\u00fcr eine antirussische Agenda zu mobilisieren.<\/p>\n<p data-start=\"3310\" data-end=\"3690\">Diese Entwicklung verringere die Chancen auf eine politische L\u00f6sung des Konflikts, verl\u00e4ngere die &#8220;Agonie des Kiewer Regimes&#8221; und erh\u00f6he das Risiko einer gro\u00dfangelegten Konfrontation. F\u00fcr einen dauerhaften Frieden m\u00fcssten die westlichen Staaten ihre Politik grundlegend \u00fcberdenken und die Sicherheitsinteressen Russlands sowie dessen Entwicklungsrecht ber\u00fccksichtigen.<\/p>\n<p data-start=\"3141\" data-end=\"3413\"><em>&#8220;Der Frieden auf dem Kontinent wird umso stabiler sein, je mehr Russland als gleichberechtigter Partner in die europ\u00e4ische Sicherheitsarchitektur eingebunden ist. Keinesfalls aber wird so eine Sicherheitsarchitektur tragf\u00e4hig sein, wenn sie gegen Russland aufgebaut wird.&#8221;<\/em><\/p>\n<p data-start=\"4685\" data-end=\"4970\">Vor diesem Hintergrund bezeichnete Netschajew den Zustand der russisch-deutschen Beziehungen ebenfalls als bedr\u00fcckend. Diese seien auf Initiative der deutschen Seite nahezu vollst\u00e4ndig zerst\u00f6rt worden. Die aktuelle Lage sei kontraproduktiv und entspreche nicht den Interessen beider Seiten. Dies habe nicht Russland entschieden, betonte er. Moskau habe die Zusammenarbeit nie aufgek\u00fcndigt und keine &#8220;Br\u00fccken&#8221; abgebrochen. Abschlie\u00dfend hob der Botschafter die Bedeutung der historischen Verantwortung Deutschlands hervor.<\/p>\n<p data-start=\"4685\" data-end=\"4970\"><em>&#8220;Wir sind \u00fcberzeugt, dass das historische Bewusstsein, das Verantwortungsgef\u00fchl Deutschlands f\u00fcr die schrecklichen Verbrechen des Nazismus ebenso wie das Gef\u00fchl der Dankbarkeit gegen\u00fcber dem sowjetischen Volk f\u00fcr die Befreiung, die Nachkriegsvers\u00f6hnung und die deutsche Einheit weder von politischer Konjunktur beeinflusst werden d\u00fcrfen noch der Erosion und dem Vergessen anheimfallen k\u00f6nnen.&#8221;<\/em><\/p>\n<p data-start=\"4819\" data-end=\"4997\" data-is-last-node=\"\" data-is-only-node=\"\">Russland messe der Vermittlung dieser Positionen in Deutschland besondere Bedeutung bei \u2013 auch im Kontext der Bem\u00fchungen um globale Sicherheit und Stabilit\u00e4t.<\/p>\n<p><strong>Mehr zum Thema\u00a0<\/strong>\u2013 <a rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/freedert.online\/inland\/265278-nicht-einmal-fuer-tote-russen-ist-in-deutschland-mehr-platz\/\" target=\"_blank\" rel=\"noopener noreferrer\">Nicht einmal f\u00fcr tote Russen ist in Deutschland mehr Platz<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v73e0zo\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/europa\/276437-beispiellos-seit-krieg-netschajew-kritisiert-russophobie-deutschland\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Russophobie in Deutschland habe ein beispielloses Ausma\u00df erreicht, warnt der russische Botschafter Netschajew. Gleichzeitig sieht er kaum Interesse westlicher Staaten an einer politischen L\u00f6sung des Ukraine-Konflikts und spricht von einer weiteren Eskalationsspirale. Die Russophobie in Deutschland hat nach Einsch\u00e4tzung des russischen Botschafters in Deutschland, Sergei Netschajew, ein Ausma\u00df erreicht, das in der gesamten Nachkriegszeit [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":101460,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1775662583"],"wp_automatic_camp":["217"],"b39088b76d922f4f608c1c261888d86d":["&quot;Beispiellos seit dem Krieg&quot; \u2013 Netschajew kritisiert Russophobie in Deutschland"],"original_link":["https:\/\/de.rt.com\/europa\/276437-beispiellos-seit-krieg-netschajew-kritisiert-russophobie-deutschland\/"],"_thumbnail_id":["101460"],"jnews_social_counter_last_update":["1778627511"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2026-04-08 17:38:24\";}"]},"categories":[19,23],"tags":[134,179,18890,739,41303,46618,1542,1829],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Beispiellos seit dem Krieg&quot; \u2013 Netschajew kritisiert Russophobie in Deutschland - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Beispiellos seit dem Krieg&quot; \u2013 Netschajew kritisiert Russophobie in Deutschland\" \/>\n<meta property=\"og:description\" content=\"Die Russophobie in Deutschland habe ein beispielloses Ausma\u00df erreicht, warnt der russische Botschafter Netschajew. Gleichzeitig sieht er kaum Interesse westlicher Staaten an einer politischen L\u00f6sung des Ukraine-Konflikts und spricht von einer weiteren Eskalationsspirale. Die Russophobie in Deutschland hat nach Einsch\u00e4tzung des russischen Botschafters in Deutschland, Sergei Netschajew, ein Ausma\u00df erreicht, das in der gesamten Nachkriegszeit [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-08T15:27:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/69d61bfa48fbef6335681ade.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"&quot;Beispiellos seit dem Krieg&quot; \u2013 Netschajew kritisiert Russophobie in Deutschland\",\"datePublished\":\"2026-04-08T15:27:09+00:00\",\"dateModified\":\"2026-04-08T15:27:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/\"},\"wordCount\":806,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/quotBeispiellos-seit-dem-Kriegquot-\u2013-Netschajew-kritisiert-Russophobie-in-Deutschland.jpg\",\"keywords\":[\"DEM\",\"Deutschland\",\"Kriegquot\",\"kritisiert\",\"Netschajew\",\"quotBeispiellos\",\"Russophobie\",\"seit\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/\",\"name\":\"&quot;Beispiellos seit dem Krieg&quot; \u2013 Netschajew kritisiert Russophobie in Deutschland - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/quotBeispiellos-seit-dem-Kriegquot-\u2013-Netschajew-kritisiert-Russophobie-in-Deutschland.jpg\",\"datePublished\":\"2026-04-08T15:27:09+00:00\",\"dateModified\":\"2026-04-08T15:27:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/quotBeispiellos-seit-dem-Kriegquot-\u2013-Netschajew-kritisiert-Russophobie-in-Deutschland.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/quotBeispiellos-seit-dem-Kriegquot-\u2013-Netschajew-kritisiert-Russophobie-in-Deutschland.jpg\",\"width\":460,\"height\":259,\"caption\":\"&quot;Beispiellos seit dem Krieg&quot; \u2013 Netschajew kritisiert Russophobie in Deutschland\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&quot;Beispiellos seit dem Krieg&quot; \u2013 Netschajew kritisiert Russophobie in Deutschland\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"&quot;Beispiellos seit dem Krieg&quot; \u2013 Netschajew kritisiert Russophobie in Deutschland - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/","og_locale":"de_DE","og_type":"article","og_title":"&quot;Beispiellos seit dem Krieg&quot; \u2013 Netschajew kritisiert Russophobie in Deutschland","og_description":"Die Russophobie in Deutschland habe ein beispielloses Ausma\u00df erreicht, warnt der russische Botschafter Netschajew. Gleichzeitig sieht er kaum Interesse westlicher Staaten an einer politischen L\u00f6sung des Ukraine-Konflikts und spricht von einer weiteren Eskalationsspirale. Die Russophobie in Deutschland hat nach Einsch\u00e4tzung des russischen Botschafters in Deutschland, Sergei Netschajew, ein Ausma\u00df erreicht, das in der gesamten Nachkriegszeit [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2026-04-08T15:27:09+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/69d61bfa48fbef6335681ade.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"&quot;Beispiellos seit dem Krieg&quot; \u2013 Netschajew kritisiert Russophobie in Deutschland","datePublished":"2026-04-08T15:27:09+00:00","dateModified":"2026-04-08T15:27:09+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/"},"wordCount":806,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/quotBeispiellos-seit-dem-Kriegquot-\u2013-Netschajew-kritisiert-Russophobie-in-Deutschland.jpg","keywords":["DEM","Deutschland","Kriegquot","kritisiert","Netschajew","quotBeispiellos","Russophobie","seit"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/","url":"https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/","name":"&quot;Beispiellos seit dem Krieg&quot; \u2013 Netschajew kritisiert Russophobie in Deutschland - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/quotBeispiellos-seit-dem-Kriegquot-\u2013-Netschajew-kritisiert-Russophobie-in-Deutschland.jpg","datePublished":"2026-04-08T15:27:09+00:00","dateModified":"2026-04-08T15:27:09+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/quotBeispiellos-seit-dem-Kriegquot-\u2013-Netschajew-kritisiert-Russophobie-in-Deutschland.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/quotBeispiellos-seit-dem-Kriegquot-\u2013-Netschajew-kritisiert-Russophobie-in-Deutschland.jpg","width":460,"height":259,"caption":"&quot;Beispiellos seit dem Krieg&quot; \u2013 Netschajew kritisiert Russophobie in Deutschland"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/beispiellos-seit-dem-krieg-netschajew-kritisiert-russophobie-in-deutschland\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"&quot;Beispiellos seit dem Krieg&quot; \u2013 Netschajew kritisiert Russophobie in Deutschland"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/101459"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=101459"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/101459\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/101460"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=101459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=101459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=101459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}