{"id":101263,"date":"2026-04-04T12:31:15","date_gmt":"2026-04-04T10:31:15","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\/"},"modified":"2026-04-04T12:31:15","modified_gmt":"2026-04-04T10:31:15","slug":"tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\/","title":{"rendered":"TASS: Putin f\u00fchrt mehr als zehn Telefongespr\u00e4che zu Nahost-Krise"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/69d0d77c48fbef38c9367afe.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Russlands Pr\u00e4sident Wladimir Putin hat im Zusammenhang mit der Gewalteskalation im Nahen Osten mit einer Reihe von ausl\u00e4ndischen Spitzenpolitikern telefoniert. Die meisten der Gespr\u00e4che fanden einem Medienbericht zufolge mit unmittelbar involvierten Akteuren statt.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Der Konflikt im Nahen Osten, der mit US-amerikanischen und israelischen Luftangriffen auf Ziele in Iran begann, dauert seit Ende Februar an. W\u00e4hrend dieser Zeit f\u00fchrte Russlands Staatspr\u00e4sident Wladimir Putin mehr als zehn Telefongespr\u00e4che mit ausl\u00e4ndischen Spitzenpolitikern. Dar\u00fcber berichtet die Nachrichtenagentur <em>TASS<\/em> unter Verweis auf eine eigene Analyse.<\/p>\n<p>Die meisten der Telefonate fanden dem Bericht zufolge mit Vertretern der L\u00e4nder statt, die direkt am Konflikt beteiligt sind. So sprach\u00a0Putin mehrmals mit dem iranischen Pr\u00e4sidenten Massud Peseschkian. Am 9. M\u00e4rz telefonierte der russische Staatschef mit US-Pr\u00e4sident Donald Trump.<\/p>\n<p>Putin f\u00fchrte au\u00dferdem Telefongespr\u00e4che mit den Staatsoberh\u00e4uptern der Golfregion, darunter Bahrain, Katar, die Vereinigten Arabischen Emirate (VAE) und Saudi-Arabien. Das iranische Milit\u00e4r f\u00fchrte Vergeltungsschl\u00e4ge gegen US-Milit\u00e4reinrichtungen in diesen L\u00e4ndern durch.<\/p>\n<p>Wie der Kreml bekanntgab, versprach Putin, Iran die tiefe Besorgnis der arabischen Staaten \u00fcber die Angriffe auf ihre Infrastrukturanlagen zu \u00fcbermitteln. Pr\u00e4sident Putin unternehme alle Anstrengungen und werde auch weiterhin alles tun, um zur Entspannung der Lage im Nahen Osten beizutragen, hie\u00df es.<\/p>\n<p>Die Gewalteskalation in der Region wurde auch bei Telefongespr\u00e4chen Putins mit den Staatschefs \u00c4gyptens, der T\u00fcrkei und Aserbaidschans ausf\u00fchrlich er\u00f6rtert. Das Thema kam zudem in Telefonaten mit den Pr\u00e4sidenten Usbekistans, Ungarns und Serbiens zur Sprache.<\/p>\n<p>Kremlsprecher Dmitri Peskow erkl\u00e4rte k\u00fcrzlich bei einem Pressebriefing, Pr\u00e4sident Putin befasse sich weiterhin mit der Krise im Nahen Osten, die sich zunehmend versch\u00e4rfe. Die Angelegenheit nehme in den letzten Tagen ziemlich viel Zeit des russischen Staatschefs in Anspruch, so der Sprecher.<\/p>\n<p>In einem Interview mit <em>TASS<\/em> ging Wladimir Fitin, Experte im Russischen Institut f\u00fcr Strategische Studien, auf die Frage ein, inwieweit diese Art der Diplomatie per Telefon darauf hindeute, dass Russland als m\u00f6glicher Vermittler wahrgenommen werde.<\/p>\n<p>&#8220;Russland nimmt in allen andauernden Konflikten im Nahen Osten eine sehr wichtige Stellung ein&#8221;, meinte der Experte. Vor allem handele es sich um den israelisch-pal\u00e4stinensischen Konflikt, in dem Russland stets als Vermittler fungiert und eigene Vorschl\u00e4ge f\u00fcr die Beilegung angeboten habe.<\/p>\n<p>Und weiter:<\/p>\n<p><em>&#8220;Ich glaube, dass diese Traditionen bewahrt werden und alle arabischen L\u00e4nder Russland als einen sehr wichtigen Bestandteil bei der L\u00f6sung schwerwiegender Widerspr\u00fcche auf dem Kontinent betrachten.&#8221;<\/em><\/p>\n<p><strong>Mehr zum Thema<\/strong>\u00a0\u2012 <a rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/freedert.online\/meinung\/275889-lehre-aus-dem-iran-krieg-moskau-muss-umziehen-am-besten-schon-gestern\/\" target=\"_blank\" rel=\"noopener noreferrer\">Lehre aus dem Iran-Krieg: Moskau muss umziehen, am besten schon gestern<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v75u75i\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/275983-tass-putin-fuehrt-mehr-als\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Russlands Pr\u00e4sident Wladimir Putin hat im Zusammenhang mit der Gewalteskalation im Nahen Osten mit einer Reihe von ausl\u00e4ndischen Spitzenpolitikern telefoniert. Die meisten der Gespr\u00e4che fanden einem Medienbericht zufolge mit unmittelbar involvierten Akteuren statt. Der Konflikt im Nahen Osten, der mit US-amerikanischen und israelischen Luftangriffen auf Ziele in Iran begann, dauert seit Ende Februar an. W\u00e4hrend [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":101264,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1775298703"],"wp_automatic_camp":["217"],"d309678252ea1dbec499826f7ede150c":["TASS: Putin f\u00fchrt mehr als zehn Telefongespr\u00e4che zu Nahost-Krise"],"original_link":["https:\/\/de.rt.com\/international\/275983-tass-putin-fuehrt-mehr-als\/"],"_thumbnail_id":["101264"],"jnews_social_counter_last_update":["1788380877"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2026-04-04 12:32:13\";}"]},"categories":[19,23],"tags":[273,3525,2063,50735,125,66940,67043,7076],"class_list":["post-101263","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-als","tag-fuehrt","tag-mehr","tag-nahostkrise","tag-putin","tag-tass","tag-telefongespraeche","tag-zehn"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>TASS: Putin f\u00fchrt mehr als zehn Telefongespr\u00e4che zu Nahost-Krise - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TASS: Putin f\u00fchrt mehr als zehn Telefongespr\u00e4che zu Nahost-Krise\" \/>\n<meta property=\"og:description\" content=\"Russlands Pr\u00e4sident Wladimir Putin hat im Zusammenhang mit der Gewalteskalation im Nahen Osten mit einer Reihe von ausl\u00e4ndischen Spitzenpolitikern telefoniert. Die meisten der Gespr\u00e4che fanden einem Medienbericht zufolge mit unmittelbar involvierten Akteuren statt. Der Konflikt im Nahen Osten, der mit US-amerikanischen und israelischen Luftangriffen auf Ziele in Iran begann, dauert seit Ende Februar an. W\u00e4hrend [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-04T10:31:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/69d0d77c48fbef38c9367afe.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"TASS: Putin f\u00fchrt mehr als zehn Telefongespr\u00e4che zu Nahost-Krise\",\"datePublished\":\"2026-04-04T10:31:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\\\/\"},\"wordCount\":440,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/04\\\/TASS-Putin-fuehrt-mehr-als-zehn-Telefongespraeche-zu-Nahost-Krise.jpg\",\"keywords\":[\"als\",\"f\u00fchrt\",\"mehr\",\"NahostKrise\",\"putin\",\"TASS\",\"Telefongespr\u00e4che\",\"zehn\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\\\/\",\"name\":\"TASS: Putin f\u00fchrt mehr als zehn Telefongespr\u00e4che zu Nahost-Krise - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/04\\\/TASS-Putin-fuehrt-mehr-als-zehn-Telefongespraeche-zu-Nahost-Krise.jpg\",\"datePublished\":\"2026-04-04T10:31:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/04\\\/TASS-Putin-fuehrt-mehr-als-zehn-Telefongespraeche-zu-Nahost-Krise.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/04\\\/TASS-Putin-fuehrt-mehr-als-zehn-Telefongespraeche-zu-Nahost-Krise.jpg\",\"width\":460,\"height\":259,\"caption\":\"TASS: Putin f\u00fchrt mehr als zehn Telefongespr\u00e4che zu Nahost-Krise\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TASS: Putin f\u00fchrt mehr als zehn Telefongespr\u00e4che zu Nahost-Krise\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"TASS: Putin f\u00fchrt mehr als zehn Telefongespr\u00e4che zu Nahost-Krise - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\/","og_locale":"de_DE","og_type":"article","og_title":"TASS: Putin f\u00fchrt mehr als zehn Telefongespr\u00e4che zu Nahost-Krise","og_description":"Russlands Pr\u00e4sident Wladimir Putin hat im Zusammenhang mit der Gewalteskalation im Nahen Osten mit einer Reihe von ausl\u00e4ndischen Spitzenpolitikern telefoniert. Die meisten der Gespr\u00e4che fanden einem Medienbericht zufolge mit unmittelbar involvierten Akteuren statt. Der Konflikt im Nahen Osten, der mit US-amerikanischen und israelischen Luftangriffen auf Ziele in Iran begann, dauert seit Ende Februar an. W\u00e4hrend [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2026-04-04T10:31:15+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/69d0d77c48fbef38c9367afe.jpg","type":"","width":"","height":""}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"TASS: Putin f\u00fchrt mehr als zehn Telefongespr\u00e4che zu Nahost-Krise","datePublished":"2026-04-04T10:31:15+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\/"},"wordCount":440,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/TASS-Putin-fuehrt-mehr-als-zehn-Telefongespraeche-zu-Nahost-Krise.jpg","keywords":["als","f\u00fchrt","mehr","NahostKrise","putin","TASS","Telefongespr\u00e4che","zehn"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\/","url":"https:\/\/now-news.de\/de\/deutschland\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\/","name":"TASS: Putin f\u00fchrt mehr als zehn Telefongespr\u00e4che zu Nahost-Krise - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/TASS-Putin-fuehrt-mehr-als-zehn-Telefongespraeche-zu-Nahost-Krise.jpg","datePublished":"2026-04-04T10:31:15+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/TASS-Putin-fuehrt-mehr-als-zehn-Telefongespraeche-zu-Nahost-Krise.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/TASS-Putin-fuehrt-mehr-als-zehn-Telefongespraeche-zu-Nahost-Krise.jpg","width":460,"height":259,"caption":"TASS: Putin f\u00fchrt mehr als zehn Telefongespr\u00e4che zu Nahost-Krise"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/tass-putin-fuehrt-mehr-als-zehn-telefongespraeche-zu-nahost-krise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"TASS: Putin f\u00fchrt mehr als zehn Telefongespr\u00e4che zu Nahost-Krise"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/101263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=101263"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/101263\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/101264"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=101263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=101263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=101263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}