{"id":101184,"date":"2026-04-02T16:25:18","date_gmt":"2026-04-02T14:25:18","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/"},"modified":"2026-04-02T16:25:18","modified_gmt":"2026-04-02T14:25:18","slug":"usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/","title":{"rendered":"USA streichen Venezuelas \u00dcbergangspr\u00e4sidentin Rodr\u00edguez von Sanktionsliste"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/69ce3b0148fbef44de611674.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Nach knapp acht Jahren auf der US-Sanktionsliste stehen nun Venezuelas \u00dcbergangspr\u00e4sidentin Delcy Rodr\u00edguez keine Hindernisse mehr im Weg, um die Beziehungen zwischen Caracas und Washington zu normalisieren. Die Politikerin hofft, dass bald weitere Einschr\u00e4nkungen fallen werden.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Die US-Kontrollbeh\u00f6rde f\u00fcr Auslandsverm\u00f6gen (OFAC), die dem Finanzministerium in Washington untersteht, hat am Mittwoch die Sanktionen gegen Venezuelas \u00dcbergangspr\u00e4sidentin Delcy Rodr\u00edguez\u00a0<a rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/www.cbsnews.com\/news\/trump-administration-lifts-sanctions-delcy-rodriguez-venezuela-acting-president\/\" target=\"_blank\" rel=\"noopener noreferrer\">aufgehoben<\/a>. Die Spitzenpolitikerin befand sich seit ungef\u00e4hr acht Jahren auf der sogenannten Liste der besonders benannten Staatsangeh\u00f6rigen, nachdem die USA sie im September 2018 noch im Amt der Vizepr\u00e4sidentin mit Einschr\u00e4nkungen belegt hatten. Rodr\u00edguez war unter anderem verboten, Verm\u00f6genswerte in den USA zu nutzen und mit US-Unternehmen Gesch\u00e4fte einzugehen.<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet lazyload\" data-twitter=\"twitter-tweet\">\n<p lang=\"en\" dir=\"ltr\">US lifts sanctions on Delcy Rodriguez. <a rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/t.co\/lwKE9UWpTF\">pic.twitter.com\/lwKE9UWpTF<\/a><\/p>\n<p>\u2014 Richard Escobedo (@RichardEscobedo) <a rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/twitter.com\/RichardEscobedo\/status\/2039437065755230712?ref_src=twsrc%5Etfw\">April 1, 2026<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<p>Rodr\u00edguez begr\u00fc\u00dfte die Geste der US-Regierung von Pr\u00e4sident Donald Trump als &#8220;einen Schritt in die Richtung der Normalisierung und St\u00e4rkung&#8221; der Beziehungen zwischen den beiden Staaten. Auf der Plattform X\u00a0<a rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/x.com\/delcyrodriguezv\/status\/2039441129888682020\" target=\"_blank\" rel=\"noopener noreferrer\">schrieb<\/a>\u00a0die Politikerin: \u00a0<\/p>\n<blockquote>\n<p><em>&#8220;Wir rechnen damit, dass dieser Fortschritt die Aufhebung der bis heute geltenden Sanktionen gegen unser Land erm\u00f6glichen und uns erlauben wird, die Agenda f\u00fcr eine effektive bilaterale Kooperation zum Wohl unserer V\u00f6lker zu gestalten und zu garantieren.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Abschlie\u00dfend rief die kommissarische Staatschefin zu weiteren Schritten nach vorw\u00e4rts und dazu auf, gemeinsam ein prosperierendes Venezuela &#8220;f\u00fcr alle&#8221; zu bauen.<\/p>\n<p>Die Entscheidung der OFAC kam knapp drei Monate, nachdem die USA bei einem ebenso filmreifen wie v\u00f6lkerrechtswidrigen Milit\u00e4reinsatz Venezuelas Staatschef Nicol\u00e1s Maduro in seiner Residenz gefasst hatten. Bei der Operation kamen mehr als 100 venezolanische und kubanische Sicherheitskr\u00e4fte ums Leben. Mehrere zivile und milit\u00e4rische Infrastrukturen wurden besch\u00e4digt. Im Einklang mit der venezolanischen Verfassung \u00fcbertrug der Oberste Gerichtshof in Caracas Maduros Amtsgesch\u00e4fte auf Vizepr\u00e4sidentin Delcy Rodr\u00edguez.<\/p>\n<p>Kurz darauf rief die Politikerin eine Etappe der Wiederherstellung der bilateralen Beziehungen zu Washington auf, die im Jahr 2019 abgebrochen worden waren. Inzwischen erlie\u00dfen die USA eine Reihe von Genehmigungen, die es privaten Unternehmen \u2013 vor allem aus den USA \u2013 erlaubten, wieder in die Erd\u00f6l- und Gasf\u00f6rderung sowie in den Bergbau im s\u00fcdamerikanischen Land zu investieren. Die Sanktionen im Allgemeinen wurden aber bislang nicht aufgehoben. Die Erd\u00f6lgesch\u00e4fte mit Unternehmen aus Russland, China, Kuba, dem Iran und der DVRK wurden untersagt.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/freedert.online\/amerika\/275218-us-praesident-trump-droht-kuba-n%C3%A4chstes-ziel\/\" target=\"_blank\" rel=\"noopener noreferrer\">US-Pr\u00e4sident Trump droht: Kuba n\u00e4chstes Ziel eines Milit\u00e4rschlags<\/a><\/p>\n<\/p>\n<\/div>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/amerika\/275714-usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nach knapp acht Jahren auf der US-Sanktionsliste stehen nun Venezuelas \u00dcbergangspr\u00e4sidentin Delcy Rodr\u00edguez keine Hindernisse mehr im Weg, um die Beziehungen zwischen Caracas und Washington zu normalisieren. Die Politikerin hofft, dass bald weitere Einschr\u00e4nkungen fallen werden. Die US-Kontrollbeh\u00f6rde f\u00fcr Auslandsverm\u00f6gen (OFAC), die dem Finanzministerium in Washington untersteht, hat am Mittwoch die Sanktionen gegen Venezuelas \u00dcbergangspr\u00e4sidentin [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":101185,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1775140420"],"wp_automatic_camp":["217"],"173d1fa91fb926765b70f42cadbf489f":["USA streichen Venezuelas \u00dcbergangspr\u00e4sidentin Rodr\u00edguez von Sanktionsliste"],"original_link":["https:\/\/de.rt.com\/amerika\/275714-usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/"],"_thumbnail_id":["101185"],"jnews_social_counter_last_update":["1778646884"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2026-04-02 16:34:43\";}"]},"categories":[19,23],"tags":[70349,2001,20702,72138,193,36779,50],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>USA streichen Venezuelas \u00dcbergangspr\u00e4sidentin Rodr\u00edguez von Sanktionsliste - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"USA streichen Venezuelas \u00dcbergangspr\u00e4sidentin Rodr\u00edguez von Sanktionsliste\" \/>\n<meta property=\"og:description\" content=\"Nach knapp acht Jahren auf der US-Sanktionsliste stehen nun Venezuelas \u00dcbergangspr\u00e4sidentin Delcy Rodr\u00edguez keine Hindernisse mehr im Weg, um die Beziehungen zwischen Caracas und Washington zu normalisieren. Die Politikerin hofft, dass bald weitere Einschr\u00e4nkungen fallen werden. Die US-Kontrollbeh\u00f6rde f\u00fcr Auslandsverm\u00f6gen (OFAC), die dem Finanzministerium in Washington untersteht, hat am Mittwoch die Sanktionen gegen Venezuelas \u00dcbergangspr\u00e4sidentin [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-02T14:25:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/69ce3b0148fbef44de611674.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"USA streichen Venezuelas \u00dcbergangspr\u00e4sidentin Rodr\u00edguez von Sanktionsliste\",\"datePublished\":\"2026-04-02T14:25:18+00:00\",\"dateModified\":\"2026-04-02T14:25:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/\"},\"wordCount\":420,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/USA-streichen-Venezuelas-Uebergangspraesidentin-Rodriguez-von-Sanktionsliste.jpg\",\"keywords\":[\"Rodr\u00edguez\",\"Sanktionsliste\",\"streichen\",\"\u00dcbergangspr\u00e4sidentin\",\"USA\",\"Venezuelas\",\"von\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/\",\"name\":\"USA streichen Venezuelas \u00dcbergangspr\u00e4sidentin Rodr\u00edguez von Sanktionsliste - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/USA-streichen-Venezuelas-Uebergangspraesidentin-Rodriguez-von-Sanktionsliste.jpg\",\"datePublished\":\"2026-04-02T14:25:18+00:00\",\"dateModified\":\"2026-04-02T14:25:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/USA-streichen-Venezuelas-Uebergangspraesidentin-Rodriguez-von-Sanktionsliste.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/USA-streichen-Venezuelas-Uebergangspraesidentin-Rodriguez-von-Sanktionsliste.jpg\",\"width\":460,\"height\":259,\"caption\":\"USA streichen Venezuelas \u00dcbergangspr\u00e4sidentin Rodr\u00edguez von Sanktionsliste\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"USA streichen Venezuelas \u00dcbergangspr\u00e4sidentin Rodr\u00edguez von Sanktionsliste\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"USA streichen Venezuelas \u00dcbergangspr\u00e4sidentin Rodr\u00edguez von Sanktionsliste - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/","og_locale":"de_DE","og_type":"article","og_title":"USA streichen Venezuelas \u00dcbergangspr\u00e4sidentin Rodr\u00edguez von Sanktionsliste","og_description":"Nach knapp acht Jahren auf der US-Sanktionsliste stehen nun Venezuelas \u00dcbergangspr\u00e4sidentin Delcy Rodr\u00edguez keine Hindernisse mehr im Weg, um die Beziehungen zwischen Caracas und Washington zu normalisieren. Die Politikerin hofft, dass bald weitere Einschr\u00e4nkungen fallen werden. Die US-Kontrollbeh\u00f6rde f\u00fcr Auslandsverm\u00f6gen (OFAC), die dem Finanzministerium in Washington untersteht, hat am Mittwoch die Sanktionen gegen Venezuelas \u00dcbergangspr\u00e4sidentin [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2026-04-02T14:25:18+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/69ce3b0148fbef44de611674.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"USA streichen Venezuelas \u00dcbergangspr\u00e4sidentin Rodr\u00edguez von Sanktionsliste","datePublished":"2026-04-02T14:25:18+00:00","dateModified":"2026-04-02T14:25:18+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/"},"wordCount":420,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/USA-streichen-Venezuelas-Uebergangspraesidentin-Rodriguez-von-Sanktionsliste.jpg","keywords":["Rodr\u00edguez","Sanktionsliste","streichen","\u00dcbergangspr\u00e4sidentin","USA","Venezuelas","von"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/","url":"https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/","name":"USA streichen Venezuelas \u00dcbergangspr\u00e4sidentin Rodr\u00edguez von Sanktionsliste - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/USA-streichen-Venezuelas-Uebergangspraesidentin-Rodriguez-von-Sanktionsliste.jpg","datePublished":"2026-04-02T14:25:18+00:00","dateModified":"2026-04-02T14:25:18+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/USA-streichen-Venezuelas-Uebergangspraesidentin-Rodriguez-von-Sanktionsliste.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/04\/USA-streichen-Venezuelas-Uebergangspraesidentin-Rodriguez-von-Sanktionsliste.jpg","width":460,"height":259,"caption":"USA streichen Venezuelas \u00dcbergangspr\u00e4sidentin Rodr\u00edguez von Sanktionsliste"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/usa-streichen-venezuelas-uebergangspraesidentin-rodriguez-von-sanktionsliste\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"USA streichen Venezuelas \u00dcbergangspr\u00e4sidentin Rodr\u00edguez von Sanktionsliste"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/101184"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=101184"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/101184\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/101185"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=101184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=101184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=101184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}