{"id":100255,"date":"2026-03-14T19:14:14","date_gmt":"2026-03-14T17:14:14","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/"},"modified":"2026-03-14T19:14:14","modified_gmt":"2026-03-14T17:14:14","slug":"stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/","title":{"rendered":"Stagflation, Rezession, Sanktionen? Experten \u00fcber den Zustand der russischen Wirtschaft (Teil 2)"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/03\/69b44a0148fbef4ac10f9daa.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Nach Jahren des Erfolgs im Kampf gegen die Sanktionen zeichnet sich in der russischen Wirtschaft eine Krise ab. Der Westen will darin die Folgen seiner Sanktionen sehen, in Wirklichkeit handelt es sich um interne Probleme.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>(Teil 1 k\u00f6nnen Sie <a rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/freeassange.tech\/russland\/272984-stagflation-rezession-sanktionen-experten-ueber\/\" target=\"_blank\" rel=\"noopener noreferrer\">hier nachlesen<\/a>)<\/em><\/p>\n<p><em>Eine Analyse von Dora Werner<\/em><\/p>\n<p><strong>Der Wirtschaftsblock \u2013 Freund oder Feind?<\/strong><\/p>\n<p>Viele Experten sind der Ansicht, dass Vertreter des sogenannten &#8220;Wirtschaftsblocks&#8221; \u2013 des Finanzministeriums, der Zentralbank und\u00a0weiterer Institutionen\u00a0\u2013 in den letzten Jahren eine Reihe fataler Fehler im Krisenmanagement begangen haben. Dieses Thema taucht immer wieder in den Sitzungen der Staatsduma auf und ist wohl aus den Medien nicht mehr wegzudenken. Hier kommen die Wirtschaftswissenschaftler zu Wort. Dmitri Beloussow, Leiter des Bereichs Analyse und Prognose makro\u00f6konomischer Prozesse am Institut f\u00fcr volkswirtschaftliche Prognosen der Russischen Akademie der Wissenschaften, erkl\u00e4rt in einem Interview mit dem Portal<em>\u00a0BusinessOnline<\/em> die aktuelle Situation in Bezug auf den Haushalt, Investitionen und Fehleinsch\u00e4tzungen des Finanzblocks wie folgt:<\/p>\n<p><em>&#8220;Die Lage ist insgesamt unter Kontrolle. Der Export hat sich trotz der Sanktionen stabilisiert. Unsere Unternehmen schaffen es, schnell neue Absatzm\u00e4rkte und neue Wege zu finden. Was schlecht ist: Der sich schon lange abzeichnende \u00dcbergang zur Stagnation hat eingesetzt\u00a0[\u2026] Wir haben eine sehr schwierige Situation bei den Investitionen. Wir haben davor gewarnt, dass das Investitionswachstum gef\u00e4hrdet ist, da die Kombination aus hohen Zinss\u00e4tzen, einem starken Rubel, der die Einnahmen der Exporteure schm\u00e4lert, und niedrigen Rohstoffpreisen insgesamt die Investitionen sowohl durch Fremd- als auch durch Eigenmittel ersticken k\u00f6nnte [\u2026]<\/em><em>\u00a0Im Grunde genommen ist die Lage nicht gut. Wir befinden uns in einer ziemlich schwierigen<\/em>\u00a0<em>Entwicklung, die wir nun umkehren m\u00fcssen. Das ist das gravierendste Problem, denn bei dem Versuch, die Inflation einzud\u00e4mmen, haben wir die Wirtschaftst\u00e4tigkeit gebremst [\u2026] Den st\u00e4rksten Schlag haben wir dem Investitionsbereich versetzt. Und innerhalb dieses Bereichs nicht dem Bauwesen, sondern der Produktion von Maschinen und Anlagen sowie den Investitionen in Betriebsverm\u00f6gen. Wir haben eine schwierige Situation in der Lkw-Produktion, und auch alles andere in diesem Bereich befindet sich in einem schlechten Zustand, abgesehen vom Verteidigungssektor [\u2026] Bei uns nehmen die negativen Trends zu. Im n\u00e4chsten Jahr m\u00fcssen diese Trends umgekehrt werden. Seien wir ehrlich: Man h\u00e4tte es nicht so weit kommen lassen m\u00fcssen. Wir haben uns selbst \u00fcber den Zinskanal unter Druck gesetzt. Das hei\u00dft, wir haben mithilfe der Zentralbank diese Zinserh\u00f6hungswelle ab 2024 inszeniert, und zwar eine \u00e4u\u00dferst unsinnige Welle, da die Zinsen aktiv in die Preise einflossen. All dies endete im Zuge der letzten Hotline des Pr\u00e4sidenten. Ich erinnere mich nicht mehr an den genauen Wortlaut, aber im Grunde hat er dort kategorisch gefordert, dass die Zentralbank eine vern\u00fcnftigere Haltung einnehmen solle. Und dort hat man, muss man sagen, darauf geh\u00f6rt [\u2026]\u00a0Die gr\u00f6\u00dften Schocks kommen derzeit <\/em><em>also <\/em><em>aus dem Inneren der Wirtschaft.<\/em><em>&#8220;<\/em><\/p>\n<p>Der \u00d6konom Oleg Komolow, leitender wissenschaftlicher Mitarbeiter am Zentrum f\u00fcr internationale Makro\u00f6konomie und Au\u00dfenwirtschaftsbeziehungen des Wirtschaftsinstituts der Russischen Akademie der Wissenschaften, stellt fest, dass es trotz der allgemeinen Krise auch Nutznie\u00dfer gibt. Diese werden von der Zentralbank und bestimmten Kr\u00e4ften in der Regierung mit allen Mitteln unterst\u00fctzt \u2013 obwohl dies der Wirtschaft insgesamt schadet:<\/p>\n<p><em>&#8220;Es gibt Akteure der russischen Wirtschaft, die sich derzeit in einer privilegierten Lage befinden. Das sind die Banken. Der Gesamtgewinn der russischen Banken erreichte im Jahr 2024 mit 3,8 Billionen Rubel \u2013 fast 2 <\/em><em>Prozent<\/em><em> des BIP \u2013 einen absoluten Rekordwert in der gesamten postsowjetischen Geschichte. Im Jahr 2025 liegt das Ergebnis etwas darunter, aber die Gr\u00f6\u00dfenordnung ist dieselbe. Man k\u00f6nnte meinen, 2 <\/em><em>Prozent<\/em><em> seien nicht viel. Vergleicht man dies jedoch mit den Vereinigten Staaten, dem eigentlichen Finanzzentrum der Weltwirtschaft, wo sich alle gro\u00dfen Banken der Welt konzentrieren, so betr\u00e4gt der dortige Anteil der Bankgewinne lediglich 1 <\/em><em>Prozent<\/em><em> des BIP, und in den letzten Jahren ist ein Trend zur Verringerung dieses Wertes zu beobachten.<\/em><\/p>\n<p><em>Die Banken selbst schaffen ja keinen Mehrwert, sondern verteilen ihn nur um. Sie sind ein riesiger Blutsauger, der sich an das Wirtschaftssystem geheftet hat. Dabei haben sowohl El<\/em><em>w<\/em><em>ira Nabiullina als auch Anton Siluano<\/em><em>w<\/em><em> wiederholt betont, dass keine zus\u00e4tzlichen Steuern auf Bankgewinne eingef\u00fchrt werden sollten. Der Staat l\u00e4sst die Seinen, wie man so sagt, nicht im Stich.<\/em><\/p>\n<p><em>Vor dem Hintergrund der Privilegien f\u00fcr das Gro\u00dfkapital und das Bankensystem ger\u00e4t die Kleinunternehmerschaft zunehmend unter Druck [\u2026] Wenn es um die Gewinnverteilung geht, dominieren die Interessen des Privatkapitals. Das ist eine typische Vergesellschaftung der Verluste und Privatisierung der Gewinne. Der Staat verfolgt derzeit eine Wirtschaftspolitik, die nicht im Interesse der arbeitenden Mehrheit liegt \u2013 er betrachtet das Volk ausschlie\u00dflich als Quelle f\u00fcr Ressourcen.&#8221;<\/em><\/p>\n<p>Das Zentrum f\u00fcr makro\u00f6konomische Analyse und kurzfristige Prognosen berichtete k\u00fcrzlich: Die russische Wirtschaft steht kurz vor einer Stagflation. Der Finanzanalyst und Doktor der Wirtschaftswissenschaften Michail Beljajew kommentierte in einer Sendung des Radiosenders <em>Komsomolskaja Prawda<\/em> die Aussage der Experten des Zentrums und betonte, dass von Anfang an alles schiefgelaufen sei, da die Inflation in Russland keineswegs durch monet\u00e4re Faktoren verursacht werde, wie die Zentralbank zu versichern versuche. Beljajew erkl\u00e4rt:<\/p>\n<p><em>&#8220;Die heutige Inflation und der Preisanstieg sind ganz und gar den H\u00e4ndlern zuzuschreiben. Und das wurde nicht erst im Jahr 1980 des vergangenen Jahrhunderts erkannt, sondern bereits in den 20er und 30er Jahren desselben Jahrhunderts. Es gab einen amerikanischen Wissenschaftler namens Gardiner Means, der dies als sogenannte &#8216;administrierte Preise&#8217; bezeichnete und all dies den Monopolen zuschrieb, die auf dem Markt ihr Unwesen treiben und die Preise ungehemmt in die H\u00f6he schrauben. Genau das ist bei uns passiert. Aus irgendeinem Grund gef\u00e4llt diese Theorie der Zentralbank nicht. Sie ist der Ansicht, dass Inflation zwangsl\u00e4ufig ein monet\u00e4res Ph\u00e4nomen ist und mithilfe eines hohen Leitzinses bek\u00e4mpft werden muss. Nun, die Zentralbank hat begonnen, die Inflation mithilfe eines hohen Leitzinses einzud\u00e4mmen. Es ist ihr zwar gelungen, die Inflation ein wenig zu senken, aber vor allem hat sie damit die Wirtschaft erstickt. H\u00e4tte man unsere Wirtschaft nicht eingeengt und sie nicht mit diesem hohen Leitzins erstickt, h\u00e4tte das Geld f\u00fcr alles gereicht \u2013 f\u00fcr die spezielle Milit\u00e4roperation, f\u00fcr den Haushalt und f\u00fcr alles zusammen.&#8221;<\/em><\/p>\n<p>Der \u00d6konom Walentin Katassonow stellt im Gespr\u00e4ch mit dem Portal\u00a0<em>Business<\/em><em>Online<\/em> ebenfalls fest, dass eine gro\u00dfe Anzahl von Branchen der heimischen Wirtschaft im Vergleich zum entsprechenden Zeitraum des Jahres 2024 ein Minus verzeichnet und die Lage insgesamt wenig erfreulich ist. &#8220;Ich beobachte die Schwachstellen der russischen Wirtschaft und muss leider feststellen: Wir haben sehr viele solcher Schwachstellen [\u2026] Das ist eine Auspr\u00e4gung der Ideologie des Wirtschaftsliberalismus \u2013 immer noch dieselbe, die nach Adam Smith darauf vertraut, dass die unsichtbare Hand des Marktes alles von selbst regeln wird. Nun, wie lange soll das noch so weitergehen?&#8221;, wirft er ein und f\u00e4hrt fort, indem er so etwas wie eine Verschw\u00f6rung der Oligarchen aufdeckt:<\/p>\n<p><em>&#8220;Ich kann nicht umhin, auf den Beschluss einzugehen, der am 8. Dezember letzten Jahres in Kraft getreten ist \u2013 n\u00e4mlich die Aufhebung der Beschr\u00e4nkungen f\u00fcr den Abfluss von Devisen aus Russland durch die Zentralbank. Es ist klar, dass diese T\u00fcren f\u00fcr Deviseneinlagen auf keinen Fall ge\u00f6ffnet werden durften, denn, wie Sie mir sicherlich zustimmen werden, es herrscht Krieg, und daher ist eine wirtschaftliche Mobilisierung erforderlich. Stattdessen werden jedoch die T\u00fcren f\u00fcr Deviseneinlagen ge\u00f6ffnet. Es ist offensichtlich, dass diese Entscheidung durch Lobbyarbeit durchgesetzt wurde. Zuvor gab es lediglich einen &#8216;engen Flaschenhals&#8217;, der es erlaubte, monatlich nur eine Million Dollar ins Ausland zu transferieren \u2013 sofern Interbankkan\u00e4le genutzt wurden. 12 Millionen US-Dollar pro Jahr sind f\u00fcr unsere Milliard\u00e4re nat\u00fcrlich Peanuts. Deshalb haben sie die Aufhebung der Beschr\u00e4nkungen durchgesetzt. Allerdings gab es viele Lobbyisten hinter dieser Entscheidung, und einer der wichtigsten war meiner Meinung nach Finanzminister Anton Siluanow, der einen schwachen Rubel brauchte.&#8221;<\/em><\/p>\n<p>Der Wirtschaftsprofessor Igor Belski warnt: Sobald die Wirtschaft in eine Phase der Stagnation und Krise eintritt, beginnt auch die Suche nach den Schuldigen. In Russland gehe man davon aus, dass jedes Problem einen Nachnamen, einen Vornamen und einen Vatersnamen habe, wie es Stalins Minister Kaganowitsch formulierte. Der Hauptvorwurf gegen die Zentralbankchefin Nabiullina wird offensichtlich der hohe Leitzins sein. &#8220;In diesem Fall leiden die meisten Firmen und Unternehmen des Landes unter dem hohen Zinssatz. Kredite sind teuer. Der Markt und ein Teil der Wirtschaftsbeamten sind der Meinung, dass der Zinssatz schneller h\u00e4tte gesenkt werden m\u00fcssen. Die Wirtschaft ben\u00f6tigt Unterst\u00fctzung durch billiges Geld, au\u00dferdem w\u00e4chst die Staatsverschuldung stark und bislang zu hohen Kosten. Es w\u00e4re w\u00fcnschenswert, diese ebenfalls kosteng\u00fcnstig zu gestalten, durch eine rasche Senkung des Zinssatzes. Daran wird der Vertreter des Finanzzentrums des Landes schuld sein&#8221;, meint Igor Belski. Dabei betont er, dass das Problem des Wirtschaftswachstums und der Entwicklung in Wirklichkeit tiefer liegt als der Zinssatz und die regulierenden Ma\u00dfnahmen der Zentralbank zur Eind\u00e4mmung der Inflation:<\/p>\n<blockquote>\n<p><em>&#8220;<\/em><em>Das Problem hat viel mehr Namen und Ursachen.<\/em><em>&#8220;<\/em><\/p>\n<\/blockquote>\n<p>Und eine davon ist zweifellos die Korruption.<\/p>\n<p><strong>Bestechliche Amtstr\u00e4ger<\/strong><\/p>\n<p>Seit Beginn der milit\u00e4rischen Sonderoperation wird die Medienlandschaft regelm\u00e4\u00dfig von medialen Erdbeben ersch\u00fcttert \u2013 mittlerweile sind Nachrichten \u00fcber die Verhaftung eines weiteren hochrangigen Beamten, der Staatsgelder veruntreut hat, fast schon an der Tagesordnung. Und die aus dem Staatshaushalt unterschlagenen Summen gehen in die Billionen.<\/p>\n<p>Beh\u00f6rden verzeichnen eine bisher beispiellose Dynamik bei Korruptionsf\u00e4llen in den russischen Regionen. Allein im Jahr 2025 wurden mindestens 15 amtierende und ehemalige Stellvertreter der Leiter von F\u00f6derationssubjekten strafrechtlich verfolgt \u2013 dies entspricht in etwa der Gesamtzahl des vorangegangenen F\u00fcnfjahreszeitraums, schreibt der Telegram-Kanal <em>Baschni Federazii<\/em>.<\/p>\n<p>Dabei haben die Sicherheitsbeh\u00f6rden in den letzten zehn Jahren 50 Vizegouverneure aus 23 Regionen ins Visier genommen und damit fast ein Viertel der administrativen Karte des Landes mit Strafverfahren erfasst. Doch gerade seit Anfang des vergangenen Jahres ist die Zahl der Korruptionsf\u00e4lle in beispiellosem Tempo gestiegen.<\/p>\n<p>Im Jahr 2025 gab es praktisch jede Woche Meldungen \u00fcber die Festnahme hochrangiger regionaler Beamter. Moskau ging zum ersten Mal in solch gro\u00dfem Umfang gegen die au\u00dfer Kontrolle geratene regionale Elite vor. Insgesamt haben die f\u00f6deralen Strafverfolgungsbeh\u00f6rden im vergangenen Jahr \u00fcber 100 hochrangige Beamte festgenommen. Dabei meldete die Generalstaatsanwaltschaft im vergangenen Jahr 36.000 registrierte Korruptionsdelikte und 24,5 Milliarden Rubel an beschlagnahmten Verm\u00f6genswerten, die dem Staat zuflossen, was ebenfalls eine Art Rekord darstellt, so die Medien.<\/p>\n<p>Das Zusammenspiel zwischen dem FSB, dem von Alexander Bastrykin geleiteten Ermittlungskomitee und dem neuen Generalstaatsanwalt Alexander Guzan funktioniert seit Anfang letzten Jahres als einheitlicher Mechanismus zur Wiederherstellung der Ordnung in den Regionen. &#8220;Die f\u00f6derale F\u00fchrung hat erkannt: Die regionalen Eliten sind so sehr au\u00dfer Kontrolle geraten, dass sanfte Ma\u00dfnahmen nicht mehr greifen. Man musste chirurgisch ohne Bet\u00e4ubung vorgehen&#8221;, berichtet der analytische Telegram-Kanal <em>Baschni Federazii<\/em>.<\/p>\n<p>Nachfolgend beispielhaft\u00a0einige der zahlreichen Schlagzeilen zu diesem Thema:<\/p>\n<p>&#8211; Bei dem ehemaligen Abgeordneten der Staatsduma Anatoli Woronowski und mit ihm verbundenen Personen wurde Verm\u00f6gen im Wert von \u00fcber 20 Milliarden Rubel beschlagnahmt. Dies teilte der gemeinsame Pressedienst der Gerichte der Region Krasnodar am 19. Februar \u00fcber seinen Telegram-Kanal mit.<\/p>\n<p>&#8211; Das Gericht hat die Ermittlungen im Fall gegen den Gr\u00fcnder von Rusagro und ehemaligen Senator der Region Belgorod, Wadim Moschkowitsch, sowie den ehemaligen Generaldirektor Maxim Bassow abgeschlossen, berichtete die Zeitung <em>Wedomosti<\/em>. In der endg\u00fcltigen Anklageschrift werden Betrug, vors\u00e4tzliche Insolvenz und Geldw\u00e4sche angef\u00fchrt, wobei sich der Schaden auf 86 Milliarden Rubel bel\u00e4uft.<\/p>\n<p>&#8211; Timur Iwanow, der stellvertretende Verteidigungsminister, der f\u00fcr die Baut\u00e4tigkeit zust\u00e4ndig war, wird beschuldigt, Bestechungsgelder in H\u00f6he von mehr als 1 Milliarde Rubel angenommen zu haben. Gerade sein Ministerium war f\u00fcr den Bau von Kasernen und Truppen\u00fcbungspl\u00e4tzen verantwortlich, deren Qualit\u00e4t nun in Frage gestellt wird.<\/p>\n<p>&#8211; Juri Jaskin, einer der f\u00fchrenden Beamten des Konzerns Roskosmos, begab sich auf Dienstreise nach Europa und kehrte nicht zur\u00fcck, da er eine Untersuchung wegen gro\u00dfangelegter Unterschlagungen innerhalb seines Ressorts bef\u00fcrchtete. Dabei hatte er lange vor seiner Abreise Immobilien in Griechenland erworben und dort eine Aufenthaltsgenehmigung erhalten. Nach vorliegenden Informationen hat sich Jaskin auf der Insel Kreta niedergelassen \u2013 in unmittelbarer N\u00e4he des Marinest\u00fctzpunkts Souda, dem gr\u00f6\u00dften St\u00fctzpunkt der NATO im \u00f6stlichen Mittelmeerraum. Jaskin erwarb f\u00fcnf gro\u00dfe Grundst\u00fccke, Hotels und eine Villa \u2013 buchst\u00e4blich im unmittelbaren Umfeld dieses strategischen Objekts des B\u00fcndnisses.<\/p>\n<p>Die Sanktionen des Westens spielen also, wie wir sehen, in der aktuellen Lage der russischen Wirtschaft eine v\u00f6llig nebens\u00e4chliche Rolle. Abschlie\u00dfend muss man die Worte von Michail Demurin erw\u00e4hnen, einem ehemaligen hochrangigen Mitarbeiter des Au\u00dfenministeriums und Publizisten, der der Ansicht ist, dass &#8220;im Zuge der Perestroika und der Konterrevolution seit dem Jahr 1991 Menschen an die Macht kamen, die f\u00fcr historisches Schaffen ungeeignet waren und zu ihrem eigenen Vorteil ein sekund\u00e4res und sch\u00e4dliches Ungeheuer der Unterw\u00fcrfigkeit gegen\u00fcber dem Westen, des Marktes, der sozialen Segregation und der Abkehr von den eigenen Wurzeln geschaffen haben&#8221;. Mit Wehmut stellt er fest:<\/p>\n<blockquote>\n<p><em>&#8220;<\/em><em>In all den folgenden Jahren haben sie, an der Macht festhaltend, unser Land ruiniert und ruinieren es weiterhin. Und die sich abzeichnenden Schwankungen in Richtung <\/em><em>&#8216;<\/em><em>Traditionalismus<\/em><em>&#8216;<\/em><em> und <\/em><em>&#8216;<\/em><em>Wende<\/em><em>&#8216;<\/em><em> nach Osten und S\u00fcden haben, wie wir sehen, unsere Lage nicht grundlegend ver\u00e4ndert und zu keiner prinzipiellen Besserung gef\u00fchrt. Warum? Weil beides von denselben Leuten initiiert wurde und wird. Die tiefste Krise, die unser Land derzeit durchlebt, k\u00f6nnen wir mit den heutigen Eliten nicht \u00fcberwinden.<\/em><em>&#8220;<\/em><\/p>\n<\/blockquote>\n<p><strong>Mehr zum Thema\u00a0\u2012 <\/strong><a rel=\"nofollow\" target=\"_blank\" href=\"https:\/\/freedert.online\/russland\/266012-russland-ist-in-neue-phase\/\" target=\"_blank\" rel=\"noopener noreferrer\">Russland ist in eine neue Phase der Korruptionsbek\u00e4mpfung eingetreten<\/a><\/p>\n<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/russland\/273254-stagflation-rezession-sanktionen-was-experten\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nach Jahren des Erfolgs im Kampf gegen die Sanktionen zeichnet sich in der russischen Wirtschaft eine Krise ab. Der Westen will darin die Folgen seiner Sanktionen sehen, in Wirklichkeit handelt es sich um interne Probleme. (Teil 1 k\u00f6nnen Sie hier nachlesen) Eine Analyse von Dora Werner Der Wirtschaftsblock \u2013 Freund oder Feind? Viele Experten sind [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":100256,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1773509140"],"wp_automatic_camp":["217"],"abb657d2b699e83e06b5feed00cde8d4":["Stagflation, Rezession, Sanktionen? Experten \u00fcber den Zustand der russischen Wirtschaft (Teil 2)"],"original_link":["https:\/\/de.rt.com\/russland\/273254-stagflation-rezession-sanktionen-was-experten\/"],"_thumbnail_id":["100256"],"jnews_social_counter_last_update":["1784148679"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2026-03-14 19:26:41\";}"]},"categories":[19,23],"tags":[48,82,3312,7847,973,713,7475,3240,139,291,21829],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Stagflation, Rezession, Sanktionen? Experten \u00fcber den Zustand der russischen Wirtschaft (Teil 2) - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stagflation, Rezession, Sanktionen? Experten \u00fcber den Zustand der russischen Wirtschaft (Teil 2)\" \/>\n<meta property=\"og:description\" content=\"Nach Jahren des Erfolgs im Kampf gegen die Sanktionen zeichnet sich in der russischen Wirtschaft eine Krise ab. Der Westen will darin die Folgen seiner Sanktionen sehen, in Wirklichkeit handelt es sich um interne Probleme. (Teil 1 k\u00f6nnen Sie hier nachlesen) Eine Analyse von Dora Werner Der Wirtschaftsblock \u2013 Freund oder Feind? Viele Experten sind [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-14T17:14:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/03\/69b44a0148fbef4ac10f9daa.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"11\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Stagflation, Rezession, Sanktionen? Experten \u00fcber den Zustand der russischen Wirtschaft (Teil 2)\",\"datePublished\":\"2026-03-14T17:14:14+00:00\",\"dateModified\":\"2026-03-14T17:14:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/\"},\"wordCount\":2243,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/03\/1773509145_Stagflation-Rezession-Sanktionen-Experten-ueber-den-Zustand-der-russischen-Wirtschaft.jpg\",\"keywords\":[\"den\",\"der\",\"Experten\",\"Rezession\",\"russischen\",\"Sanktionen\",\"stagflation\",\"Teil\",\"\u00fcber\",\"wirtschaft\",\"Zustand\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/\",\"name\":\"Stagflation, Rezession, Sanktionen? Experten \u00fcber den Zustand der russischen Wirtschaft (Teil 2) - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/03\/1773509145_Stagflation-Rezession-Sanktionen-Experten-ueber-den-Zustand-der-russischen-Wirtschaft.jpg\",\"datePublished\":\"2026-03-14T17:14:14+00:00\",\"dateModified\":\"2026-03-14T17:14:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/03\/1773509145_Stagflation-Rezession-Sanktionen-Experten-ueber-den-Zustand-der-russischen-Wirtschaft.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/03\/1773509145_Stagflation-Rezession-Sanktionen-Experten-ueber-den-Zustand-der-russischen-Wirtschaft.jpg\",\"width\":460,\"height\":259,\"caption\":\"Stagflation, Rezession, Sanktionen? Experten \u00fcber den Zustand der russischen Wirtschaft (Teil 2)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stagflation, Rezession, Sanktionen? Experten \u00fcber den Zustand der russischen Wirtschaft (Teil 2)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Stagflation, Rezession, Sanktionen? Experten \u00fcber den Zustand der russischen Wirtschaft (Teil 2) - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/","og_locale":"de_DE","og_type":"article","og_title":"Stagflation, Rezession, Sanktionen? Experten \u00fcber den Zustand der russischen Wirtschaft (Teil 2)","og_description":"Nach Jahren des Erfolgs im Kampf gegen die Sanktionen zeichnet sich in der russischen Wirtschaft eine Krise ab. Der Westen will darin die Folgen seiner Sanktionen sehen, in Wirklichkeit handelt es sich um interne Probleme. (Teil 1 k\u00f6nnen Sie hier nachlesen) Eine Analyse von Dora Werner Der Wirtschaftsblock \u2013 Freund oder Feind? Viele Experten sind [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2026-03-14T17:14:14+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/03\/69b44a0148fbef4ac10f9daa.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"11\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Stagflation, Rezession, Sanktionen? Experten \u00fcber den Zustand der russischen Wirtschaft (Teil 2)","datePublished":"2026-03-14T17:14:14+00:00","dateModified":"2026-03-14T17:14:14+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/"},"wordCount":2243,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/03\/1773509145_Stagflation-Rezession-Sanktionen-Experten-ueber-den-Zustand-der-russischen-Wirtschaft.jpg","keywords":["den","der","Experten","Rezession","russischen","Sanktionen","stagflation","Teil","\u00fcber","wirtschaft","Zustand"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/","url":"https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/","name":"Stagflation, Rezession, Sanktionen? Experten \u00fcber den Zustand der russischen Wirtschaft (Teil 2) - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/03\/1773509145_Stagflation-Rezession-Sanktionen-Experten-ueber-den-Zustand-der-russischen-Wirtschaft.jpg","datePublished":"2026-03-14T17:14:14+00:00","dateModified":"2026-03-14T17:14:14+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/03\/1773509145_Stagflation-Rezession-Sanktionen-Experten-ueber-den-Zustand-der-russischen-Wirtschaft.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/03\/1773509145_Stagflation-Rezession-Sanktionen-Experten-ueber-den-Zustand-der-russischen-Wirtschaft.jpg","width":460,"height":259,"caption":"Stagflation, Rezession, Sanktionen? Experten \u00fcber den Zustand der russischen Wirtschaft (Teil 2)"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/stagflation-rezession-sanktionen-experten-ueber-den-zustand-der-russischen-wirtschaft-teil-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Stagflation, Rezession, Sanktionen? Experten \u00fcber den Zustand der russischen Wirtschaft (Teil 2)"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/100255"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=100255"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/100255\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/100256"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=100255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=100255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=100255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}